{"id":99393,"date":"2024-05-07T20:11:00","date_gmt":"2024-05-08T00:11:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=99393"},"modified":"2024-05-11T15:29:24","modified_gmt":"2024-05-11T19:29:24","slug":"resultats-pour-le-wwe-nxt-du-7-mai-2024","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/05\/07\/resultats-pour-le-wwe-nxt-du-7-mai-2024\/","title":{"rendered":"R\u00e9sultats pour le WWE NXT du 7 Mai 2024!"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/05\/07\/avant-gout-pour-le-wwe-nxt-du-7-mai-2024\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir NXT,  cliquez ici.<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p><strong>WWE NXT, Orlando, Floride, 7 mai 2024<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Vic Joseph et Booker T.<\/p>\n\n\n\n<p>-Le WWE NXT d\u00e9bute sur une vid\u00e9o sur la blessure et le retour de Wes Lee, et  on le retrouve en coulisses qui verse des larmes et marche vers le ring en disant que c&rsquo;est bien d&rsquo;\u00eatre de retour \u00e0 la maison et que son seul objectif est le championnat Nord-Am\u00e9ricain.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Wes Lee vs Josh Briggs<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin, Lee repousse Briggs en bas du ring et se lance en saut suicide. Lee enchaine avec un Drop Kick sur Briggs et il chute sur Ivar qui \u00e9tait \u00e0 la table des commentateurs. Lee ram\u00e8ne Briggs sur le ring et lui fait son Corkscrew Splash pour le compte de trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnant : Wes Lee<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, Ivar et Briggs commencent \u00e0 \u00e9changer les coups en ringside pendant la c\u00e9l\u00e9bration de Wes Lee. Lee se lance du coin sur les deux alors que Oba Femi regarde la sc\u00e8ne en rigolant.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur le NXT Underground Match entre Natalya et Vice de&nbsp;la semaine derni\u00e8re \u00e0 NXT.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; En coulisses, des \u00e9quipes discutent avec Nathan Frazer et Axiom pour les f\u00e9liciter de leur match. Le clan de Charlie Dempsey arrive et d\u00e9clare que c&rsquo;est dr\u00f4le de voir Dupont et Igwe parler ainsi alors qu&rsquo;ils ont perdu. Dupont dit qu&rsquo;ils n&rsquo;ont pas peur de la douleur. Les deux \u00e9quipes argumentent. The OC arrive. Karl Anderson dit qu&rsquo;ils ne vont pas se d\u00e9barrasser des \u00e9quipes de RAW et de SmackDown si facilement.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Shayna Baszler<em>&nbsp;acc de Lola Vice<\/em>&nbsp;vs Karmen Patrovic&nbsp;<em>acc de Natalya<\/em><\/strong><\/p>\n\n\n\n<p>\u00c0 la fin , Petrovic se lance du coin, mais Baszler la repousse au sol et lui applique sa Kirifuda Clutch pour la faire taper.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnante : Shayna Baszler&nbsp;<\/em><\/p>\n\n\n\n<p>&#8211; En coulisses, les catcheuses discutent de la trahison de Fallon Henley sur Thea Hail. Kelani Jordan demande quel genre d&rsquo;amie ferait \u00e7a. Fallon Henley arrive et lui demande pourquoi elle ne fait rien. Jordan dit qu&rsquo;elle croyait qu&rsquo;elles \u00e9taient des amies. Henley dit que maintenant elle pense qu&rsquo;\u00e0 elle. Les deux catcheuses commencent \u00e0 argumenter, mais elles se font s\u00e9parer.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o de pr\u00e9sentation sur le&nbsp;<strong>NXT Women&rsquo;s Combine<\/strong>&nbsp;o\u00f9 20 femmes vont s&rsquo;affronter dans diff\u00e9rentes \u00e9preuves afin de se qualifier. En passant par la vitesse et la force. On voit la premi\u00e8re \u00e9preuve o\u00f9 les catcheuses doivent pousser une charge et la seconde la rapidit\u00e9 en courant.<\/p>\n\n\n\n<p>&#8211; Le prochain match allait se lancer, mais l&rsquo;annonceuse pr\u00e9cise que l&rsquo;arbitre est \u00a0\u00bbindisponible\u00a0\u00bb pour le match sous la menace de la Famille D&rsquo;Angelo. Alors l&rsquo;arbitre sp\u00e9cial sera Channing Lorenzo.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Tyson Dupont et Tyriek Igwe vs Charlie Dempsey et Myles Borne&nbsp;<em>accompagn\u00e9 de Damon Kemp<\/em><\/strong><br><em>Arbitre sp\u00e9cial : Channing Lorenzo<\/em><\/p>\n\n\n\n<p>\u00c0 la fin, Lorenzo fait un compte lent de Dempsey tr\u00e8s lent. Dempsey est furieux et le pousse, Lorenzo le frappe ! Dupont en profite pour faire un Roll Up sur Dempsey pour le compte de trois, un compte tr\u00e8s rapide de l&rsquo;arbitre.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnants : Tyson Dupont et Tyriek Igwe<\/em><\/p>\n\n\n\n<p>&#8211; En coulisses, on retrouve Arianna Grace avec Gigi Dolin et Chelsea Green. Grace dit que c&rsquo;est fabuleux d&rsquo;avoir Green ici ce soir. La possibilit\u00e9 de voir Green championne lui fait chaud au coeur. <\/p>\n\n\n\n<p>Green dit qu&rsquo;elle a enfin trouv\u00e9 quelqu&rsquo;un de presque autant parfaite qu&rsquo;elle avec Grace. Green dit qu&rsquo;elle va prendre le titre au nom du vestiaire. Grace dit qu&rsquo;elle va aller s&rsquo;occuper de son probl\u00e8me Michin.<strong>&nbsp;<\/strong><\/p>\n\n\n\n<p>Dolin quitte en disant qu&rsquo;elle ne peut plus endurer cette histoire.<\/p>\n\n\n\n<p>&#8211; En coulisses, Kelly demande \u00e0 Roxanne Perez ses commentaires pour ce soir. Perez dit que ce n&rsquo;est pas une question d&rsquo;Ava ou Green, ce soir c&rsquo;est elle le sujet principal. Elle est le main event du show, elle est la prot\u00e9g\u00e9e. Personne n&rsquo;aime Green \u00e0 RAW et personne n&rsquo;aime Green ici. Elle va battre Green et on va encore entendre qu&rsquo;elle reste la championne.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Michin vs Arianna Grace<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin, Grace fait un compte en trichant, mais l&rsquo;arbitre voit le geste et arr\u00eate le compte. Michin en profite pour repousser Grace et lui faire son Eat Defeat pour le compte de trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnante : Michin<\/em><\/p>\n\n\n\n<p>&#8211; En coulisses, Thea Hail remercie Ridge Holland pour avoir pris de ses nouvelles et l&rsquo;aider dans cette col\u00e8re. Hail dit qu&rsquo;Andre Chase a essay\u00e9 de la calmer, mais rien ne semblait marcher. Holland dit que Hail lui rappel sa fille, il comprend bien Hail.<\/p>\n\n\n\n<p> Andre Chase et Chase U arrivent pour f\u00e9liciter Hail pour sa victoire. Lexis King arrive et demande ce qu&rsquo;ils font. Il a essay\u00e9 d&rsquo;aviser Holland que le business n&rsquo;est pas fait pour tout le monde. Holland dit que King m\u00e9rite une correction. <\/p>\n\n\n\n<p>Duke Hudson dit que King n&rsquo;a pas le droit de parler ainsi. King dit que Hudson vient de f\u00e2cher le roi et il devra payer.<\/p>\n\n\n\nhttps:\/\/ypmate.com\/cam\/AcadiaClark\n\n\n\n<p>&#8211; On retrouve Meta Four sur le ring pour le talk-show du Super Nova Sessions. Dar pr\u00e9sente le champion Trick Williams qui arrive sur le ring. Dar dit que tout va bien pour Williams, \u00e7a doit \u00eatre bien d&rsquo;\u00eatre Trick Williams. Ils ont pr\u00e9par\u00e9 une petite vid\u00e9o sur l&rsquo;ascension de Williams. On voit une vid\u00e9o sur la carri\u00e8re de Trick Williams. Williams dit qu&rsquo;il est ici pour une seule raison, il veut savoir ce que l&rsquo;enveloppe contient. <\/p>\n\n\n\n<p>Dar dit que c&rsquo;est son show, c&rsquo;est lui qui d\u00e9cide. Dar demande \u00e0 Lash Legend de montrer la premi\u00e8re preuve. Lash Legend dit que c&rsquo;est le moment de d\u00e9voiler la v\u00e9rit\u00e9.&nbsp;Legend sort une photo montrant que Noam Dar avait son pied sous un c\u00e2ble pendant un tomb\u00e9 sur lui.<\/p>\n\n\n\n<p>Dar dit que cette victoire a donn\u00e9 tout l&rsquo;\u00e9lan \u00e0 Trick Williams pour devenir champion. Cette photo montre que l&rsquo;ascension de Williams est construite sur un mensonge. Il va montrer de quoi est vraiment fait Williams. Williams demande s&rsquo;il est vraiment venu ici pour une photo. Oro Mensah parle, mais Williams lui dit de parler un bon anglais. Williams dit que si Dar veut un match de titre, il fallait seulement le demander, il n&rsquo;a aucun probl\u00e8me \u00e0 lui cogner la t\u00eate. Williams fait une allusion disant qu&rsquo;il a une relation avec Lash Legend. Legend dit que ce n&rsquo;est pas le temps.&nbsp;<\/p>\n\n\n\n<p>Williams termine en disant qu&rsquo;ils peuvent, ils sont entre eux. Legend doit d\u00e9voiler comment elle le nomme. Noam Dar porte un coup de genou \u00e0 Trick Williams !&nbsp;Dar pose avec le titre de NXT.<\/p>\n\n\n\n<p>&#8211; C&rsquo;est la suite du NXT Combine avec une \u00e9preuve d&rsquo;agilit\u00e9 et de force cette fois-ci.<\/p>\n\n\n\n<p>&#8211; En coulisses, Natalya et Petrovic marchent ensemble. Petrovic dit qu&rsquo;elle est d\u00e9sol\u00e9e de toujours la laisser tomber. Natalya dit que \u00e7a fait partie du processus de trouver sa fa\u00e7on sur le ring. Un homme arrive et dit que malgr\u00e9 la d\u00e9faite de Petrovic elle reste bien jolie. Petrovic le sonne avec un Round Kick !<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Kelani Jordan vs Fallon Henley<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin, Jordan charge Henley, mais Henley la repousse contre le coin qui n&rsquo;avait plus de coussin. Henley enchaine avec son Shinning Wizard pour le compte de trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnante : Fallon Henley<\/em><\/p>\n\n\n\n<p>&#8211; En coulisses, on retrouve le clan de Charlie Dempsey. Dempsey dit que Tony D&rsquo;Angelo veut son paiement, il va lui donner ce qu&rsquo;il veut. Mais D&rsquo;Angelo va le regretter, c&rsquo;est son clan qui a tout le pouvoir avec l&rsquo;Heritage Cup. La Famille peut \u00e9tudier ce qu&rsquo;ils veulent, \u00e7a ne changera rien pour la suite.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une troisi\u00e8me vid\u00e9o sur le&nbsp;NXT Women&rsquo;s Combine et l&rsquo;\u00e9preuve est sur la force et l&rsquo;endurance cette fois-ci.<\/p>\n\n\n\n<p>&#8211; En coulisses, Kelly demande \u00e0 Ava qui sont les&nbsp;catcheuses s\u00e9lectionner suite au Women&rsquo;s Combine. Ava dit qu&rsquo;elle a s\u00e9lectionn\u00e9 les 12 noms&nbsp;qui sont&nbsp;Sol Ruca, Thea Hail, Jaida Parker, Brinley Reece, Michin, Fallon Henley, Lash Legend, Ivy Nile, Izzi Dame, Kelani Jordan, Tatum Paxley et Wren Sinclair. Et les matchs du tournoi vont commencer la semaine prochaine.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Lexis King vs Duke Hudson&nbsp;<em>acc de Chase U<\/em><\/strong><\/p>\n\n\n\n<p>\u00c0 la fin, King fait son Running Knee derri\u00e8re la t\u00eate de Hudson. Thea Hail est en col\u00e8re, King s&rsquo;approche d&rsquo;elle, mais Ridge Holland arrive avec une chaise. Hudson se retrouve avec la chaise dans les mains par erreur, l&rsquo;arbitre lui enl\u00e8ve et King profite de la distraction pour faire son Coronation pour le compte de trois sur Hudson.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnant : Lexis King<\/em><\/p>\n\n\n\n<p>&#8211; Dans le stationnement ext\u00e9rieur du Centre de Performance de la WWE, Meta Four quitte, mais Je&rsquo;Von Evans arrive pour venir voir Trick Williams. Oro Mensah lui dit de bouger de leur chemin. Dar lui demande c&rsquo;est quoi son point. Evans les avise de se calmer. Dar dit que ce n&rsquo;est pas le bon moment pour les provoquer.<\/p>\n\n\n\n<p>&#8211; En coulisses, Jazmyn Nyx annonce que&nbsp;Jacy Jayne a souffert d&rsquo;une fracture au nez pendant son match contre Thea Hail. <\/p>\n\n\n\n<p>Ava devrait suspendre Hail pour le geste et elle va tout faire en son pouvoir pour venger Jayne.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; En coulisses, on retrouve Chase U. Ridge Holland arrive et dit qu&rsquo;il est d\u00e9sol\u00e9, il ne voulait pas causer leur d\u00e9faite. Il comprend qu&rsquo;ils sont en col\u00e8re. <\/p>\n\n\n\n<p>Hudson dit qu&rsquo;ils comprennent. Holland dit que s&rsquo;il doit gagner leur confiance et respect, il le fera.<\/p>\n\n\n\n<p style=\"font-size:25px\"><strong>Championnat F\u00e9minin NXT<\/strong><\/p>\n\n\n\n<p><strong>Chelsea Green vs Roxanne Perez <\/strong>\u00a9<\/p>\n\n\n\n<p>\u00c0 la fin du combat, Green veut faire son finisher, mais Perez la bloque. Green fait des comptes rapides sur Perez, mais elle r\u00e9siste \u00e0 deux. Perez enchaine avec son Code Red pour le compte de trois sur Green.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnante : Roxanne Perez<\/em><\/p>\n\n\n\n<p>&#8211; Sur le parking, on retrouve la Famille D&rsquo;Angelo qui attaque Damon Kemp et Myles Borne et les embarque dans leur voiture. T<\/p>\n\n\n\n<p>ony D&rsquo;Angelo avise Charlie Dempsey qu&rsquo;il n&rsquo;a aucun contr\u00f4le.&nbsp;La Famille quitte en voiture avec Kemp et Borne dans le coffre. Charlie Dempsey sort du building et cherche ses partenaires. Le show se termine ainsi.<\/p>\n\n\n\n<p>Le show se termine avec une c\u00e9l\u00e9bration de la championne.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-center\" style=\"font-size:25px\"><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2024\/05\/07\/avant-gout-pour-le-wwe-nxt-du-7-mai-2024\/\" target=\"_blank\">Pour voir NXT,  cliquez ici.<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"Gb1aU516B3\"><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/05\/07\/avant-gout-pour-le-wwe-nxt-du-7-mai-2024\/\">Reprise Vid\u00e9o et Programme pour le WWE NXT du 7 mai 2024!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Reprise Vid\u00e9o et Programme pour le WWE NXT du 7 mai 2024!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2024\/05\/07\/avant-gout-pour-le-wwe-nxt-du-7-mai-2024\/embed\/#?secret=A3WPlEizhi#?secret=Gb1aU516B3\" data-secret=\"Gb1aU516B3\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>WWE NXT, Orlando, Floride, 7 mai 2024 Les commentateurs sont Vic Joseph et Booker T. -Le WWE NXT d\u00e9bute sur une vid\u00e9o sur la blessure et le retour de Wes Lee, et on le retrouve en coulisses qui verse des larmes et marche vers le ring en disant que c&rsquo;est bien d&rsquo;\u00eatre de retour \u00e0&#8230;<\/p>\n","protected":false},"author":609,"featured_media":99394,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85,21,23],"tags":[],"ppma_author":[295],"class_list":["post-99393","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nxt","category-resultats","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/99393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=99393"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/99393\/revisions"}],"predecessor-version":[{"id":99396,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/99393\/revisions\/99396"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/99394"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=99393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=99393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=99393"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=99393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}