{"id":98828,"date":"2024-04-25T16:18:34","date_gmt":"2024-04-25T20:18:34","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=98828"},"modified":"2024-04-25T16:18:36","modified_gmt":"2024-04-25T20:18:36","slug":"la-saga-se-poursuit-janel-grant-contrecarre-vince-mcmahon-en-deposant-une-requete-pour-radier-la-derniere-decision-juridique-de-mcmahon","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/04\/25\/la-saga-se-poursuit-janel-grant-contrecarre-vince-mcmahon-en-deposant-une-requete-pour-radier-la-derniere-decision-juridique-de-mcmahon\/","title":{"rendered":"La saga se poursuit: Janel Grant contrecarre Vince McMahon en d\u00e9posant une requ\u00eate pour radier la derni\u00e8re d\u00e9cision juridique de McMahon!"},"content":{"rendered":"\n<p>Janel Grant contre-attaque.<\/p>\n\n\n\n<p>Grant et son \u00e9quipe d\u2019avocats ont rapidement contr\u00e9 la requ\u00eate de Vince McMahon, son \u00e9quipe juridique, visant \u00e0 forcer l\u2019arbitrage concernant le proc\u00e8s intent\u00e9 par Grant plus t\u00f4t cette ann\u00e9e. Grant a r\u00e9pondu en contestant les affirmations de McMahon, d\u00e9clarant que McMahon avait r\u00e9fut\u00e9 avec v\u00e9h\u00e9mence les all\u00e9gations de Grant, qui englobaient des accusations de trafic sexuel, de maltraitance \u00e9motionnelle et d\u2019agression sexuelle.<\/p>\n\n\n\n<p>Dans une r\u00e9plique rapide, Grant d\u00e9posa une requ\u00eate pour \u00e9liminer les d\u00e9clarations initiales de McMahon du dossier juridique, indiquant qu\u2019il \u00e9tait pr\u00eat \u00e0 contester sa position devant les tribunaux.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>La d\u00e9claration pr\u00e9liminaire de McMahon se lisait comme suit :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>En d\u00e9posant publiquement sa plainte salace, fausse et diffamatoire, la demanderesse a viol\u00e9 effront\u00e9ment et intentionnellement un contrat d\u2019arbitrage contraignant. Les all\u00e9gations scandaleuses d\u2019abus sexuel et de coercition formul\u00e9es dans la plainte sont de la pure fiction \u2013 manifestement destin\u00e9es \u00e0 attirer la publicit\u00e9 \u2013 et sont cat\u00e9goriquement contredites par les propres d\u00e9clarations contemporaines du demandeur. Contrairement aux fausses all\u00e9gations de la demanderesse, la demanderesse et la d\u00e9fenderesse (collectivement, les \u00ab parties \u00bb) se sont engag\u00e9es dans une relation consensuelle au cours de laquelle la d\u00e9fenderesse n\u2019a jamais forc\u00e9 la demanderesse \u00e0 faire quoi que ce soit et ne l\u2019a jamais maltrait\u00e9e de quelque fa\u00e7on que ce soit. En fait, dans une lettre d\u2019amour que la demanderesse a \u00e9crite \u00e0 la d\u00e9fenderesse peu de temps avant que les parties ne mettent fin \u00e0 leur relation, la demanderesse a d\u00e9crit la d\u00e9fenderesse comme [traduction] \u00ab [m]e meilleur ami, mon amour et tout \u00bb, le f\u00e9licitant d\u2019\u00eatre \u00ab l\u2019\u00e2me merveilleuse, tendre, vuln\u00e9rable et le c\u0153ur sur la manche que vous \u00eates vraiment \u00bb. Il est incr\u00e9dule que la demanderesse, une femme alors \u00e2g\u00e9e de 42 ans qui pr\u00e9tend avoir un dipl\u00f4me en droit de l\u2019Universit\u00e9 Pace, ait \u00e9crit ces mots \u00e0 la d\u00e9fenderesse des mois apr\u00e8s que tous les \u00e9v\u00e9nements de la plainte d\u2019abus, de coercition et de \u00ab trafic sexuel \u00bb pr\u00e9sum\u00e9s aient eu lieu.<\/p>\n\n\n\n<p>Au moment o\u00f9 les parties se sont rencontr\u00e9es en 2019, la demanderesse n\u2019\u00e9tait pas \u00ab aux prises avec un profond chagrin [\u00e0 la suite du d\u00e9c\u00e8s de ses parents] et n\u2019\u00e9prouvait pas de difficult\u00e9s financi\u00e8res \u00bb comme d\u00e9crit dans sa plainte et elle n\u2019avait pas \u00ab consacr\u00e9 des ann\u00e9es \u00e0 s\u2019occuper de ses parents 24 heures sur 24 \u00bb. (Voir Compl. \u00b6 3.) Ces affirmations sont compl\u00e8tement fausses. Sur la base d\u2019une action en forclusion contre la demanderesse et ses parents, le p\u00e8re de la demanderesse est d\u00e9c\u00e9d\u00e9 le 18 avril 2017 \u2013 deux ans avant que la demanderesse ne rencontre la d\u00e9fenderesse \u2013 et son \u00e9tat matrimonial a \u00e9t\u00e9 enregistr\u00e9 comme \u00ab veuf \u00bb, confirmant que la m\u00e8re de la demanderesse \u00e9tait d\u00e9c\u00e9d\u00e9e plus t\u00f4t.<\/p>\n<\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Les dossiers judiciaires montrent en outre que, contrairement \u00e0 son affirmation selon laquelle elle prodiguait des soins 24 heures sur 24, le p\u00e8re de la demanderesse vivait dans une maison de retraite \u00e0 Stamford, dans le Connecticut, avant de d\u00e9c\u00e9der \u2013 et non avec elle \u2013 et que le voisin des Grant apportait \u00e0 la m\u00e8re de la plaignante le d\u00eener et \u00ab l\u2019aidait \u00e0 la maison \u00bb avant qu\u2019elle ne d\u00e9c\u00e8de. Id. Dkt. No. 31 (\u00ab Affidavit de diligence raisonnable \u00bb), \u00e0 la p. 3. En fait, contrairement \u00e0 ce qu\u2019elle a racont\u00e9 dans la plainte, l\u2019action en forclusion de la maison de ses parents r\u00e9v\u00e8le que la demanderesse \u00e9tait cat\u00e9gorique sur le fait qu\u2019elle ne voulait pas \u00eatre associ\u00e9e \u00e0 \u00ab tout cela \u00bb et qu\u2019elle n\u2019avait pas r\u00e9pondu aux demandes concernant l\u2019action en forclusion. Affidavit de diligence raisonnable, p. 3. En effet, la demanderesse \u00e9tait tellement absente de la vie de ses parents qu\u2019il a fallu beaucoup de temps et d\u2019efforts consid\u00e9rables au cr\u00e9ancier dans l\u2019action pour la localiser et l\u2019identifier comme \u00e9tant la plus proche parente de ses parents.<\/p>\n\n\n\n<p>En plus des mensonges sur ses propres ant\u00e9c\u00e9dents, la plainte de la demanderesse est en outre truff\u00e9e de fabrications et d\u2019omissions au sujet de sa relation avec le d\u00e9fendeur. Au cours de la relation consensuelle des parties, la demanderesse et la d\u00e9fenderesse savaient que l\u2019autre \u00e9tait \u00e9galement impliqu\u00e9e dans d\u2019autres relations amoureuses. La demanderesse vivait \u00e0 Park Tower, un immeuble de luxe de plusieurs millions de dollars \u00e0 Stamford, dans le Connecticut, avec son fianc\u00e9 de longue date, l\u2019avocat Brian Goncalves (\u00ab Goncalves \u00bb). Depuis ao\u00fbt 2022, M. Goncalves occupe le poste de vice-pr\u00e9sident principal et directeur de la protection de la vie priv\u00e9e de TelevisaUnivision, et il a pr\u00e9c\u00e9demment occup\u00e9 des postes chez Mastercard et Hewlett-Packard. La demanderesse et Goncalves vivaient dans le m\u00eame immeuble de luxe que la d\u00e9fenderesse, \u00e0 peine quatre \u00e9tages plus bas, lorsque les parties ont commenc\u00e9 leur liaison en 2019. La demanderesse rendait souvent visite \u00e0 la d\u00e9fenderesse dans son condominium \u00e0 toute heure, y compris \u00e0 2 h 30 du matin, pour poursuivre leur liaison, puis retournait \u00e0 son condominium avec Goncalves le soir m\u00eame. Il est absurde que les actes troublants all\u00e9gu\u00e9s dans la plainte, y compris la violence, les relations sexuelles forc\u00e9es et le fait de forcer la demanderesse \u00e0 d\u00e9f\u00e9quer dessus, aient eu lieu avant que la demanderesse ne retourne aupr\u00e8s de son fianc\u00e9 avocat quatre \u00e9tages plus bas sans incident. Le d\u00e9fendeur n\u2019a jamais \u00e9t\u00e9 contact\u00e9 par Goncalves (qui si\u00e9geait au conseil d\u2019administration de l\u2019immeuble de luxe), par qui que ce soit dans l\u2019immeuble, par la police, par des amis du demandeur ou par un avocat ou un d\u00e9fenseur du demandeur \u00e0 aucun moment au sujet du comportement abusif fictif, \u00e9tendu et de plusieurs ann\u00e9es all\u00e9gu\u00e9 dans la plainte.<\/p>\n<\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Apr\u00e8s trois ans et apr\u00e8s avoir d\u00e9cid\u00e9 de retourner chez leurs partenaires, en janvier 2022, le demandeur et le d\u00e9fendeur ont convenu de mettre fin \u00e0 leur liaison consensuelle et de se s\u00e9parer l\u2019un de l\u2019autre, le demandeur quittant la soci\u00e9t\u00e9 o\u00f9 ils travaillaient, World Wrestling Entertainment, Inc. (\u00ab WWE \u00bb). La demanderesse et la d\u00e9fenderesse ont conclu un contrat ex\u00e9cutoire pour comm\u00e9morer cette entente, intitul\u00e9 Entente de r\u00e8glement confidentielle, renonciation g\u00e9n\u00e9rale et engagement de ne pas intenter de poursuite (pi\u00e8ce 1, l&rsquo;\u00ab entente \u00bb ou l&rsquo;\u00ab entente \u00bb). 1 La demanderesse voulait initialement inclure une condition dans le contrat stipulant que la d\u00e9fenderesse ne pouvait pas quitter l\u2019immeuble qu\u2019elle partageait, mais la d\u00e9fenderesse a refus\u00e9 d\u2019inclure cette condition et a d\u00e9m\u00e9nag\u00e9. L\u2019affirmation du demandeur selon laquelle ce contrat, entre le d\u00e9fendeur et la WWE, d\u2019une part, et le demandeur, d\u2019autre part, n\u2019est pas ex\u00e9cutoire est totalement d\u00e9nu\u00e9e de fondement, mais c\u2019est une question qui rel\u00e8ve de l\u2019arbitre. En fait, parce que les parties souhaitaient \u00ab pr\u00e9server le caract\u00e8re confidentiel et priv\u00e9 \u00bb de tout diff\u00e9rend en vertu de l\u2019accord, elles pr\u00e9voyaient express\u00e9ment dans l\u2019accord que les diff\u00e9rends seraient r\u00e9solus par voie d\u2019arbitrage. La demanderesse \u00e9tait repr\u00e9sent\u00e9e par un avocat qui a n\u00e9goci\u00e9 l\u2019entente pour elle avant qu\u2019elle ne l\u2019ex\u00e9cute.<\/p>\n\n\n\n<p>Lorsque le d\u00e9fendeur a appris que la demanderesse, malgr\u00e9 ses promesses, avait viol\u00e9 l\u2019entente en divulguant \u00e0 tort l\u2019existence de l\u2019entente et leur relation, il a exerc\u00e9 son droit contractuel de retenir le paiement qui lui \u00e9tait autrement d\u00fb en vertu de l\u2019entente. En r\u00e9ponse,<br>1 La pi\u00e8ce 1, qui est jointe \u00e0 la d\u00e9claration de Vincent K. McMahon (\u00ab McMahon Decl. \u00bb) jointe aux pr\u00e9sentes, est l\u2019accord enti\u00e8rement sign\u00e9. La pi\u00e8ce 1 est par ailleurs identique \u00e0 la pi\u00e8ce A de la plainte (Dkt. n\u00b0 1-1), qui n\u2019est sign\u00e9e que par le demandeur.<\/p>\n\n\n\n<p>Le demandeur a cherch\u00e9 \u00e0 lui nuire. Elle a intentionnellement viol\u00e9 le contrat ex\u00e9cutoire en d\u00e9posant publiquement des documents salaces, faux et diffamatoires. Cependant, la FAA et la jurisprudence contraignante de la Cour supr\u00eame des \u00c9tats-Unis \u2013 ainsi que l\u2019accord de la demanderesse elle-m\u00eame \u2013 exigent que si la demanderesse souhaite aller de l\u2019avant avec ses r\u00e9clamations fictives, elle doit le faire dans le cadre d\u2019un arbitrage, et non devant cette Cour, et que cette action soit suspendue en attendant l\u2019arbitrage.<\/p>\n\n\n\n<p>Comme il s\u2019agit d\u2019une requ\u00eate pr\u00e9alable \u00e0 la r\u00e9ponse, le d\u00e9fendeur n\u2019aborde pas sp\u00e9cifiquement le bien-fond\u00e9 des chefs d\u2019accusation du demandeur retenus contre lui. Pour \u00e9viter toute ambigu\u00eft\u00e9, cependant, la d\u00e9fenderesse nie avec v\u00e9h\u00e9mence et cat\u00e9goriquement toutes les all\u00e9gations d\u2019actes r\u00e9pr\u00e9hensibles dans la plainte, y compris les all\u00e9gations scandaleuses de la demanderesse selon lesquelles la d\u00e9fenderesse l\u2019a forc\u00e9e \u00e0 des actes sexuels non d\u00e9sir\u00e9s, l\u2019a agress\u00e9e sexuellement et\/ou battue, l\u2019a trafiqu\u00e9e et a d\u00e9f\u00e9qu\u00e9 sur elle. Il s\u2019agit l\u00e0 de fausses d\u00e9clarations destin\u00e9es \u00e0 la publicit\u00e9. Lorsque les all\u00e9gations de la plainte sont jug\u00e9es dans le forum appropri\u00e9 (arbitrage), que des t\u00e9moins sont appel\u00e9s \u00e0 t\u00e9moigner sous serment et que toutes les communications entre les parties (y compris celles r\u00e9dig\u00e9es par la demanderesse qu\u2019elle n\u2019a intentionnellement pas partag\u00e9es dans sa plainte) sont produites, les all\u00e9gations et les all\u00e9gations seront r\u00e9fut\u00e9es et la demanderesse sera expos\u00e9e pour la menteuse qu\u2019elle est. Dans l\u2019intervalle, pour les motifs qui pr\u00e9c\u00e8dent et tels qu\u2019ils sont expos\u00e9s ci-dessous, la requ\u00eate de la d\u00e9fenderesse devrait \u00eatre accueillie.<\/p>\n<\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Voici la r\u00e9ponse de Grant :<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>M\u00eame pour Vince McMahon, les d\u00e9clarations sans fondement, non pertinentes et fausses de la \u00ab d\u00e9claration pr\u00e9liminaire \u00bb de la motion, con\u00e7ues uniquement pour harceler et intimider sa victime de longue date, Janel Grant, sont un nouveau creux. Par exemple, les affirmations non \u00e9tay\u00e9es de McMahon selon lesquelles Janel \u00e9tait \u00ab absente \u00bb de la vie de ses parents mourants et fianc\u00e9e \u00e0 un riche avocat lorsqu\u2019elle a rencontr\u00e9 McMahon ne sont pas seulement des mensonges con\u00e7us par McMahon pour intimider Janel afin qu\u2019elle se soumette \u2013 comme il l\u2019a fait d\u2019innombrables fois auparavant \u2013 mais n\u2019ont rien \u00e0 voir avec les arguments juridiques soulev\u00e9s par la requ\u00eate. Les mensonges de McMahon sont facilement r\u00e9fut\u00e9s. En v\u00e9rit\u00e9, alors que le p\u00e8re de Janel \u00e9tait en soins palliatifs \u00e0 domicile pendant ses derniers jours, Janel a continu\u00e9 \u00e0 lui fournir des soins 24 heures sur 24. En m\u00eame temps, Janel s\u2019est \u00e9galement occup\u00e9e de sa m\u00e8re aveugle et en fauteuil roulant jusqu\u2019\u00e0 sa mort. De plus, Janel ne sortait pas avec son ex-fianc\u00e9 en 2019, et encore moins ne s\u2019\u00e9tait pas fianc\u00e9e \u00e0 lui. Au contraire, l\u2019ex-fianc\u00e9 de Janel a g\u00e9n\u00e9reusement permis \u00e0 Janel de rester dans son appartement alors qu\u2019elle reconstruisait sa vie apr\u00e8s le d\u00e9c\u00e8s de ses parents. <\/p>\n\n\n\n<p>Pendant ce temps, Janel n\u2019avait pas d\u2019emploi ni d\u2019autre soutien financier que l\u2019amiti\u00e9 et la g\u00e9n\u00e9rosit\u00e9 de son ex. Conform\u00e9ment \u00e0 son comportement pass\u00e9, McMahon tord ces v\u00e9rit\u00e9s pour les adapter \u00e0 son propre r\u00e9cit fictif, un peu comme le monde imaginaire de la lutte professionnelle d\u2019o\u00f9 il vient. Pourtant, m\u00eame si les mensonges de McMahon concernant la vie priv\u00e9e de Janel \u00e9taient vrais (ils ne le sont pas), ces d\u00e9clarations n\u2019ont aucune incidence sur le bien-fond\u00e9 des r\u00e9clamations de Janel, et encore moins sur la requ\u00eate. Les d\u00e9clarations de McMahon n\u2019ont pas leur place dans la requ\u00eate, qui devrait porter uniquement sur la question de savoir si ce diff\u00e9rend doit \u00eatre soumis \u00e0 l\u2019arbitrage. Il n\u2019\u00e9tait ni n\u00e9cessaire, ni raisonnable, ni responsable d\u2019avoir recours \u00e0 un d\u00e9p\u00f4t public pour contester la moralit\u00e9 de Janel. En effet, la tentative d\u00e9sesp\u00e9r\u00e9e de McMahon de d\u00e9tourner l\u2019attention de la substance juridique de la requ\u00eate met en \u00e9vidence sa faiblesse et la faiblesse de l\u2019ensemble de son argumentation. Notre Cour a le pouvoir inh\u00e9rent de radier les documents d\u00e9pos\u00e9s par une partie. La Cour devrait user de ce pouvoir pour radier l&rsquo;\u00ab expos\u00e9 pr\u00e9liminaire \u00bb de la requ\u00eate dans son int\u00e9gralit\u00e9 et avertir McMahon et son avocat que de telles d\u00e9clarations n\u2019ont pas leur place dans un litige civil.<\/p>\n<\/blockquote>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"4xzEkEZ8qQ\"><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/04\/24\/vince-mcmahon-la-wwe-et-john-laurinaitis-repondront-au-proces-de-janel-grant-a-moins-que-le-tout-se-regle-devant-un-arbitre\/\">Vince McMahon, la WWE et John Laurinaitis r\u00e9pondront au proc\u00e8s de Janel Grant \u00e0 moins que le tout se r\u00e8gle devant un arbitre!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Vince McMahon, la WWE et John Laurinaitis r\u00e9pondront au proc\u00e8s de Janel Grant \u00e0 moins que le tout se r\u00e8gle devant un arbitre!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2024\/04\/24\/vince-mcmahon-la-wwe-et-john-laurinaitis-repondront-au-proces-de-janel-grant-a-moins-que-le-tout-se-regle-devant-un-arbitre\/embed\/#?secret=JIs0JUmFrT#?secret=4xzEkEZ8qQ\" data-secret=\"4xzEkEZ8qQ\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Janel Grant contre-attaque. Grant et son \u00e9quipe d\u2019avocats ont rapidement contr\u00e9 la requ\u00eate de Vince McMahon, son \u00e9quipe juridique, visant \u00e0 forcer l\u2019arbitrage concernant le proc\u00e8s intent\u00e9 par Grant plus t\u00f4t cette ann\u00e9e. Grant a r\u00e9pondu en contestant les affirmations de McMahon, d\u00e9clarant que McMahon avait r\u00e9fut\u00e9 avec v\u00e9h\u00e9mence les all\u00e9gations de Grant, qui englobaient&#8230;<\/p>\n","protected":false},"author":665,"featured_media":98854,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,4,23],"tags":[],"ppma_author":[289],"class_list":["post-98828","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ex-wwe","category-news","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/98828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=98828"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/98828\/revisions"}],"predecessor-version":[{"id":98855,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/98828\/revisions\/98855"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/98854"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=98828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=98828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=98828"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=98828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}