{"id":98809,"date":"2024-04-24T23:43:30","date_gmt":"2024-04-25T03:43:30","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=98809"},"modified":"2024-04-27T16:18:52","modified_gmt":"2024-04-27T20:18:52","slug":"resultats-et-video-pour-le-aew-dynamite-du-24-avril-2024","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/04\/24\/resultats-et-video-pour-le-aew-dynamite-du-24-avril-2024\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le AEW Dynamite du 24 Avril 2024!"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/04\/24\/avant-gout-pour-le-aew-dynamite-du-24-avril-2024\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir Dynamite, cliquez ici.<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size\"><strong>AEW Dynamite Jacksonville, Floride, 24 avril 2024<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Taz, Tony Schiavone et Excalibur.<\/p>\n\n\n\n<p>&#8211; Le AEW Dynamite d\u00e9bute sur une vid\u00e9o de plus t\u00f4t aujourd&rsquo;hui o\u00f9 The Elite d\u00e9barque en voiture. Les trois discutent de leur victoire \u00e0 Dynasty.&nbsp;Une seconde voiture arrive et Jack Perry en sort ! The Elite lui souhaite la bienvenue.&nbsp;La s\u00e9curit\u00e9 veut stopper Jack Perry d&rsquo;entrer dans la salle, mais Matthew dit que Jack Perry est avec eux.<\/p>\n\n\n\n<p>&#8211; Les commentateurs nous souhaitent la bienvenue en direct du Daily&rsquo;s Place. <\/p>\n\n\n\n<p>&#8211; La musique d&rsquo;Orange Cassidy commence, mais il se fait attaquer par Trent Beretta. Beretta am\u00e8ne Cassidy sur le ring en lui donnant des coups. Beretta prend le micro et demande \u00e0 Chuck Taylor des rejoindre car c&rsquo;est le moment. Taylor arrive.<\/p>\n\n\n\n<p> Beretta dit qu&rsquo;il soit d&rsquo;excuser. Il s&rsquo;excuse de ne pas avoir fait \u00e7a avant. Il s&rsquo;excuse qu&rsquo;ils ont pass\u00e9 5 ans \u00e0 faire des c\u00e2lins \u00e0 ce narcissique. Orange Cassidy devait \u00eatre leur mascotte, mais Cassidy a pris leur place. Beretta dit que Cassidy n&rsquo;est pas leur ami. Beretta dit \u00e0 Taylor de faire la bonne chose et donner aux gens ce qu&rsquo;ils veulent.<\/p>\n\n\n\n<p>Beretta ouvre ses bras et attend Taylor. Taylor dit qu&rsquo;il a toujours vu Beretta comme une merde. Taylor le frappe avec le micro, mais Beretta s&rsquo;\u00e9chappe&nbsp;! Taylor dit qu&rsquo;il ne veut pas l&rsquo;affronter sur le ring, mais bien dans le parking !<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; En coulisses, on retrouve Jon Moxley. Moxley dit qu&rsquo;il est confiant pour d\u00e9fendre son titre IWGP avec succ\u00e8s ce soir. Ce n&rsquo;est pas de l&rsquo;arrogance ou ignorance. Il connait bien Hobbs, il sait bien ce que Hobbs peut faire. Un g\u00e9ant qui peut \u00e9craser quelqu&rsquo;un. Une seule erreur et son univers peut s&rsquo;effondrer. Moxley dit qu&rsquo;il sait ce que \u00e7a prend pour rester au sommet. Il va marcher en enfer ce soir comme il a connu. Il va rappeler au monde entier qui il est ce soir.<\/p>\n\n\n\n<p>&#8211; La musique de Swerve Strickland commence et Princa Nana nous pr\u00e9sente le nouveau champion mondial AEW.<\/p>\n\n\n\n<p style=\"font-size:25px\"><strong>AEW World Title Eliminator <\/strong><\/p>\n\n\n\n<p><strong>Swerve Strickland&nbsp;<em>acc de Prince Nana<\/em>&nbsp;vs Kyle Fletcher<em>&nbsp;accompagn\u00e9 de Don Callis<\/em><\/strong><\/p>\n\n\n\n<p>En fin de match, Strickland se lance en House Call, mais Fletcher lui attrape la jambe pour lui appliquer un Ankle Lock. Strickland arrive \u00e0 le repousser. Les deux \u00e9changent les coups. Strickland arrive \u00e0 faire un Flatliner et un Brain Buster sur Fletcher pour le couvrir, mais il r\u00e9siste \u00e0 deux. Strickland veut faire un PileDriver, mais Fletcher renverse la prise en sa faveur pour le couvrir, et il r\u00e9siste \u00e0 deux. Don Callis hurle des instructions \u00e0 Fletcher. Fletcher ne l&rsquo;\u00e9coute pas et porte un coup de pied \u00e0 Strickland. Fletcher le prend pour une Superplex, mais Strickland le repousse et lui fait un Double Stomp pour le couvrir, mais il r\u00e9siste \u00e0 deux. Strickland lui fait un House Call pour le compte de trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnant : Swerve Strickland<\/em><\/p>\n\n\n\n<p>&#8211; En coulisses, on voit The Elite avec Jack Perry entrer dans le bureau de Tony Khan.<\/p>\n\n\n\n<p>&#8211; En coulisses, Renee Paquette est avec Thunder Rosa pour avoir ses commentaires sur sa d\u00e9faite \u00e0 Dynasty. Rosa dit qu&rsquo;elle pourrait se plaindre et dire que Deonna Purrazzo s&rsquo;est encore point\u00e9e dans son match, mais elle ne va pas le faire. Purrazzo arrive et les deux catcheuses argumentent et commencent \u00e0 se pousser.<\/p>\n\n\n\n<p>&#8211; De retour suite \u00e0 la pause, on pr\u00e9sente une vid\u00e9o sur le match entre Ospreay et Danielson \u00e0&nbsp;AEW Dynasty dimanche dernier.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Mina Shirakawa&nbsp;<em>acc de Mariah May<\/em>&nbsp;vs Anna Jay<\/strong><\/p>\n\n\n\n<p>En fin de match, Jay bloque le DDT de Shirakawa et veut lui appliquer son Queen Slayer. Jay est distraire par May, et Shirakawa en profite pour lui faire un compte de trois pour la victoire.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gafnante : Mina Shirakawa&nbsp;<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, Mariah May d\u00e9barque sur le ring avec le champagne pour c\u00e9l\u00e9brer, mais Anna Jay attaque les deux dans le dos ! Jay applique son Queen Slayer sur May, mais Toni Storm arrive sur le ring. <\/p>\n\n\n\n<p>Anna Jay prend la fuite. La musique de Serena Deeb commence et elle arrive sur la sc\u00e8ne. <\/p>\n\n\n\n<p>Deeb dit que la prochaine fois qu&rsquo;elle va toucher au titre f\u00e9minin c&rsquo;est parce qu&rsquo;elle sera la championne f\u00e9minine AEW.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; De retour, Stokely Hathaway et Kris Statlander sont sur le ring pour pr\u00e9senter la nouvelle championne TBS Willow Nightingale. Nightingale arrive sur le ring. Hathaway dit qu&rsquo;il n&rsquo;aimait pas Nightingale lorsque tout a commenc\u00e9, il n&rsquo;aimait pas son \u00e9nergie, mais maintenant tout va bien. Tout le monde est bien fier de Nightingale. Nightingale dit qu&rsquo;en 2020 elle \u00e9tait en premi\u00e8re rang\u00e9e ici \u00e0 soutenir les catcheurs et en 2022 elle a eu sa premi\u00e8re chance. Nightingale dit que ce soir elle n&rsquo;est plus une rookie, mais bien l&rsquo;image de TBS ! La musique de Mercedes Mon\u00e9 commence et la patronne arrive.<\/p>\n\n\n\n<p>Nightingale dit que c&rsquo;est comme la quatri\u00e8me fois que Mon\u00e9 vient l&rsquo;interrompe et c&rsquo;est son moment ce soir. Alors si Mon\u00e9 veut dire quelque chose, elle doit le faire pour de bon. Mon\u00e9 dit qu&rsquo;elle est aussi pour la f\u00e9liciter pour sa victoire et lui dire que dans 22 jours \u00e0 Double or Nothing on regarde \u00e0 la nouvelle championne. Elle voulait aussi savoir si c&rsquo;est Nightingale qui l&rsquo;a attaqu\u00e9 dans le noir l&rsquo;autre semaine. Kris Statlander dit que Nightingale a aussi \u00e9t\u00e9 attaqu\u00e9 avant. <\/p>\n\n\n\n<p>athaway dit que c&rsquo;est clairement Julia Hart. Nightingale dit que c&rsquo;est \u00e0 surveiller, mais est-ce que Mon\u00e9 croit vraiment qu&rsquo;elle a essay\u00e9 de la blesser \u00e0 la New Japan ? Mon\u00e9 demande si Nightingale veut vraiment savoir si elle la bl\u00e2me pour la douleur de sa blessure et \u00eatre sur la touche pendant un an ? Nightingale ne veut pas savoir la v\u00e9rit\u00e9. Nightingale dit qu&rsquo;elle se sent mal que c&rsquo;est arriv\u00e9 \u00e0 Mon\u00e9, mais elle aussi \u00e0 beaucoup douter. Apr\u00e8s le match, elle a dout\u00e9 en demandant si elle serait capable de battre une Mon\u00e9 \u00e0 100%. Les gens sur les r\u00e9seaux sociaux ont aussi soulev\u00e9 le point. Mais sa victoire du titre TBS \u00e0 Dynasty est bien d\u00e9finitive. Et elle veut Mon\u00e9 \u00e0 100% \u00e0 Double or Nothing afin de montrer qu&rsquo;elle peut battre Mon\u00e9 et pourquoi elle est la championne TBS. <\/p>\n\n\n\n<p>Mon\u00e9 lui r\u00e9pond de bien profiter du titre, car Willow sait bien qu&rsquo;elle ne peut pas la battre puis elles  font un face \u00e0 face. Mon\u00e9 veut quitter, Statlander lui attrape le bras, Mon\u00e9 croit que c&rsquo;est Willow et lui donne une claque. Les officiels arrivent sur le ring pour les s\u00e9parer.<\/p>\n\n\n\n<p>&#8211; En coulisses, Jack Perry sort du bureau de Tony Khan. Alex Marvez lui demande s&rsquo;il retrouve sa place \u00e0 la AEW. Perry ne r\u00e9pond rien et quitte. Marvez pose la m\u00eame question \u00e0 Okada et Nick Jackson, mais ils ne r\u00e9pondent pas. <\/p>\n\n\n\n<p>Matthew dit qu&rsquo;il aimerait lui donner une info sur le sujet, mais il peut seulement dire que Tony Khan a accept\u00e9 de rencontrer Jack Perry sur le ring en direct&nbsp;!<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-center\" style=\"font-size:25px\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/?p=98810\">Pour la suite de Dynamite, cliquez ici.<\/a><\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>AEW Dynamite Jacksonville, Floride, 24 avril 2024 Les commentateurs sont Taz, Tony Schiavone et Excalibur. &#8211; Le AEW Dynamite d\u00e9bute sur une vid\u00e9o de plus t\u00f4t aujourd&rsquo;hui o\u00f9 The Elite d\u00e9barque en voiture. Les trois discutent de leur victoire \u00e0 Dynasty.&nbsp;Une seconde voiture arrive et Jack Perry en sort ! The Elite lui souhaite la&#8230;<\/p>\n","protected":false},"author":4,"featured_media":98822,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,50,30,21],"tags":[],"ppma_author":[292],"class_list":["post-98809","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-dynamite","category-ex-wwe","category-resultats"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/98809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=98809"}],"version-history":[{"count":5,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/98809\/revisions"}],"predecessor-version":[{"id":99026,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/98809\/revisions\/99026"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/98822"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=98809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=98809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=98809"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=98809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}