{"id":98662,"date":"2024-04-21T02:26:00","date_gmt":"2024-04-21T06:26:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=98662"},"modified":"2024-04-22T14:35:00","modified_gmt":"2024-04-22T18:35:00","slug":"plusieurs-licenciements-a-la-wwe","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/04\/21\/plusieurs-licenciements-a-la-wwe\/","title":{"rendered":"Plusieurs licenciements \u00e0 la WWE!"},"content":{"rendered":"\n<p>Plusieurs Superstars de la WWE ont malheureusement \u00e9t\u00e9 licenci\u00e9es de la compagnie de catch.<\/p>\n\n\n\n<p>Ainsi, Fightful nous informe que\u00a0Jinder Mahal, Xia Li, Xyon Quinn, en plus de &#8230;\u00a0ont tous les trois \u00e9t\u00e9 renvoy\u00e9s de la WWE. Jinder Mahal a d&rsquo;ores et d\u00e9j\u00e0 confirm\u00e9 la nouvelle sur les r\u00e9seaux sociaux en disant qu&rsquo;il s&rsquo;en allait.<\/p>\n\n\n\n<p>Xia Li a \u00e9galement confirm\u00e9 son d\u00e9part sur X (Twitter) et remercie la WWE, Triple H et les fans, apr\u00e8s avoir rejoint la compagnie il y a 7 ans en tant que premi\u00e8re catcheuse chinoise.<\/p>\n\n\n\n<p>Toujours d&rsquo;apr\u00e8s Fightful, ces trois stars devront attendre 90 jours avant de monter sur le ring d&rsquo;une autre compagnie comme il est pr\u00e9vu pour ceux qui avaient des contrats WWE. Pour ceux de NXT c&rsquo;est 30 jours.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>Un autre catcheur fait \u00e9galement partie de cette liste de licenciements. H\u00e9las, nous apprenons via Fightful que\u00a0Von Wagner, catcheur de NXT qu&rsquo;on a pu vu quelques fois dans le Main Roster, a lui aussi \u00e9t\u00e9 renvoy\u00e9 la semaine derni\u00e8re.<\/p>\n\n\n\n<p>Ce catcheur am\u00e9ricain est le fils de Wayne Bloom, connu sous le nom de Beau Beverly dans les ann\u00e9es 90 \u00e0 la WWE. Il avait rejoint la WWE en 2019 et son aventure se termine malheureusement ici.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Voici la liste des noms licenci\u00e9s de la WWE (mise \u00e0 jour) :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Jinder Mahal<\/li>\n\n\n\n<li>Xia Li<\/li>\n\n\n\n<li>Xyon Quinn<\/li>\n\n\n\n<li>Veer Mahaan<\/li>\n\n\n\n<li>Sanga<\/li>\n<\/ul>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Plusieurs Superstars de la WWE ont malheureusement \u00e9t\u00e9 licenci\u00e9es de la compagnie de catch. Ainsi, Fightful nous informe que\u00a0Jinder Mahal, Xia Li, Xyon Quinn, en plus de &#8230;\u00a0ont tous les trois \u00e9t\u00e9 renvoy\u00e9s de la WWE. Jinder Mahal a d&rsquo;ores et d\u00e9j\u00e0 confirm\u00e9 la nouvelle sur les r\u00e9seaux sociaux en disant qu&rsquo;il s&rsquo;en allait. Xia&#8230;<\/p>\n","protected":false},"author":609,"featured_media":98663,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,85,23],"tags":[],"ppma_author":[295],"class_list":["post-98662","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-nxt","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/98662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=98662"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/98662\/revisions"}],"predecessor-version":[{"id":98664,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/98662\/revisions\/98664"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/98663"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=98662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=98662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=98662"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=98662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}