{"id":98500,"date":"2024-04-15T23:11:00","date_gmt":"2024-04-16T03:11:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=98500"},"modified":"2024-04-16T15:23:20","modified_gmt":"2024-04-16T19:23:20","slug":"cest-fait-ripley-forcee-dabandonner-son-titre","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/04\/15\/cest-fait-ripley-forcee-dabandonner-son-titre\/","title":{"rendered":"C&rsquo;est fait, Ripley forc\u00e9e d&rsquo;abandonner son titre!"},"content":{"rendered":"\n<p>C&rsquo;\u00e9tait une rumeur\u00a0supposition en d\u00e9but de soir\u00e9e mais la nouvelle est malheureusement concr\u00e9tis\u00e9 hier soir \u00e0 Montr\u00e9al durant le Monday Night RAW.<\/p>\n\n\n\n<p>Rhea Ripley est bien bless\u00e9e et a \u00e9t\u00e9 oblig\u00e9e de rendre son titre mondial f\u00e9minin vacant. En effet, Ripley a annonc\u00e9 souffrir d&rsquo;une blessure et\u00a0devoir s&rsquo;absenter pour les \u00a0\u00bbprochains mois\u00a0\u00bb\u00a0pendant le show de\u00a0RAW du 15 avril 2024. Ripley portait une \u00e9charpe afin de tenir en place son \u00e9paule, la th\u00e9orie de la blessure \u00e0 l&rsquo;\u00e9paule pendant l&rsquo;attaque de Liv Morgan semble l&rsquo;histoire qui la sort des \u00e9missions t\u00e9l\u00e9. Nous vous reviendrons sur quand la blessure est survenue. <\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Le r\u00e8gne de Rhea Ripley \u00e0 la WWE s&rsquo;arr\u00eate apr\u00e8s 380 jours en raison d&rsquo;une blessure alors qu&rsquo;elle \u00e9tait au sommet de la division f\u00e9minine et de la WWE. <\/p>\n\n\n\n<p>Maintenant que la WWE a pris la d\u00e9cision de la retirer des \u00e9crans, on peut s&rsquo;imaginer qu&rsquo;elle devra passer sous le bistouri prochainement. Son retour reste \u00e0 surveiller, les prochaines semaines en diront plus. Rhea Ripley a promis de revenir en force pour faire saigner, sp\u00e9cialement Liv Morgan qui l&rsquo;a bless\u00e9e.<\/p>\n\n\n\n<p>On devrait savoir tr\u00e8s prochainement ce qui arrivera avec le titre maintenant vacant!<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"AUas4wu86S\"><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/04\/15\/resultats-et-video-pour-le-wwe-monday-night-raw-du-15-avril-2024-a-montreal\/\">R\u00e9sultats et Vid\u00e9o pour le WWE Monday Night RAW du 15 Avril 2024 \u00e0 Montr\u00e9al!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0R\u00e9sultats et Vid\u00e9o pour le WWE Monday Night RAW du 15 Avril 2024 \u00e0 Montr\u00e9al!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2024\/04\/15\/resultats-et-video-pour-le-wwe-monday-night-raw-du-15-avril-2024-a-montreal\/embed\/#?secret=GQ1DgKRjRd#?secret=AUas4wu86S\" data-secret=\"AUas4wu86S\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>C&rsquo;\u00e9tait une rumeur\u00a0supposition en d\u00e9but de soir\u00e9e mais la nouvelle est malheureusement concr\u00e9tis\u00e9 hier soir \u00e0 Montr\u00e9al durant le Monday Night RAW. Rhea Ripley est bien bless\u00e9e et a \u00e9t\u00e9 oblig\u00e9e de rendre son titre mondial f\u00e9minin vacant. En effet, Ripley a annonc\u00e9 souffrir d&rsquo;une blessure et\u00a0devoir s&rsquo;absenter pour les \u00a0\u00bbprochains mois\u00a0\u00bb\u00a0pendant le show de\u00a0RAW&#8230;<\/p>\n","protected":false},"author":4,"featured_media":98501,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,43,23],"tags":[],"ppma_author":[292],"class_list":["post-98500","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-raw-wwe","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/98500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=98500"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/98500\/revisions"}],"predecessor-version":[{"id":98502,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/98500\/revisions\/98502"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/98501"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=98500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=98500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=98500"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=98500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}