{"id":97457,"date":"2024-04-02T00:25:00","date_gmt":"2024-04-02T04:25:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=97457"},"modified":"2024-04-02T16:41:48","modified_gmt":"2024-04-02T20:41:48","slug":"la-aew-a-offert-un-nouveau-contrat-a-matt-hardy-et-ce-dernier-dit-je-decide-de-ce-que-je-veux-faire-a-lavenir","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/04\/02\/la-aew-a-offert-un-nouveau-contrat-a-matt-hardy-et-ce-dernier-dit-je-decide-de-ce-que-je-veux-faire-a-lavenir\/","title":{"rendered":"La AEW a offert un nouveau contrat \u00e0 Matt Hardy et ce dernier dit: \u00ab\u00a0Je d\u00e9cide de ce que je veux faire \u00e0 l\u2019avenir\u00a0\u00bb."},"content":{"rendered":"\n<p>Matt Hardy affirme que la All Elite Wrestling  lui a effectivement propos\u00e9 un nouveau contrat.<\/p>\n\n\n\n<p>The Broken One a r\u00e9v\u00e9l\u00e9 cette nouvelle lors de la derni\u00e8re \u00e9dition de son podcast Extreme Life, o\u00f9 il a pr\u00e9cis\u00e9 qu\u2019il n\u2019avait pas encore mis la plume sur papier car il voulait peser toutes ses options. Il ajoute qu\u2019il est tr\u00e8s heureux que l\u2019AEW veuille qu\u2019il revienne.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Il y a une petite nouvelle pour accompagner mes n\u00e9gociations contractuelles. J\u2019ai un contrat avec l\u2019AEW pour quelques ann\u00e9es, et je suis en train de le regarder. Je d\u00e9cide de ce que je veux faire \u00e0 l\u2019avenir. Il y a \u00e9videmment encore des options. Je dois m\u2019assurer que je suis au courant des tenants et aboutissants du contrat, et je veux m\u2019assurer que tout est \u00e0 la hauteur de ce que je veux qu\u2019il soit parce qu\u2019encore une fois, je sais qu\u2019il ne me reste que quelques ann\u00e9es pour le faire, et je veux tirer le meilleur parti de ces ann\u00e9es. quoi que ce soit. <\/p>\n<\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Je veux \u00eatre optimis\u00e9 dans tout ce que je fais, donc c\u2019est tr\u00e8s important pour moi. Je suis donc tr\u00e8s heureux d\u2019\u00eatre invit\u00e9 \u00e0 revenir \u00e0 la AEW et \u00e0 travailler pour la AEW dans un avenir pr\u00e9visible, mais nous verrons parce que pour l\u2019instant, je suis en train de peser les options. Il y a plusieurs choses l\u00e0-bas, et je dirais que dans le mois prochain, je devrais probablement savoir ce que mon avenir imm\u00e9diat va me r\u00e9server.<\/p>\n<\/blockquote>\n\n\n\n<center><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/4CUfqbMTkkA?si=n8WIOyOw15N-UG5h\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/center>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Matt Hardy affirme que la All Elite Wrestling lui a effectivement propos\u00e9 un nouveau contrat. The Broken One a r\u00e9v\u00e9l\u00e9 cette nouvelle lors de la derni\u00e8re \u00e9dition de son podcast Extreme Life, o\u00f9 il a pr\u00e9cis\u00e9 qu\u2019il n\u2019avait pas encore mis la plume sur papier car il voulait peser toutes ses options. Il ajoute qu\u2019il&#8230;<\/p>\n","protected":false},"author":665,"featured_media":97604,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,30,4],"tags":[],"ppma_author":[289],"class_list":["post-97457","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-ex-wwe","category-news"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/97457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=97457"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/97457\/revisions"}],"predecessor-version":[{"id":97605,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/97457\/revisions\/97605"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/97604"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=97457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=97457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=97457"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=97457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}