{"id":97035,"date":"2024-03-19T23:16:00","date_gmt":"2024-03-20T03:16:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=97035"},"modified":"2024-03-21T14:50:53","modified_gmt":"2024-03-21T18:50:53","slug":"asuka-fait-face-a-une-blessure-rodrigues-encore-retiree-de-laction-nikita-lyons-parle-de-sa-date-de-retour-avec-booker-t-leffet-mone-et-plus","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/03\/19\/asuka-fait-face-a-une-blessure-rodrigues-encore-retiree-de-laction-nikita-lyons-parle-de-sa-date-de-retour-avec-booker-t-leffet-mone-et-plus\/","title":{"rendered":"Asuka fait face \u00e0 une blessure! Rodrigues encore retir\u00e9e de l&rsquo;action! Nikita Lyons parle de sa date de retour avec Booker T, L&rsquo;effet Mon\u00e9, et plus!"},"content":{"rendered":"\n<p>Une star de la WWE est bless\u00e9e.<\/p>\n\n\n\n<p>L\u2019actuelle co-championne des titres par \u00e9quipe f\u00e9minin, Asuka boitait visiblement lors du SmackDown de vendredi dernier apr\u00e8s avoir \u00e9t\u00e9 impliqu\u00e9e dans le match Dakota Kai et Bayley. <\/p>\n\n\n\n<p>Le PW Insider a depuis confirm\u00e9 que l\u2019<em>Empress of Tomorow<\/em> souffre d\u2019une blessure au genou et qu\u2019elle a \u00e9t\u00e9 retir\u00e9e de tous les house shows de la WWE de la semaine. <\/p>\n\n\n\n<p>Il n\u2019a pas encore \u00e9t\u00e9 d\u00e9termin\u00e9 si la blessure est tr\u00e8s grave ou si c\u2019est quelque chose qu\u2019Asuka peut surmonter.<\/p>\n\n\n\n<p>Nous vous tiendrons au courant de cette histoire. Asuka d\u00e9tient actuellement les titres WWE Women\u2019s Tag-Team avec Kairi Sane.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>Raquel Rodiguez a de nouveau \u00e9t\u00e9 retir\u00e9e de l\u2019action, apprend-on cette semaine.<\/p>\n\n\n\n<p>En janvier, Raquel Rodriguez r\u00e9v\u00e9lait&nbsp;souffrir du syndrome d\u2019activation mastocytaire (SAMA), une pathologie immunologique susceptible de provoquer des probl\u00e8mes cardiovasculaires et respiratoires, et des r\u00e9actions allergiques aigu\u00ebs et potentiellement douloureuses.<\/p>\n\n\n\n<p>On ne sait pas si le SAMA est la raison pour laquelle Raquel Rodriguez a \u00e9t\u00e9 retir\u00e9e de la liste des Superstars actives de la WWE, mais le site PWInsider rapporte la catcheuse \u00ab&nbsp;est actuellement list\u00e9e en interne avec d\u2019autres talents hors d\u2019action&nbsp;\u00bb.&nbsp;Le site d\u2019informations explique qu\u2019il est possible que Rodriguez ait \u00e9t\u00e9 mise \u00e0 l\u2019\u00e9cart en raison d\u2019une blessure sans rapport sa maladie.<\/p>\n\n\n\n<p>Raquel Rodriguez avait fait son retour \u00e0 l\u2019action \u00e0 temps pour participer \u00e0&nbsp;l\u2019Elimination Chamber f\u00e9minin \u00e0 Perth en Australie&nbsp;et avait particip\u00e9 dans l\u2019\u00e9pisode de RAW  le lendemain (28 f\u00e9vrier) avant de s\u2019absenter de nouveau. La catcheuse a par ailleurs r\u00e9v\u00e9l\u00e9 avoir commenc\u00e9 un traitement en caisson hyperbare la semaine derni\u00e8re sur son compte Instagram pour soigner son SAMA.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>L&rsquo;effet Mercedes Mon\u00e9 s&rsquo;es bien fait ressentir sur les audiences de Dynamite la semaine derni\u00e8re.<\/p>\n\n\n\n<p>Le r\u00e9sultat au niveau du nombre de t\u00e9l\u00e9spectateurs est sorti et on apprend que l&rsquo;\u00e9pisode de Dynamite du 13 mars 2024 sp\u00e9cial Big Business a fait&nbsp;une moyenne de 801 000 t\u00e9l\u00e9spectateurs&nbsp;aux \u00c9tats-Unis selon WrestleNomics et le Wrestling Observer. Un r\u00e9sultat qui est dans la moyenne d&rsquo;un show normal puisque Dynamite est toujours normalement entre 790 000 et 890 000.<\/p>\n\n\n\n<p>Par contre, il est important de noter que les d\u00e9buts de Mercedes Mon\u00e9 ont bien fonctionn\u00e9 puisque le premier quart d&rsquo;heure avec ses d\u00e9buts a d\u00e9pass\u00e9 la barre du million de t\u00e9l\u00e9spectateurs. <\/p>\n\n\n\n<p>C&rsquo;est la suite qui a fait mal, avec la carte propos\u00e9e qui \u00e9tait moins int\u00e9ressante pour le public am\u00e9ricain alors que le show a descendu \u00e0 chacun des segments pour finir \u00e0 627 000 au main event. Ce qui explique pourquoi la moyenne g\u00e9n\u00e9rale est si basse. <\/p>\n\n\n\n<p>Comme quoi il faut garder les rouges pour la faim comme disait le cr\u00e9ateur des Smarties!<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>Et parlant de blessure, le retour de Nikkita Lyons \u00e0 WWE NXT ne se fera pas de ci t\u00f4t si l&rsquo;ont en croit les derni\u00e8res infos \u00e0 son sujet.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Lyons \u00e9tait en interview pour le podcast de Booker T \u00a0\u00bbHall of Fame\u00a0\u00bb et elle a confirm\u00e9&nbsp;qu&rsquo;elle est bless\u00e9e et que son retour est pr\u00e9vu pour NXT Halloween Havoc 2024&nbsp;en octobre :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00a0\u00bb\u00c7a fait deux mois depuis mon op\u00e9ration et honn\u00eatement j&rsquo;ai l&rsquo;impression que \u00e7a l&rsquo;a pass\u00e9 tr\u00e8s vite, du moins pour moi, car je travaille fort \u00e0 chaque jour. Mais pr\u00e9sentement j&rsquo;esp\u00e8re Halloween Havoc pour mon retour. J&rsquo;esp\u00e8re que ce sera un bon moment, mais je veux aussi m&rsquo;assurer d&rsquo;\u00eatre pr\u00eate.\u00a0\u00bb<\/p>\n<\/blockquote>\n\n\n\n<p>Nikkita Lyons n&rsquo;a pas d\u00e9voil\u00e9 qu&rsquo;elle \u00e9tait la nature de cette seconde blessure alors qu&rsquo;elle venait de faire son retour de sa premi\u00e8re blessure. Pour rappel, Lyons avait souffert d&rsquo;une blessure en d\u00e9but 2023 au niveau de son genou et elle avait effectu\u00e9 son retour en fin 2023 jusqu&rsquo;\u00e0 une nouvelle fois souffrir d&rsquo;une blessure en d\u00e9but janvier 2024.<\/p>\n\n\n\n<center><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/RkZ-U9nT6Ao?si=54bTZg0DQctiMsaG\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/center>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Une star de la WWE est bless\u00e9e. L\u2019actuelle co-championne des titres par \u00e9quipe f\u00e9minin, Asuka boitait visiblement lors du SmackDown de vendredi dernier apr\u00e8s avoir \u00e9t\u00e9 impliqu\u00e9e dans le match Dakota Kai et Bayley. Le PW Insider a depuis confirm\u00e9 que l\u2019Empress of Tomorow souffre d\u2019une blessure au genou et qu\u2019elle a \u00e9t\u00e9 retir\u00e9e de&#8230;<\/p>\n","protected":false},"author":665,"featured_media":97118,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,30,4,85,23],"tags":[],"ppma_author":[289],"class_list":["post-97035","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-ex-wwe","category-news","category-nxt","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/97035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=97035"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/97035\/revisions"}],"predecessor-version":[{"id":97228,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/97035\/revisions\/97228"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/97118"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=97035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=97035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=97035"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=97035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}