{"id":96932,"date":"2024-03-13T23:11:00","date_gmt":"2024-03-14T03:11:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=96932"},"modified":"2024-03-14T14:15:19","modified_gmt":"2024-03-14T18:15:19","slug":"le-prochain-tournage-pour-dwayne-the-rock-johnson-en-2024","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/03\/13\/le-prochain-tournage-pour-dwayne-the-rock-johnson-en-2024\/","title":{"rendered":"Le Prochain Tournage pour Dwayne The Rock Johnson en 2024!"},"content":{"rendered":"\n<p>The Rock est de retour en force \u00e0 la WWE pour WrestleMania 40 et peut-\u00eatre un peu plus longtemps puisque l&rsquo;Info est que la WWE aimerait l&rsquo;avoir pour le PLE en Arabie saoudite en mai 2024. <\/p>\n\n\n\n<p>Tout repose sur son prochain tournage au cin\u00e9ma puisqu&rsquo;un tournage o\u00f9 il occuperait un r\u00f4le principal l&#8217;emp\u00eacherait de pouvoir participer \u00e0 l&rsquo;action sur le ring. Nous avons appris \u00e0 ce sujet que The Rock allait d\u00e9buter un tournage le 1er mai prochain, et le projet devrait se poursuivre jusqu&rsquo;au d\u00e9but du mois d&rsquo;Ao\u00fbt.<\/p>\n\n\n\n<p>En janvier dernier, on apprenait que\u00a0le projet du film \u00a0\u00bbSmashing Machine\u00a0\u00bb allait reprendre. Un projet qui avait d\u00e9but\u00e9 en 2019, mais <span style=\"text-decoration: underline;\">la<\/span>  COVID-19 l&rsquo;avait mis sur pause. Johnson y incarne le r\u00f4le principal du combattant MMA Mark Kerr.<\/p>\n\n\n\n<p>Des sc\u00e8nes auront lieu \u00e0 Los Angeles, au Nouveau-Mexique, \u00e0 Tokyo au Japon et \u00e0 Vancouver au Canada. Cette derni\u00e8re ville ne sera pas dans le sc\u00e9nario mais comme les studios Canadiens co\u00fbtes moins cher avec les cr\u00e9dits d&rsquo;imp\u00f4t et le taux de change favorable, plusieurs sc\u00e8ne s&rsquo;y tournerons donc l\u00e0.<\/p>\n\n\n\n<p>The Rock sera donc tr\u00e8s occup\u00e9 pendant cette p\u00e9riode et un risque de blessure \u00e0 la WWE serait trop grave pour le film et son portefeuille car les films le payent beaucoup plus qu&rsquo;une ann\u00e9e \u00e0 la WWE m\u00eame si TKO compense avec un salaire de cadre. <\/p>\n\n\n\n<p>Pr\u00e9sentement la nouvelle n&rsquo;est pas confirm\u00e9e par la WWE mais cela regarde plus l&rsquo;acteur et la production de le faire. <\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>The Rock est de retour en force \u00e0 la WWE pour WrestleMania 40 et peut-\u00eatre un peu plus longtemps puisque l&rsquo;Info est que la WWE aimerait l&rsquo;avoir pour le PLE en Arabie saoudite en mai 2024. Tout repose sur son prochain tournage au cin\u00e9ma puisqu&rsquo;un tournage o\u00f9 il occuperait un r\u00f4le principal l&#8217;emp\u00eacherait de pouvoir&#8230;<\/p>\n","protected":false},"author":4,"featured_media":96933,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,100,23],"tags":[],"ppma_author":[292],"class_list":["post-96932","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-tko","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/96932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=96932"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/96932\/revisions"}],"predecessor-version":[{"id":96934,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/96932\/revisions\/96934"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/96933"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=96932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=96932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=96932"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=96932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}