{"id":96566,"date":"2024-03-05T14:00:27","date_gmt":"2024-03-05T19:00:27","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=96566"},"modified":"2024-03-05T14:00:29","modified_gmt":"2024-03-05T19:00:29","slug":"tout-etait-pret-pour-que-cena-turn-heel-il-etait-meme-enthousiasme-que-cela-arrive","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/03\/05\/tout-etait-pret-pour-que-cena-turn-heel-il-etait-meme-enthousiasme-que-cela-arrive\/","title":{"rendered":"Tout \u00e9tait pr\u00eat pour que Cena \u00ab\u00a0Turn Heel\u00a0\u00bb. Il \u00e9tait m\u00eame enthousiasme que cela arrive!"},"content":{"rendered":"\n<p>John Cena dit qu&rsquo;un talon s&rsquo;est presque produit \u00e0 la WWE.<\/p>\n\n\n\n<p>L&rsquo;ancien 16 fois champion du monde est apparu dans la derni\u00e8re \u00e9dition d&rsquo;Insight With Chris Van Vilet pour discuter de sa longue carri\u00e8re au sein de l&rsquo;entreprise, qui l&rsquo;a amen\u00e9 \u00e0 aborder le projet de devenir un m\u00e9chant qui n&rsquo;a jamais eu lieu. Cena d\u00e9clare que juste au moment o\u00f9 il a commenc\u00e9 sa premi\u00e8re querelle avec The Rock, c&rsquo;\u00e9tait au moment o\u00f9 la WWE allait appuyer sur la g\u00e2chette pour qu&rsquo;il se mette du c\u00f4t\u00e9 obscure. L&rsquo;id\u00e9e a parcouru tous les canaux appropri\u00e9s car Cena a enregistr\u00e9 une nouvelle chanson d&rsquo;introduction et a m\u00eame re\u00e7u du nouveau mat\u00e9riel.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>C&rsquo;\u00e9tait Cena Rock 1. J&rsquo;ai appris qu&rsquo;ils allaient le faire. Je suis sorti et j&rsquo;ai enregistr\u00e9 une nouvelle chanson. Je suis sorti et j&rsquo;ai achet\u00e9 du nouveau mat\u00e9riel. Je n\u2019\u00e9tais pas pr\u00e9par\u00e9 \u00e0 une agression impitoyable, c\u2019\u00e9tait la derni\u00e8re fois que je n\u2019\u00e9tais pas pr\u00e9par\u00e9. Je veux dire, j\u2019ai entendu des rumeurs selon lesquelles nous allions le faire. Et en 48 heures, j&rsquo;avais un nouveau morceau, une nouvelle chanson th\u00e8me du mix studio, le mix final. J&rsquo;avais sept nouveaux maillots, des maillots d\u00e9collet\u00e9s avec des robes de type boxe. J&rsquo;avais d\u00e9j\u00e0 les bottes en stock, alors je les ai d\u00e9poussi\u00e9r\u00e9es. J&rsquo;\u00e9tais pr\u00eat \u00e0 partir et je pensais d\u00e9j\u00e0 \u00e0 ce que je pourrais faire avec l&rsquo;histoire.<\/p>\n<\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Cena expliquait ensuite quels changements il allait apporter \u00e0 son personnage et comment sa transformation physique n&rsquo;\u00e9tait que la premi\u00e8re \u00e9tape.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>OK, qu&rsquo;est-ce qu&rsquo;un \u00ab\u00a0heel\u00a0\u00bb? Ce  n\u2019est pas seulement un nouvel \u00e9quipement. L&rsquo;objectivit\u00e9, ou le message derri\u00e8re le maillot, les robes de boxe et les bottes, est exactement le contraire de ce que vous avez vu avec les v\u00eatements de ville, les shorts en jean, les t-shirts, les casquettes, les baskets. Suivez la voie oppos\u00e9e et penchez vous maintenant \u00e0 l\u2019oppos\u00e9 de tout ce que vous repr\u00e9sentez. Alors je commencerais \u00e0 travailler moins dur. Je me pr\u00e9senterais moins, je serais indigne de confiance et peu loyal. Je manquerais de respect dans ce que je faisais. Comme si tout ce que vous aviez \u00e0 faire \u00e9tait de le retourner sur sa t\u00eate. J&rsquo;abandonnerais beaucoup. Toutes ces choses que vous pouvez prendre et cr\u00e9er des histoires int\u00e9ressantes. Et c\u2019est ce qui me passe par la t\u00eate, pas les mouvements que je peux faire. C\u2019est comme si je pouvais prendre la propri\u00e9t\u00e9 intellectuelle que les gens connaissent et la d\u00e9former pour que ce soit comme si ce type \u00e9tait fou.<\/p>\n<\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Restant sur le sujet, Cena r\u00e9v\u00e8le qu\u2019il s\u2019est trop engag\u00e9 dans la direction dans laquelle il envisageait de prendre et que la WWE a finalement retir\u00e9 l\u2019id\u00e9e. Cependant, il r\u00e9it\u00e8re qu\u2019il \u00e9tait pr\u00eat et enthousiasm\u00e9 par le changement.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>C\u2019est tout ce que j\u2019aime et maintenant je d\u00e9teste vraiment \u00e7a. Et en \u00e9tant un vrai m\u00e9chant, et je pense que c\u2019est la conversation qui a finalement eu lieu o\u00f9 on se dit, d\u2019accord, c\u2019est une mauvaise id\u00e9e. Je me dis : H\u00e9, je sais que \u00e7a va piquer mais je ne vais pas vendre un autre T-shirt. Je vais retirer toutes les marchandises du march\u00e9. Je ne vais rien mettre de nouveau. Je ne ferai plus d\u2019apparitions. Je ne vais pas faire de Make-A-Wish. Je ne ferai rien de tel. Je vais \u00eatre un m\u00e9chant pour faire de ton gentil un gentil, alors ton gentil fait tout \u00e7a. Et c\u2019est \u00e0 ce moment-l\u00e0 que j\u2019ai eu l\u2019impression que nous \u00e9tions un peu trop plong\u00e9s. Donc \u00e7a s\u2019est pass\u00e9 comme \u00e7a s\u2019est pass\u00e9. Mais mon fr\u00e8re, j&rsquo;\u00e9tais pr\u00eat.<\/p>\n<\/blockquote>\n\n\n\n<p>Vous pouvez consulter l\u2019interview compl\u00e8te ci-dessous.<\/p>\n\n\n\n<center><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/D3PUBVWrdH8?si=Xsd5XlvDRnuTdxQA\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/center>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>John Cena dit qu&rsquo;un talon s&rsquo;est presque produit \u00e0 la WWE. L&rsquo;ancien 16 fois champion du monde est apparu dans la derni\u00e8re \u00e9dition d&rsquo;Insight With Chris Van Vilet pour discuter de sa longue carri\u00e8re au sein de l&rsquo;entreprise, qui l&rsquo;a amen\u00e9 \u00e0 aborder le projet de devenir un m\u00e9chant qui n&rsquo;a jamais eu lieu. Cena&#8230;<\/p>\n","protected":false},"author":609,"featured_media":96567,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,23],"tags":[],"ppma_author":[295],"class_list":["post-96566","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/96566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=96566"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/96566\/revisions"}],"predecessor-version":[{"id":96568,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/96566\/revisions\/96568"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/96567"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=96566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=96566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=96566"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=96566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}