{"id":96550,"date":"2024-03-04T23:59:00","date_gmt":"2024-03-05T04:59:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=96550"},"modified":"2024-03-05T13:47:30","modified_gmt":"2024-03-05T18:47:30","slug":"paul-heyman-au-hall-of-fame-bien-quil-a-refuse-plusieurs-fois-avant","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/03\/04\/paul-heyman-au-hall-of-fame-bien-quil-a-refuse-plusieurs-fois-avant\/","title":{"rendered":"Paul Heyman Au Hall of Fame bien qu&rsquo;il a refus\u00e9 plusieurs fois avant!"},"content":{"rendered":"\n<p>Vous, vous en \u00eates rendu compte, la WWE tarde  \u00e0 annoncer les noms qui garniront leWWE Hall of Fame 2024. Aujourd&rsquo;hui 4 mars nous avons apprit le premier.<\/p>\n\n\n\n<p><strong>L&rsquo;Associated Press a annonc\u00e9 en exclusivit\u00e9 que Paul Heyman sera introduit au temple de la renomm\u00e9e de la WWE<\/strong>\u00a0lors de la c\u00e9r\u00e9monie de 2024. La c\u00e9r\u00e9monie aura lieu le 5 avril 2024 directement apr\u00e8s SmackDown.<\/p>\n\n\n\n<p>Paul Heyman est aujourd&rsquo;hui manager pour le Chef Tribal Roman Reigns, mais il occupe aussi un r\u00f4le de producteur dans les coulisses afin d&rsquo;aider \u00e0 l&rsquo;organisation des matchs. Et pour les plus jeunes, Paul Heyman a \u00e9t\u00e9 le principal directeur de la ECW dans les ann\u00e9es 1990 o\u00f9 il a red\u00e9fini le terme \u00a0\u00bbextr\u00eame\u00a0\u00bb pour le catch.<\/p>\n\n\n\n<p>Tout a commenc\u00e9 pour Paul Heyman dans les ann\u00e9es 70 alors qu&rsquo;il a particip\u00e9 \u00e0 son premier show de catch encore adolescent sous une accr\u00e9ditation de photographe. Avec sa d\u00e9termination il a \u00e9t\u00e9 en mesure d&rsquo;\u00eatre embauch\u00e9 par Vince McMahon Sr et \u00eatre pay\u00e9 50$ pour \u00eatre photographe ringside, ce qui \u00e9tait beaucoup d&rsquo;argent quand m\u00eame \u00e0 l&rsquo;\u00e9poque. Il a ensuite \u00e9t\u00e9 en mesure de transitionner vers un r\u00f4le d&rsquo;intervieweur dans les coulisses, et vous connaissez la suite. <\/p>\n\n\n\n<p>Malgr\u00e9 avoir r\u00e9alis\u00e9 beaucoup de choses,\u00a0Paul Heyman dit avoir de la difficult\u00e9 \u00e0 accepter cette place\u00a0au Hall of Fame puisqu&rsquo;il a encore beaucoup de choses \u00e0 accomplir :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00a0\u00bbJ&rsquo;ai toujours l&rsquo;impression que je ne fais que commencer et que je suis juste en train de comprendre le business. Pour moi, parce qu&rsquo;il y a encore des choses que je veux accomplir, c&rsquo;est ce qui est un travail incomplet, c&rsquo;est un reflet d&rsquo;une carri\u00e8re enti\u00e8re, je ne me suis jamais senti \u00e0 l&rsquo;aise d&rsquo;accepter \u00e7a.<\/p>\n<\/blockquote>\n\n\n\n<p><\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&nbsp;Paul Heyman \u00e9tait en interview pour le New York Post et il dit avoir refus\u00e9 l&rsquo;offre du Hall of Fame \u00a0\u00bbplusieurs fois\u00a0\u00bb lors des derni\u00e8res ann\u00e9es. Il dit :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00a0\u00bbIl m&rsquo;a fallu toutes ces d\u00e9cennies pour comprendre ce m\u00e9tier et l&rsquo;art de la pr\u00e9sentation \u00e0 un public, alors m\u00eame si je d\u00e9teste utiliser le vieux clich\u00e9 du \u00ab Vous n&rsquo;avez encore rien vu et je ne fais que commencer \u00bb &#8230; Vous n&rsquo;avez encore rien vu, et je ne fais que commencer \u00bb. Je ne veux pas d&rsquo;un prix pour l\u2019ensemble de ma carri\u00e8re alors que je n&rsquo;ai pas fini de r\u00e9aliser des choses.<\/p>\n\n\n\n<p>J&rsquo;ai encore beaucoup de choses que je souhaite faire dans cette industrie. Je veux \u00eatre impliqu\u00e9 dans le premier \u00e9v\u00e9nement principal de WrestleMania \u00e0 La Havane, ou sur la Lune, ou sur Mars quand Elon Musk la colonisera. Ce sont des choses qui vont se produire dans le futur et je veux d\u00e9sesp\u00e9r\u00e9ment en faire partie.\u00a0\u00bb<\/p>\n<\/blockquote>\n\n\n\n<p>Paul Heyman dit s&rsquo;\u00eatre d\u00e9cid\u00e9 a accept\u00e9 cette ann\u00e9e puisqu&rsquo;il s&rsquo;agit du premier Hall of Fame sous la direction de Triple H. M\u00eame si c&rsquo;est pourtant gr\u00e2ce \u00e0 Vince McMahon qui a rachet\u00e9 la ECW et lui a donn\u00e9 un job qu&rsquo;il n&rsquo;est pas \u00e0 la rue. <\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Vous, vous en \u00eates rendu compte, la WWE tarde \u00e0 annoncer les noms qui garniront leWWE Hall of Fame 2024. Aujourd&rsquo;hui 4 mars nous avons apprit le premier. L&rsquo;Associated Press a annonc\u00e9 en exclusivit\u00e9 que Paul Heyman sera introduit au temple de la renomm\u00e9e de la WWE\u00a0lors de la c\u00e9r\u00e9monie de 2024. La c\u00e9r\u00e9monie aura&#8230;<\/p>\n","protected":false},"author":609,"featured_media":96555,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[84,77,4,42,23],"tags":[],"ppma_author":[295],"class_list":["post-96550","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ecw","category-hall-of-fame","category-news","category-wrestlemania","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/96550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=96550"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/96550\/revisions"}],"predecessor-version":[{"id":96558,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/96550\/revisions\/96558"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/96555"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=96550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=96550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=96550"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=96550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}