{"id":96402,"date":"2024-03-01T15:44:11","date_gmt":"2024-03-01T20:44:11","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=96402"},"modified":"2024-03-01T15:46:03","modified_gmt":"2024-03-01T20:46:03","slug":"bulletin-indy-tama-tonga-pourrait-joindre-la-wwe-vikingo-opperation-reussie-kazuchika-okada-a-la-aew-la-cmll-bloquee-au-frontieres-et-plus","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/03\/01\/bulletin-indy-tama-tonga-pourrait-joindre-la-wwe-vikingo-opperation-reussie-kazuchika-okada-a-la-aew-la-cmll-bloquee-au-frontieres-et-plus\/","title":{"rendered":"Bulletin Indy: Tama Tonga, pourrait joindre la WWE \/ Vikingo opp\u00e9ration R\u00e9ussie \/ Kazuchika Okada \u00e0 la AEW \/ La CMLL bloqu\u00e9e au fronti\u00e8res, et plus!"},"content":{"rendered":"\n<p>D\u00e9butons ce bulletin ind\u00e9pendant juste avant ce weekend qui vous pr\u00e9sentera le ppv AEW Revolution ce dimanche ici m\u00eame sur votre site pr\u00e9f\u00e9r\u00e9. <\/p>\n\n\n\n<p>Le champion Mega de la AAA, El Hijo del Vikingo, a subi avec succ\u00e8s une op\u00e9ration \u00e0 un genou.<\/p>\n\n\n\n<p>Le lutteur mexicain \u00e2g\u00e9 de 26 ans, que l\u2019on a vu entre autres \u00e9galement \u00e0 la AEW et \u00e0 Game Changer Wrestling, a mentionn\u00e9 sur Instagram qu\u2019il a un m\u00e9nisque d\u00e9chir\u00e9 et un ligament mal en point.<\/p>\n\n\n\n<p>On ne sait toutefois pas quand il sera de retour dans le ring.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Tama Tonga, qui est dans la mire de la WWE depuis longtemps, joindra la compagnie prochainement selon Dave Meltzer du Wrestling Observer.<\/p>\n\n\n\n<p>Ce v\u00e9t\u00e9ran du ring, qui a brill\u00e9 surtout \u00e0 New Japan Pro Wrestling, a r\u00e9cemment quitt\u00e9 cette promotion afin de se rapprocher de sa famille.<\/p>\n\n\n\n<p>Il est entre autres le neveu et le fils adoptif de Haku (King Tonga).<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Kazuchika Okada, une l\u00e9gende de la lutte japonaise, joindra bel et bien la AEW \u00e0 plein temps. Et dans moins d\u2019une semaine.<\/p>\n\n\n\n<p>Notre source mentionne que celui qui a brill\u00e9 \u00e0 New Japan Pro Wrestling durant 17 ans sera \u00e0\u00a0<em>Dynamite<\/em>\u00a0mercredi prochain, soit le 6 mars. Tony Khan n\u2019a pas toutefois pas \u00e9voqu\u00e9 le nom d\u2019Okada, mais il a parl\u00e9 d\u2019une surprise majeure pour la semaine prochaine.<\/p>\n\n\n\n<p>Avec en plus l\u2019arriv\u00e9e de Will Ospreay comme lutteur \u00e0 plein temps hier \u00e0<em>\u00a0Dynamite<\/em>, en plus de la plus que probable pr\u00e9sence de Mercedes Mon\u00e9 (Sasha Banks) lors du sp\u00e9cial\u00a0<em>Big Business<\/em>\u00a0du 13 mars, les prochaines semaines seront bien remplies \u00e0 la AEW.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Plusieurs lutteurs de la promotion mexicaine CMLL, qui a \u00e9tabli r\u00e9cemment un partenariat avec la AEW, pourraient ne plus pouvoir travailler aux \u00c9tats-Unis pendant un certain temps.<\/p>\n\n\n\n<p>PWInsider rapporte que 20 lutteurs ont des probl\u00e8mes de visas. \u00c7a pourrait prendre quelques mois avant que tout soit r\u00e9gl\u00e9. Le probl\u00e8me viendrait d\u2019une mauvaise gestion du dossier par la promotion Full Blown Pro Wrestling, du Texas qui devait s\u2019occuper des visas des lutteurs de CMLL.<\/p>\n\n\n\n<p>Certains de ces lutteurs devaient participer \u00e0 des \u00e9v\u00e9nements de lutte \u00e0 Philadelphie, durant le week-end de\u00a0<em>Wrestlemania<\/em>.<\/p>\n\n\n\n<p>Les lutteurs impliqu\u00e9s sont:<\/p>\n\n\n\n<p>Volador Jr, Hechicero, Mascara Dorada, Blue Panther, Dulce Gardenia, El Sagrado, El Suicida , Electrico Espiritu Negro, Euforia, Fugaz, Gemel, Diablo 1, Diablo 2, Magico, Robin, Sangre Imperial, Soberano, Templario, Sagaz (un arbitre).<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>D\u00e9butons ce bulletin ind\u00e9pendant juste avant ce weekend qui vous pr\u00e9sentera le ppv AEW Revolution ce dimanche ici m\u00eame sur votre site pr\u00e9f\u00e9r\u00e9. Le champion Mega de la AAA, El Hijo del Vikingo, a subi avec succ\u00e8s une op\u00e9ration \u00e0 un genou. Le lutteur mexicain \u00e2g\u00e9 de 26 ans, que l\u2019on a vu entre autres&#8230;<\/p>\n","protected":false},"author":3,"featured_media":96404,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,30,22,4],"tags":[],"ppma_author":[291],"class_list":["post-96402","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew-impact-njpw-roh","category-ex-wwe","category-indy","category-news"],"authors":[{"term_id":291,"user_id":3,"is_guest":0,"slug":"amine","display_name":"Amine Benhelal","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/2ac225a45c11cce8567af8f2b64e669faee748a823f5f22499aaa30f28cfa944?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/96402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=96402"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/96402\/revisions"}],"predecessor-version":[{"id":96407,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/96402\/revisions\/96407"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/96404"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=96402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=96402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=96402"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=96402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}