{"id":96063,"date":"2024-02-24T23:59:00","date_gmt":"2024-02-25T04:59:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=96063"},"modified":"2024-02-27T14:27:42","modified_gmt":"2024-02-27T19:27:42","slug":"resultats-et-video-pour-le-wwe-elimination-chamber-2024","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/02\/24\/resultats-et-video-pour-le-wwe-elimination-chamber-2024\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le WWE Elimination Chamber 2024!"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/02\/24\/regardez-le-wwe-elimination-chamber-en-direct-des-4h-am-est-10h-am-europe-carte-complete-et-plus\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir Elimination Chamber, cliquez ici.<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size\"><strong>WWE Elimination Chamber 2024 Perth, Australie, 24 f\u00e9vrier 2024<\/strong><\/p>\n\n\n\n<p>&#8211; Le Kickoff du WWE Elimination Chamber 2024 d\u00e9bute avec le panel compos\u00e9 de Megan Morant, Peter Rosenberg et Sam Roberts qui nous souhaitent la bienvenue et pr\u00e9sentent des vid\u00e9os sur les matchs.<\/p>\n\n\n\n<p>&#8211; En coulisse, Byron Saxton fait le point disant que l&rsquo;\u00e9nergie est f\u00e9brile dans les coulisses.<\/p>\n\n\n\n<p style=\"font-size:25px\"><strong>Championnat F\u00e9minin Par \u00c9quipe WWE<\/strong><\/p>\n\n\n\n<p><strong>Indi Hartwell et Candice LeRae vs Kabuki Warriors \u00a9&nbsp;<em>(Asuka et Kairi Sane)<\/em><\/strong><\/p>\n\n\n\n<p>En fin de match, Indi surprend Asuka avec un Roll Up, mais elle r\u00e9siste \u00e0 deux. Indi frappe frappe Asuka et donne la tag \u00e0 LeRae. Sane fait chuter LeRae en bas du coin alors qu&rsquo;elle montait et attaque Indi en ringside. Sane prend ensuite la tag et elles vont leur Elbow Drop \u00e0 deux sur LeRae pour le compte de trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnantes : Kabuki Warriors<\/em><\/p>\n\n\n\n<p>&#8211; En coulisse, Byron Saxton demande \u00e0 LA Knight ses commentaires avant son premier Chamber Match. LA Knight dit que 6 gars s&rsquo;affrontent pour avoir la place \u00e0 WrestleMania. Il s&rsquo;est exactement quoi faire sur le ring pour sortir l&rsquo;aspirant.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; La carte principale du WWE Elimination Chamber d\u00e9bute avec des vid\u00e9os des SuperStars qui arrivent dans le stade un \u00e0 un et puis on a droit \u00e0 la vid\u00e9o d&rsquo;ouverture.<\/p>\n\n\n\n<p style=\"font-size:25px\"><strong>Elimination Chamber F\u00e9minin<\/strong><\/p>\n\n\n\n<p><em>La gagnante va affronter la Women&rsquo;s World Champion \u00e0 WrestleMania 40.<\/em><\/p>\n\n\n\n<p><strong>Participantes : Bianca Belair, Raquel Rodriguez, Tiffany Stratton, Liv Morgan, Naomi et Becky Lynch<\/strong><\/p>\n\n\n\n<p>Le match d\u00e9marre sur des chapeaux de roues avec Naomi et Becky comme participantes.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Stratton \u00e9limine Naomi avec un Roll Up alors que Naomi venait de faire un saut sur Morgan.<\/li>\n\n\n\n<li>Morgan et Stratton s&rsquo;affrontent, Morgan la bloque avec un Oblivion pour le compte de trois.<\/li>\n\n\n\n<li>Belair fait son KOD sur Rodriguez pour le compte de trois.<\/li>\n<\/ul>\n\n\n\n<p>En fin de match, il reste Morgan, Belair et Lynch sur le ring. Les trois femmes se bloquent tour \u00e0 tour des prises et des coups. The Man \u00e9vite le KOD de Belair, et Morgan surprend Belair avec un Roll Up pour le compte de trois. Becky en profite alors pour faire son Man Handle Slam sur Morgan pour le compte de trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnante : Becky Lynch<\/em><\/p>\n\n\n\n<p>&#8211; Une vid\u00e9o sur la carri\u00e8re et l\u2019\u00e9volution de&nbsp;Bayley&nbsp;est diffus\u00e9e. Un r\u00e9sum\u00e9 sur son ascension jusqu\u2019\u00e0 sa victoire dans le Royal Rumble f\u00e9minin en janvier dernier et sur son match de championnat \u00e0 venir, \u00e0 WrestleMania XL, face \u00e0 son ancienne partenaire au sein de Damage CTRL et l\u2019actuelle championne de la WWE, IYO SKY.<\/p>\n\n\n\n<p style=\"font-size:25px\"><strong>Championnat Incontest\u00e9 Par \u00c9quipe WWE<\/strong><\/p>\n\n\n\n<p><strong>&nbsp;New Catch Republic<em>&nbsp;(Pete Dunne et Tyler Bate)<\/em>&nbsp;vs Judgment Day \u00a9 &nbsp;<em>(Finn Balor et Damian Priest) accompagn\u00e9 de Dominik Mysterio<\/em><\/strong><\/p>\n\n\n\n<p>En fin de match, Priest prend la tag pour son Razor Edge sur Bate, mais Bate le repousse contre le coin o\u00f9 Balor montait. Bate surprend Priest avec un Roll Up, mais il r\u00e9siste. Dunne prend la tag, ils font une s\u00e9rie de coups sur Priest. Ils font un Double Burning Hammer sur Priest pour le couvrir, mais il r\u00e9siste \u00e0 deux. Dunne et Bate reprennent une s\u00e9rie de coups sur Priest. Ils veulent faire une prise \u00e0 deux sur le coin, mais Balor les bloque. Priest fait un Double ChokeSlam sur coin sur Dunne et Bate, et  Balor encha\u00eene brillament avec son Coup de Gr\u00e2ce sur Dunne pour le compte de trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnants et toujours champions: The Judgment Day<\/em><\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente la vid\u00e9o promo sur WrestleMania 40.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur la rivalit\u00e9 avec Cody\/Rollins face \u00e0 la Bloodline.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p style=\"font-size:25px\"><strong>Grayson Waller Effect<\/strong>. <\/p>\n\n\n\n<p>Austin Theory est sur le ring. Theory dit qu&rsquo;il a essay\u00e9 un plan local cette semaine et c&rsquo;\u00e9tait d\u00e9goutant. Theory nous pr\u00e9sente ensuite la star du pays: \u00ab\u00a0<strong>Grayson Waller<\/strong>\u00ab\u00a0. <\/p>\n\n\n\n<p>Waller arrive sur le ring. Waller souhaite la bienvenue \u00e0 tous au Waller Effect. C&rsquo;est le meilleur jour de sa vie. Avant de commencer le show, il doit lancer un chant Aussie Aussie. Waller dit que son invit\u00e9 ce soir est le champion Mondial Poids Lourd : \u00ab\u00a0<strong>Seth Rollins<\/strong>\u00ab\u00a0. <\/p>\n\n\n\n<p>L&rsquo;Architecte arrive sur le ring. Waller nous pr\u00e9sente ensuite <strong>Cody Rhodes<\/strong> qui fait son entr\u00e9e et une fois sur le ring, il demande aux fans r\u00e9uni au Stade de Perth, de quoi ils veulent parler. <\/p>\n\n\n\n<p>Waller dit que c&rsquo;est son show, il d\u00e9cide. Il aimerait un moment pour souligner Roman Reigns. Ensuite, il veut savoir la v\u00e9rit\u00e9, qui Seth veut affronter \u00e0 WrestleMania. Seth r\u00e9pond qu&rsquo;il ne sait pas, il y a beaucoup de talents dans le match.&nbsp;Mais il a une petite nouvelles, et ajoute qu&rsquo;il est \u00e0 quelques jours d&rsquo;avoir le feu vert du m\u00e9decin pour remonter sur le ring.&nbsp;Alors peu importe qui gagne le Chamber, il n&rsquo;aura aucune chance. Rollins dit que le monde entier va chanter son theme song pour WrestleMania et il va livrer un show comme personne n&rsquo;est capable puisqu&rsquo;il est un visionnaire, un r\u00e9volutionnaire, Seth Freaking Rollins.<\/p>\n\n\n\n<p>Waller poursuit en disant que l&rsquo;histoire \u00e9tait belle, et ajoute qu&rsquo;on a la chance d&rsquo;avoir le plus grand main event de WrestleMania avec Roman Reigns contre The Rock. Est-ce que Cody est \u00e9go\u00efste de nous enlever ce match ? <\/p>\n\n\n\n<p>Cody r\u00e9pond qu&rsquo;il est un fan de The Rock, mais si le Rock est ici il le nommerait surement un Candy Quelque Chose, quelque chose sur les tartes et dire que ses fans sont des pleurnichards. Est-ce qu&rsquo;il y a des Cody Crybabies ici ce soir ? La foule approuve. Cody dit qu&rsquo;il sait que The Rock aimerait parler de quelque chose. Pourquoi il a sorti du main event de WrestleMania afin de revenir dedans ? Waller arr\u00eate Cody et dit qu&rsquo;il doit le pr\u00e9senter comme le People Champion.<\/p>\n\n\n\n<p>Cody dit que c&rsquo;est un nom qu&rsquo;on ne peut pas s&rsquo;approprier. The Rock \u00e9tait peut-\u00eatre un champion du Peuple par le pass\u00e9, mais faut \u00eatre pr\u00e8s des gens pour l&rsquo;\u00eatre. La foule chante \u00a0\u00bbRocky Sucks\u00a0\u00bb. Le 3 fois champion t\u00e9l\u00e9 TNT de la AEW ajoute que Seth avait une nouvelle mais que lui aussi a une info. Il dit que le Rock lui a donn\u00e9 une claque, \u00e0 WrestleMania il affronte Roman Reigns mais d&rsquo;ici-l\u00e0 il est libre.&nbsp;Alors il veut rendre \u00e7a officiel, il veut affronter The Rock en un contre un, n&rsquo;importe quand et n&rsquo;importe o\u00f9.&nbsp;La foule chante \u00a0\u00bbYES\u00a0\u00bb.<\/p>\n\n\n\n<p> Rollins dit que c&rsquo;est le moment de couper la t\u00eate du serpent une fois pour toute. Il admire le challenge de Cody, mais lorsqu&rsquo;on parle du Bloodline ce n&rsquo;est pas r\u00e9el le un contre un. Alors si The Rock accepte le challenge, Cody doit savoir qu&rsquo;il ne fera pas cette bataille seule. Waller dit qu&rsquo;on a un autre scoop sur son show.<\/p>\n\n\n\n<p>Austin Theory demande si Cody pense vraiment affronter le Rock. Cody allait r\u00e9pondre, mais Theory le coupe en disant que ce n&rsquo;est pas important. Rollins r\u00e9pond que c&rsquo;\u00e9tait bon. Theory ajoute qu&rsquo;il y en a une autre : \u00ab\u00a0<em>Cody est de retour \u00e0 Perth pour enfin finir son histoire<\/em>\u00ab\u00a0. <\/p>\n\n\n\n<p>Rollins demande alors s&rsquo;il a autre chose. L&rsquo;ancien champion des USA d\u00e9bute le:\u00a0\u00bb<em>If your Smell&#8230;<\/em>\u00a0\u00bb mais le R\u00e9volutionnaire  lance Theory contre le d\u00e9cor du Waller Effect puis Cody compl\u00e8te avec un Cody Cutter. Rollins termine avec un Stomp sur Theory.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o promo sur l&rsquo;Elimination Chamber des hommes.<\/p>\n\n\n\n<p style=\"font-size:25px\"><strong>Elimination Chamber Masculin<\/strong><\/p>\n\n\n\n<p><em>Le gagnant va affronter Seth Rollins \u00e0 WrestleMania 40.<\/em><\/p>\n\n\n\n<p><strong>Participants : Kevin Owens, Bobby Lashley, Logan Paul, Randy Orton, Drew McIntyre et LA Knight<\/strong><\/p>\n\n\n\n<p>McIntyre et Knight commencent le match.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Lashley se bat avec Knight, mais McIntyre en profite pour faire un Claymore Kick sur Lashley et le couvrir pour le compte de trois.<\/li>\n\n\n\n<li>Orton veut faire son RKO sur Knight, mais Knight le bloque en BFT. Knight enchaine avec un BFT sur McIntyre et veut le couvrir, mais AJ Styles arrive pendant que Lashley sort de la cage pour rouer de coups Knight avec une chaise. AJ termine avec un Styles Clash sur Knight et les officiels le sort du ring. McIntyre couvre Knight pour l&rsquo;\u00e9liminer.<\/li>\n\n\n\n<li>&nbsp;McIntyre y va d&rsquo;un Claymore sur Owens qui le bloque en Powerbomb. Logan veut intervenir, mais KO lui fait un Stunner puis Orton revient fait un RKO sorti de nul part \u00e0 Kevin pour le couvrir et l&rsquo;\u00e9liminer.<\/li>\n<\/ul>\n\n\n\n<p>En fin de match, Logan sort un poing am\u00e9ricain de son pantalon, mais Orton le surprend avec un RKO de nulle part. Orton le couvre pour l&rsquo;\u00e9liminer. Il reste Orton et McIntyre sur le ring. Orton arrive \u00e0 bloquer une charge de McIntyre et lui fait un DDT de la deuxi\u00e8me corde. Orton se lance pour son RKO, mais McIntyre le repousse et lui fait un Spinebuster. McIntyre se lance en Claymore, mais Orton n&rsquo;arrive plus \u00e0 se tenir debout. McIntyre s&rsquo;approche, mais Orton lui fait un RKO de nulle part. Logan Paul (qui \u00e9tait \u00e9limin\u00e9) revient dans l&rsquo;action et frappe Orton avec son poing am\u00e9ricain ! McIntyre couvre Orton pour la victoire.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnants et s&rsquo;en va \u00e0 WrestleMania contre Seth Rollins: Drew McIntyre<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>&#8211; Paul \u00ab\u00a0Triple H\u00a0\u00bb Lesvesque est sur le ring pour dire qu&rsquo;il voulait simplement venir pour remercier tout le monde. Au nom de la WWE et des Superstars, merci des avoir invit\u00e9 dans leur maison. Merci pour ce beau stade, c&rsquo;\u00e9tait une soir\u00e9e incroyable. Le nombre officiel de fans est de 52 290 dans le stade. <\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; On nous pr\u00e9sente la rivalit\u00e9 entre la championne mondial Reah Ripley et Nia Jax depuis son retour destructeur \u00e0 la WWE.<\/p>\n\n\n\n<p style=\"font-size:25px\"><strong>Championnat Mondial F\u00e9minin WWE<\/strong> <\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Nia Jax vs Reah Ripley \u00a9<\/strong><\/p>\n\n\n\n<p>En fin de match, les deux se battent en bas du ring. Jax arrive \u00e0 envoyer Ripley \u00e0 travers la table des commentateurs, et encha\u00eene avec un Banzai Drop sur Ripley et la couvre, mais elle r\u00e9siste. Nia frappe Ripley contre le coin et remonte sur le coin pour son Banzai Drop, mais Ripley se rel\u00e8ve et la fait chuter du coin. Ripley y va ensuite avec une Superplex sur sa rivale. La championne porte un coup de pied \u00e0 Nia et lui fait un Riptide, et c&rsquo;est bon pour le compte de trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnante et Toujours Championne: Reah Ripley<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le match on voit la famille et amis de Ripley l&rsquo;applaudir et la championne c\u00e9l\u00e8bre avec plein de pyro \u00e0 la fin puis elle ira sur la barricade rejoindre sa famille pour un gros c\u00e2lin de groupe. <\/p>\n\n\n\n<p class=\"has-text-align-center\" style=\"font-size:25px\"><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2024\/02\/24\/regardez-le-wwe-elimination-chamber-en-direct-des-4h-am-est-10h-am-europe-carte-complete-et-plus\/\" target=\"_blank\">Pour voir Elimination Chamber, cliquez ici.<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"ELUgzIlJYw\"><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/02\/24\/regardez-le-wwe-elimination-chamber-en-direct-des-4h-am-est-10h-am-europe-carte-complete-et-plus\/\">Reprise Vid\u00e9o et Carte pour le WWE Elimination Chamber 2024!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Reprise Vid\u00e9o et Carte pour le WWE Elimination Chamber 2024!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2024\/02\/24\/regardez-le-wwe-elimination-chamber-en-direct-des-4h-am-est-10h-am-europe-carte-complete-et-plus\/embed\/#?secret=kfR7JFRFFT#?secret=ELUgzIlJYw\" data-secret=\"ELUgzIlJYw\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>WWE Elimination Chamber 2024 Perth, Australie, 24 f\u00e9vrier 2024 &#8211; Le Kickoff du WWE Elimination Chamber 2024 d\u00e9bute avec le panel compos\u00e9 de Megan Morant, Peter Rosenberg et Sam Roberts qui nous souhaitent la bienvenue et pr\u00e9sentent des vid\u00e9os sur les matchs. &#8211; En coulisse, Byron Saxton fait le point disant que l&rsquo;\u00e9nergie est f\u00e9brile&#8230;<\/p>\n","protected":false},"author":609,"featured_media":96083,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[79,4,45,21,87,23],"tags":[],"ppma_author":[295],"class_list":["post-96063","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-elimination-chamber","category-news","category-ppv-wwe","category-resultats","category-road-to-wrestlemania","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/96063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=96063"}],"version-history":[{"count":14,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/96063\/revisions"}],"predecessor-version":[{"id":96255,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/96063\/revisions\/96255"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/96083"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=96063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=96063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=96063"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=96063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}