{"id":95676,"date":"2024-02-15T22:33:00","date_gmt":"2024-02-16T03:33:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=95676"},"modified":"2024-02-16T13:29:52","modified_gmt":"2024-02-16T18:29:52","slug":"the-rock-aurait-fait-changer-les-plans-de-wrestlemania-selon-dave-meltzer-et-vous-en-serez-tres-surpris","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/02\/15\/the-rock-aurait-fait-changer-les-plans-de-wrestlemania-selon-dave-meltzer-et-vous-en-serez-tres-surpris\/","title":{"rendered":"The Rock aurait fait changer les plans de WrestleMania Selon Dave Meltzer, et vous en serez tr\u00e8s surpris!"},"content":{"rendered":"\n<p>Dwayne Johnson l&rsquo;avait dit que les fans en parleraient longtemps,  et ils parlent encore de la conf\u00e9rence de presse <strong>WrestleMania Kickoff<\/strong> de la WWE o\u00f9 il a \u00e9t\u00e9 annonc\u00e9 que Cody Rhodes a choisit d&rsquo;affronter Roman Reigns \u00e0 WrestleMania 40 pour son championnat et la grande finale du plus gros show de l&rsquo;ann\u00e9e.<\/p>\n\n\n\n<p>The Rock s&rsquo;\u00e9tait d\u00e9j\u00e0 moqu\u00e9 des fans de Rhodes en les appelant \u00ab\u00a0<em>Cody Crybabies<\/em>\u00ab\u00a0, en r\u00e9ponse \u00e0 la r\u00e9action n\u00e9gative provoqu\u00e9e par la prise de la place de Rhodes par Rock. Au point de presse, Rock a gifl\u00e9 Rhodes pour avoir insult\u00e9 sa famille, marquant le tour de talon officiel de Rock.<\/p>\n\n\n\n<p>Il y a eu des sp\u00e9culations selon lesquelles The Rock et Reigns affronteraient \u00e9galement Rhodes et le champion du monde des poids lourds Seth Rollins lors de l&rsquo;\u00e9v\u00e9nement. Ce match est bel et bien en pr\u00e9paration mais on ne sait pas exactement quand. Nous avions l&rsquo;info que s&rsquo;\u00e9tait possible que ce soir lors de l&rsquo;Elimination Chamber mais il semble que ce ne sera pas le cas.<\/p>\n\n\n\n<p>Dans la derni\u00e8re \u00e9dition du Wrestling Observer Newsletter, Dave Meltzer a rapport\u00e9 que The Rock avait rapidement modifi\u00e9 son plan pour le match avec Reigns. La r\u00e9action n\u00e9gative a influenc\u00e9 cette d\u00e9cision et il voulait incarner un personnage de talon et pensait que les hu\u00e9es pouvaient \u00eatre justifi\u00e9es dans le cadre de son r\u00f4le de m\u00e9chant.<\/p>\n\n\n\n<p>Meltzer a ajout\u00e9 : <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab&nbsp;Cependant, au cours du week-end, Johnson (The Rock) a exprim\u00e9 qu&rsquo;il serait pr\u00e9f\u00e9rable pour lui de se retirer du match Reigns et de laisser Cody prendre sa place, ce que tout le monde \u00e9tait d&rsquo;accord \u00e0 ce stade. C&rsquo;est Johnson qui a ensuite propos\u00e9 l&rsquo;id\u00e9e d&rsquo;un heel turn et a sugg\u00e9r\u00e9 le match entre Reigns &amp; Rock contre Rhodes &amp; Rollins pour la premi\u00e8re nuit. Donc, si c\u2019est ainsi que les choses se d\u00e9roulent, c\u2019\u00e9tait son id\u00e9e.<\/p>\n<\/blockquote>\n\n\n\n<p>Par contre, ce ne serait pas la premi\u00e8re fois que Meltzer se ferait pisser de fausses informations \u00e0 l&rsquo;oreil pour contourner les vrais plans de la WWE. <\/p>\n\n\n\n<p>Nous en saurons surement plus ce soir lors de Smackdown.<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"NG4nARwXll\"><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/02\/16\/avant-gout-pour-le-wwe-friday-night-smackdown-du-16-fevrier-2024\/\">Reprise Vid\u00e9o et Programme Pour le WWE Friday Night Smackdown du 16 F\u00e9vrier 2024!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Reprise Vid\u00e9o et Programme Pour le WWE Friday Night Smackdown du 16 F\u00e9vrier 2024!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2024\/02\/16\/avant-gout-pour-le-wwe-friday-night-smackdown-du-16-fevrier-2024\/embed\/#?secret=rtDWEZNj1N#?secret=NG4nARwXll\" data-secret=\"NG4nARwXll\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Dwayne Johnson l&rsquo;avait dit que les fans en parleraient longtemps, et ils parlent encore de la conf\u00e9rence de presse WrestleMania Kickoff de la WWE o\u00f9 il a \u00e9t\u00e9 annonc\u00e9 que Cody Rhodes a choisit d&rsquo;affronter Roman Reigns \u00e0 WrestleMania 40 pour son championnat et la grande finale du plus gros show de l&rsquo;ann\u00e9e. The Rock&#8230;<\/p>\n","protected":false},"author":609,"featured_media":95677,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,87,36,42,23],"tags":[],"ppma_author":[295],"class_list":["post-95676","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-road-to-wrestlemania","category-smackdown","category-wrestlemania","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/95676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=95676"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/95676\/revisions"}],"predecessor-version":[{"id":95680,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/95676\/revisions\/95680"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/95677"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=95676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=95676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=95676"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=95676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}