{"id":95520,"date":"2024-02-12T23:11:00","date_gmt":"2024-02-13T04:11:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=95520"},"modified":"2024-02-13T14:05:54","modified_gmt":"2024-02-13T19:05:54","slug":"mcintyre-aurait-peut-etre-signe-une-extension-de-contrat-dans-le-silence-les-plus-total","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/02\/12\/mcintyre-aurait-peut-etre-signe-une-extension-de-contrat-dans-le-silence-les-plus-total\/","title":{"rendered":"McIntyre aurait peut \u00eatre sign\u00e9 une extension de contrat dans le silence les plus total!"},"content":{"rendered":"\n<p>Le sujet de Drew McIntyre fait beaucoup parler depuis les derniers mois \u00e0 savoir s&rsquo;il va rester ou non avec la WWE. Un indice claire malgr\u00e9 le brouillard, la WWE lui donne quand m\u00eame du temps de qualit\u00e9 \u00e0 la t\u00e9l\u00e9 et ne le fait pas paraitre mal mais \u00e0 part \u00e7a rien n&rsquo;est claire dans sa situation.<\/p>\n\n\n\n<p>Comme son contrat arrive \u00e0 \u00e9ch\u00e9ance en avril 2024 apr\u00e8s WrestleMania 40 donc tr\u00e8s bient\u00f4t, et qu&rsquo;il est tr\u00e8s rare \u00e0 la WWE de voir un top catcheur avec si peu de temps sur son contrat puisqu&rsquo;un d\u00e9part peut fortement compliquer les storylines \u00e0 part de se faire totalement laminer sur la grande sc\u00e8ne pour passer le flambeau. Cela ne semble toute fois pas pr\u00e9vu car pr\u00e9sentement, c&rsquo;est lui qui l&rsquo;amine tout le monde sur sa route. <\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Aujourd&rsquo;hui, la WWE a annonc\u00e9\u00a0un Live Event en Italie\u00a0le 1er mai 2024 et le nom de Drew McIntyre figure sur la liste des WWE Superstars annonc\u00e9s. Une nouvelle qui peut indiquer que McIntyre <span style=\"text-decoration: underline;\">aurait<\/span>  prolong\u00e9 avec la WWE. Il s&rsquo;agit du seul show o\u00f9 Drew McIntyre est annonc\u00e9 apr\u00e8s WrestleMania 40. <\/p>\n\n\n\n<p>Pour l&rsquo;instant il est impossible d&rsquo;en savoir plus. Il faudra encore quelques jours ou semaines pour en savoir plus sur le Guerrier \u00c9cossait et son futur dans le catch.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Le sujet de Drew McIntyre fait beaucoup parler depuis les derniers mois \u00e0 savoir s&rsquo;il va rester ou non avec la WWE. Un indice claire malgr\u00e9 le brouillard, la WWE lui donne quand m\u00eame du temps de qualit\u00e9 \u00e0 la t\u00e9l\u00e9 et ne le fait pas paraitre mal mais \u00e0 part \u00e7a rien n&rsquo;est claire&#8230;<\/p>\n","protected":false},"author":4,"featured_media":95521,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,87,23],"tags":[],"ppma_author":[292],"class_list":["post-95520","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-road-to-wrestlemania","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/95520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=95520"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/95520\/revisions"}],"predecessor-version":[{"id":95522,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/95520\/revisions\/95522"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/95521"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=95520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=95520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=95520"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=95520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}