{"id":95090,"date":"2024-02-03T00:12:00","date_gmt":"2024-02-03T05:12:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=95090"},"modified":"2024-02-04T15:06:50","modified_gmt":"2024-02-04T20:06:50","slug":"la-raison-dajouter-the-rock-a-wrestlemania-40-conference-de-presse-a-venir-et-plus","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/02\/03\/la-raison-dajouter-the-rock-a-wrestlemania-40-conference-de-presse-a-venir-et-plus\/","title":{"rendered":"La raison d&rsquo;ajouter The Rock \u00e0 WrestleMania 40! Mais \u00e7a toujours \u00e9t\u00e9 le plan depuis plus de trois ans!"},"content":{"rendered":"\n<p>Suite au face \u00e0 face entre The Rock et Roman Reigns&nbsp;au SmackDown du 2 f\u00e9vrier 2024, beaucoup de fans de demandent pourquoi la WWE a pris la d\u00e9cision de changer le plan initial. Un plan qui voyait un Seth Rollins contre CM Punk et un Reigns contre Cody Rhodes \u00e0 WrestleMania 40.<\/p>\n\n\n\n<p>Le PWInsider a fait le point sur le sujet et selon de nombreuses sources \u00e0 la WWE, il a \u00e9t\u00e9 convenu que&nbsp;l&rsquo;id\u00e9e d&rsquo;aller de l&rsquo;avant avec un The Rock contre Roman Reigns \u00e0 WrestleMania vient principalement de The Rock car il a lui m\u00eame amen\u00e9 et pouss\u00e9 l&rsquo;id\u00e9e aux dirigeants du groupe TKO et les principaux dirigeants du groupe TKO ont soutenu l&rsquo;id\u00e9e afin de l&rsquo;amener sur les \u00e9crans de la WWE. Le match sera d&rsquo;ailleurs confirm\u00e9 pendant la conf\u00e9rence de presse de la WWE ce jeudi 8 f\u00e9vrier.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>Au niveau de la raison du changement, les sources disent pour l&rsquo;instant diff\u00e9rentes versions. Une source a d\u00e9clar\u00e9 au PWInsider que l&rsquo;id\u00e9e d&rsquo;avoir The Rock serait pour sauver WrestleMania 40 en raison de l&rsquo;absence de Brock Lesnar et de CM Punk. Tandis qu&rsquo;une autre source mentionne que le match aurait lieu peu importe les circonstances puisque&nbsp;TKO estime ce match comme la plus grande t\u00eate d&rsquo;affiche pour la compagnie.<\/p>\n\n\n\n<p>Alors en raison de la popularit\u00e9 de The Rock et sa nouvelle position au sein du conseil d&rsquo;administration de la WWE, il est fort probable que Cody allait perdre sa place d\u00e8s que The Rock \u00e9tait pr\u00eat. Il se dit que The Rock permet de faire \u00e9norm\u00e9ment d&rsquo;argent maintenant pour la compagnie et respecter la nouvelle position de The Rock au sein du conseil.<\/p>\n\n\n\n<p>D&rsquo;ailleurs, selon une source,&nbsp;Triple H perdrait le contr\u00f4le sur les d\u00e9cisions cr\u00e9atives de la WWE en lien avec The Rockv qui sera accompagn\u00e9 de son propre responsable cr\u00e9atif pour ses matchs et ses promos, soit Brian Gewirtz. Ce dernier a \u00e9t\u00e9 \u00e0 une \u00e9poque le scripteur  le plus ancien de la WWE, et il a quitt\u00e9 la compagnie afin d&rsquo;\u00eatre le responsable du d\u00e9veloppement de Seven Bucks, la maison de production de The Rock.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>WrestleMania 40 semble maintenant reposer sur les \u00e9paules de The Rock. Il ne faut pas oublier que The Rock est aujourd&rsquo;hui une m\u00e9ga star mondiale, ce qu&rsquo;il n&rsquo;\u00e9tait pas \u00e0 l&rsquo;\u00e9poque.<\/p>\n\n\n\n<p>Bien que ce soit la version officiel de cette ann\u00e9e,  le plan initial a toujours  \u00e9t\u00e9 pr\u00e9vu dans les livres de la WWE que The Rock allait  affronter Roman Reignsdepuis qu&rsquo;il devait faire la 39e \u00e9dition \u00e0 Hollywood mais a demander de faire quelque chose de plus \u00e9norme, donc le 40e pour affronter le champion avec le plus long r\u00e8gne de tout les temps.  <\/p>\n\n\n\n<p>L&rsquo;histoire est m\u00eame mont\u00e9 en \u00e9pingle depuis trois ans pour ceux qui auraient oubli\u00e9.<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"TUjNutauDl\"><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/02\/02\/breaking-news-cody-rhodes-tarde-a-prendre-une-decision-mais-dwayne-the-rock-johnson-qui-la-conseille-vient-la-prendre-pour-lui\/\">Dwayne The Rock Johnson vient choisir \u00e0 la place de Cody Rhodes!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Dwayne The Rock Johnson vient choisir \u00e0 la place de Cody Rhodes!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2024\/02\/02\/breaking-news-cody-rhodes-tarde-a-prendre-une-decision-mais-dwayne-the-rock-johnson-qui-la-conseille-vient-la-prendre-pour-lui\/embed\/#?secret=1fT96e0HF3#?secret=TUjNutauDl\" data-secret=\"TUjNutauDl\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Suite au face \u00e0 face entre The Rock et Roman Reigns&nbsp;au SmackDown du 2 f\u00e9vrier 2024, beaucoup de fans de demandent pourquoi la WWE a pris la d\u00e9cision de changer le plan initial. Un plan qui voyait un Seth Rollins contre CM Punk et un Reigns contre Cody Rhodes \u00e0 WrestleMania 40. Le PWInsider a&#8230;<\/p>\n","protected":false},"author":609,"featured_media":95091,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,87,36,42,23],"tags":[],"ppma_author":[295],"class_list":["post-95090","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-road-to-wrestlemania","category-smackdown","category-wrestlemania","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/95090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=95090"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/95090\/revisions"}],"predecessor-version":[{"id":95094,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/95090\/revisions\/95094"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/95091"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=95090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=95090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=95090"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=95090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}