{"id":94945,"date":"2024-02-02T13:18:19","date_gmt":"2024-02-02T18:18:19","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=94945"},"modified":"2024-02-02T13:22:43","modified_gmt":"2024-02-02T18:22:43","slug":"adam-copeland-discute-de-limportance-de-la-all-elite-wrestling-pour-le-catch-il-explique-ce-qui-fait-de-christian-un-grand-heel-et-plus","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/02\/02\/adam-copeland-discute-de-limportance-de-la-all-elite-wrestling-pour-le-catch-il-explique-ce-qui-fait-de-christian-un-grand-heel-et-plus\/","title":{"rendered":"Adam Copeland discute de l\u2019importance de la All Elite Wrestling pour le catch! Il explique ce qui fait de Christian un grand \u00ab\u00a0Heel\u00a0\u00bb, et plus!"},"content":{"rendered":"\n<p>Adam \u00ab\u00a0Edge\u00a0\u00bb Copeland a fait une interview avec\u00a0<a href=\"https:\/\/www.si.com\/fannation\/wrestling\/news\/adam-copeland-on-disney-percy-jackson-series-and-what-makes-christian-the-best-villain-in-wrestling\">Sports Illustrated\u00a0<\/a>pour discuter d\u2019un large \u00e9ventail de sujets o\u00f9 il a parl\u00e9 d\u2019un large \u00e9ventail de sujets.<\/p>\n\n\n\n<p>Le Rated R Superstar a discut\u00e9 de ce qui fait de Christian Cage un grand heel et plus encore. Voici les faits saillants :<\/p>\n\n\n\n<p><strong>Sur ce qui fait de Christian Cage un grand heel :<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab S\u2019il le fait si bien, c\u2019est parce qu\u2019il veut en \u00eatre un. Quelque part en cours de route, cela s\u2019est perdu. Les talons sont devenus plus cool que le babyface. Ce n\u2019est pas comme \u00e7a que \u00e7a devrait \u00eatre. Ce n\u2019est pas non plus comme \u00e7a qu\u2019il voit les choses. Je veux dire, l\u2019homme porte un col roul\u00e9 coup\u00e9. Il n\u2019y a rien de cool dans ce qu\u2019il fait. Il s\u2019y engage pleinement. C\u2019est un m\u00e9chant de James Bond et il adore \u00e7a. C\u2019est amusant d\u2019y participer.\u00bb<\/p>\n<\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p><strong>Sur son Cope Open :<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab L\u2019objectif est d\u2019amener tout le monde vers le haut. J\u2019aime toujours voir de nouveaux personnages et voir des ampoules s\u2019\u00e9teindre. C\u2019est ce que j\u2019ai aim\u00e9 jusqu\u2019\u00e0 pr\u00e9sent. Ce que je fais, c\u2019est impliqu\u00e9 tellement de gens diff\u00e9rents. Maintenant, il peut y en avoir encore plus avec le &lsquo;Cope Open&rsquo;.\u00bb<\/p>\n<\/blockquote>\n\n\n\n<p><strong>Sur le monopole de la lutte :<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab Chaque fois qu\u2019il y a plus d\u2019un endroit o\u00f9 exercer votre m\u00e9tier, c\u2019est bon pour tous ceux qui font partie de ce m\u00e9tier. Un monopole n\u2019est jamais une bonne id\u00e9e. Cela vaut aussi pour moi en tant que consommateur. En tant que consommateur, je veux plus de choix. Cela ne signifie pas que vous devez choisir l\u2019un plut\u00f4t que l\u2019autre. Vous pouvez tous les choisir. Je me souviens d\u2019avoir grandi et d\u2019\u00eatre mort pour pouvoir mettre la main sur des cassettes de NWA. Il n\u2019a pas \u00e9t\u00e9 diffus\u00e9 l\u00e0 o\u00f9 je vivais, l\u00e0 o\u00f9 il y avait la WWF. J\u2019ai d\u00e9couvert la lutte internationale de Montr\u00e9al. J\u2019ai trouv\u00e9 la All Star Wrestling de Vancouver. J\u2019ai trouv\u00e9 toutes ces autres s\u00e9ries, et j\u2019ai ador\u00e9 \u00e7a. Je recevais des petits bouts de gars que je n\u2019avais vus que dans les magazines. Puis l\u2019\u00e9mission\u00a0Pro Wrestling Plus avec Ed Whalen,\u00a0qui \u00e9tait l\u2019annonceur du Stampede, a commenc\u00e9, et j\u2019ai enfin pu voir des catcheurs de la NWA et de la Continental. Je me suis dit : \u00ab <em>Donne-moi tout \u00e7a<\/em>. \u00bb <\/p>\n\n\n\n<p>C\u2019est pour \u00e7a que la AEW est g\u00e9nial. C\u2019est tellement cool de voir des luttes diff\u00e9rentes. C\u2019est vraiment sp\u00e9cial, et je m\u2019\u00e9clate d\u2019\u00eatre ici.\u00bb<\/p>\n<\/blockquote>\n\n\n\n<p>Si vous voulez voir ou revoir leur premier match ensemble \u00e0 la AEW lors du Dynamite de Montr\u00e9al en d\u00e9cembre dernier ou savoir comment le tout c&rsquo;\u00e9tait d\u00e9roul\u00e9, <a href=\"https:\/\/www.jdx.info\/lutte\/2023\/12\/06\/resultats-et-video-pour-le-aew-dynamite-du-6-decembre-2023-a-montreal\/\" target=\"_blank\" rel=\"noreferrer noopener\">cliquez ici<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"bi4V9vseIi\"><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/12\/06\/resultats-et-video-pour-le-aew-dynamite-du-6-decembre-2023-a-montreal\/\">R\u00e9sultats et Vid\u00e9o pour le AEW Dynamite du 6 D\u00e9cembre 2023 \u00e0 Montr\u00e9al!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0R\u00e9sultats et Vid\u00e9o pour le AEW Dynamite du 6 D\u00e9cembre 2023 \u00e0 Montr\u00e9al!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2023\/12\/06\/resultats-et-video-pour-le-aew-dynamite-du-6-decembre-2023-a-montreal\/embed\/#?secret=rwUqtf60t8#?secret=bi4V9vseIi\" data-secret=\"bi4V9vseIi\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Adam \u00ab\u00a0Edge\u00a0\u00bb Copeland a fait une interview avec\u00a0Sports Illustrated\u00a0pour discuter d\u2019un large \u00e9ventail de sujets o\u00f9 il a parl\u00e9 d\u2019un large \u00e9ventail de sujets. Le Rated R Superstar a discut\u00e9 de ce qui fait de Christian Cage un grand heel et plus encore. Voici les faits saillants : Sur ce qui fait de Christian Cage&#8230;<\/p>\n","protected":false},"author":665,"featured_media":94994,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,30,77,4],"tags":[],"ppma_author":[289],"class_list":["post-94945","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-ex-wwe","category-hall-of-fame","category-news"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/94945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=94945"}],"version-history":[{"count":4,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/94945\/revisions"}],"predecessor-version":[{"id":94999,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/94945\/revisions\/94999"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/94994"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=94945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=94945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=94945"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=94945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}