{"id":94934,"date":"2024-01-31T12:01:00","date_gmt":"2024-01-31T17:01:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=94934"},"modified":"2024-01-31T13:08:52","modified_gmt":"2024-01-31T18:08:52","slug":"la-aew-la-preparee-pour-la-wwe-tony-khan-lui-avait-fait-plusieurs-grosses-offres-pour-la-garder","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/01\/31\/la-aew-la-preparee-pour-la-wwe-tony-khan-lui-avait-fait-plusieurs-grosses-offres-pour-la-garder\/","title":{"rendered":"La AEW l&rsquo;a pr\u00e9par\u00e9e pour la WWE! Tony Khan lui avait fait plusieurs grosses offres pour la garder!"},"content":{"rendered":"\n<p>Vous le savez maintenant, Jade Cargill a fait ses d\u00e9buts tant attendus sur le ring de la WWE lors du Royal Rumble samedi soir dernier, en entrant dans le Rumble des femmes \u00e0 la 28e position et se qualifiant pour les trois derniers, o\u00f9 Liv Morgan l&rsquo;a \u00e9limin\u00e9e.<\/p>\n\n\n\n<p>Lors d&rsquo;une r\u00e9cente interview avec Denise Salcedo, Cargill a not\u00e9 qu&rsquo;AEW l&rsquo;avait pr\u00e9par\u00e9e pour sa course \u00e0 la WWE.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab J\u2019avais l\u2019impression que je n\u2019aurais jamais eu un meilleur d\u00e9part qu&rsquo;\u00e0 la AEW. C\u2019est moi qui suis tr\u00e8s honn\u00eate. Les v\u00e9t\u00e9rans dans les vestiaires m\u2019ont pr\u00e9par\u00e9 pour la plus grande sc\u00e8ne de la WWE. J\u2019ai v\u00e9cu une exp\u00e9rience formidable l\u00e0-bas, \u00eatre jet\u00e9 \u00e0 l\u2019eau et \u00eatre capable de nager et de survivre, cela m\u2019a pr\u00e9par\u00e9 \u00e0 la grande sc\u00e8ne de la WWE, aux vestiaires, au personnel ph\u00e9nom\u00e9nal de la WWE. Ils ont une administration pas comme les autres. Je suis juste ravie d&rsquo;\u00eatre ici\u00a0\u00bb.<\/p>\n<\/blockquote>\n\n\n\n<p><\/p>\n\n\n\n<center><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/Oj8hhpvKNvg?si=K7awwHHINYS1Jol9\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/center>\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>Et parlant de la nouvelle sensation de la WWE, son ancien patron Tony Khan avait pourtant tent\u00e9 de la garder \u00e0 la All Elite Wrestling.<\/p>\n\n\n\n<p>Jade Cargill \u00e9tait absente depuis AEW Double or Nothing 2023, mais elle est revenue dans l&rsquo;\u00e9pisode du AEW Collision du 9 septembre pour organiser un match revanche avec le champion TBS Kris Statlander. Statlander l&rsquo;a ensuite battue pour conserver le titre lors de l&rsquo;\u00e9pisode du 15 septembre du AEW Rampage. Apr\u00e8s l&rsquo;enregistrement du match le 13 septembre, Fightful Select rapportait alors  que Cargill en terminait avec la AEW pensait d\u00e9j\u00e0 qu&rsquo;elle se dirigeait vers la WWE. <\/p>\n\n\n\n<p>Par la suite, la WWE a confirm\u00e9 avoir sign\u00e9 Cargill le 26 septembre.<\/p>\n\n\n\n<p>Au cours de la m\u00eal\u00e9e m\u00e9diatique d&rsquo;apr\u00e8s-spectacle AEW WrestleDream qui date du mois d&rsquo;octobre dernier, Khan avait \u00e9t\u00e9 interrog\u00e9 sur le chemin menant au d\u00e9part de Cargill et s&rsquo;il savait que \u00ab\u00a0cela\u00a0\u00bb \u00e9tait le plan de match. Il a discut\u00e9 de leurs n\u00e9gociations contractuelles et a d\u00e9clar\u00e9 qu&rsquo;il avait fait deux offres importantes, mais qu&rsquo;ils n&rsquo;avaient pas abouti.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab\u00a0Je savais que le contrat de Jade avan\u00e7ait et que nous parlions d&rsquo;un nouveau contrat et j&rsquo;\u00e9tais tr\u00e8s int\u00e9ress\u00e9 par le retour de Jade et nous \u00e9tions en n\u00e9gociation. J&rsquo;ai fait une tr\u00e8s grosse offre et j&rsquo;ai pens\u00e9 que c&rsquo;\u00e9tait une offre tr\u00e8s juste. Je Je pensais qu&rsquo;elle y r\u00e9fl\u00e9chissait, puis elle a demand\u00e9 une offre plus importante, puis j&rsquo;ai remont\u00e9 la pente, et j&rsquo;ai en quelque sorte pens\u00e9 que \u00e7a allait le faire. Ensuite, ce n&rsquo;est pas le cas, ce qui m&rsquo;a surpris parce que pour \u00eatre honn\u00eate, je est arriv\u00e9e \u00e0 un nombre sup\u00e9rieur \u00e0 sa demande initiale. Je ne sais pas ce que j&rsquo;aurais d\u00fb faire \u00e0 ce moment-l\u00e0. J&rsquo;ai \u00e9t\u00e9 un peu surpris. J&rsquo;esp\u00e9rais vraiment que Jade reviendrait. Je pense que j&rsquo;ai essay\u00e9 de g\u00e9rer le probl\u00e8me, lorsque nous \u00e9tions dans le vif du sujet et que nous en \u00e9tions aux derni\u00e8res semaines et que nous n&rsquo;\u00e9tions toujours pas d&rsquo;accord sur quelque chose, alors c&rsquo;est au moment o\u00f9 j&rsquo;ai dit : <\/p>\n\n\n\n<p>\u00ab si vous ne restez pas , je vais vous offrir la meilleure sortie possible.\u00a0\u00bb <\/p>\n\n\n\n<p>Je n&rsquo;ai que de bonnes choses \u00e0 dire \u00e0 propos de Jade. J&rsquo;ai vraiment appr\u00e9ci\u00e9 travailler avec elle. Elle \u00e9tait une grande partie d&rsquo;AEW, elle est toujours la bienvenue ici, j&rsquo;ai essay\u00e9 de lui donner le meilleur envoi possible. L\u2019envoi le plus \u00e9l\u00e9gant que j\u2019ai jamais vu dans la lutte a eu lieu, \u00e0 l\u2019\u00e9poque, lorsque Ric Flair a quitt\u00e9 la WWF. Il a fait un match avec M. Perfect, qui \u00e9tait une personne naturelle pour lui, et c&rsquo;\u00e9tait tout, il \u00e9tait parti. Ils n\u2019ont rien fait pour l\u2019embarrasser ou le g\u00e2cher, ils l\u2019ont laiss\u00e9 partir et il \u00e9tait toujours Ric Flair. Il a disput\u00e9 le match contre la personne qu\u2019il aurait d\u00fb avoir, a termin\u00e9 et est reparti avec non seulement sa dignit\u00e9 et probablement une meilleure position qu\u2019\u00e0 son arriv\u00e9e. C\u2019est ce que j\u2019ai essay\u00e9 de faire. Je voulais lui offrir le meilleur d\u00e9part possible\u00a0\u00bb, a d\u00e9clar\u00e9 Khan.<\/p>\n<\/blockquote>\n\n\n\n<p>Khan a poursuivi en d\u00e9clarant qu&rsquo;il s&rsquo;attache \u00e0 faire d&rsquo;e la AEW un foyer id\u00e9al pour les lutteurs, qu&rsquo;ils viennent ou partent, car il vise \u00e0 bien traiter les gens. Il a clairement indiqu\u00e9 qu&rsquo;il respectait et valorisait Jade, il voulait donc lui faire un grand adieu. Khan a soulign\u00e9 qu&rsquo;il souhaitait le meilleur \u00e0 Cargill et qu&rsquo;elle serait toujours la bienvenue.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Vous le savez maintenant, Jade Cargill a fait ses d\u00e9buts tant attendus sur le ring de la WWE lors du Royal Rumble samedi soir dernier, en entrant dans le Rumble des femmes \u00e0 la 28e position et se qualifiant pour les trois derniers, o\u00f9 Liv Morgan l&rsquo;a \u00e9limin\u00e9e. Lors d&rsquo;une r\u00e9cente interview avec Denise Salcedo,&#8230;<\/p>\n","protected":false},"author":609,"featured_media":94938,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,4,71,23],"tags":[],"ppma_author":[295],"class_list":["post-94934","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-news","category-royal-rumble","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/94934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=94934"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/94934\/revisions"}],"predecessor-version":[{"id":94939,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/94934\/revisions\/94939"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/94938"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=94934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=94934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=94934"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=94934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}