{"id":94764,"date":"2024-01-27T23:55:00","date_gmt":"2024-01-28T04:55:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=94764"},"modified":"2024-01-28T14:38:28","modified_gmt":"2024-01-28T19:38:28","slug":"un-deuxieme-royal-rumble-remporte-de-suite-pour-cody-rhodes-et-sa-promo-dapres-show-avec-la-video-exclusive","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/01\/27\/un-deuxieme-royal-rumble-remporte-de-suite-pour-cody-rhodes-et-sa-promo-dapres-show-avec-la-video-exclusive\/","title":{"rendered":"Un Deuxi\u00e8me Royal Rumble Remport\u00e9 de Suite pour Cody Rhodes et sa Promo d&rsquo;Apr\u00e8s Show avec la vid\u00e9o exclusive!"},"content":{"rendered":"\n<p>Pour ceux qui l&rsquo;ont rat\u00e9, Cody Rhodes est le grand gagnant du Royal Rumble chez les hommes pour une deuxi\u00e8me ann\u00e9e de suite.<\/p>\n\n\n\n<p>The Amrican Nightmare a fait son entr\u00e9e en 15e place dans cette grande bataille royale sp\u00e9ciale, et il a \u00e9t\u00e9 en mesure de rester sur le ring jusqu&rsquo;\u00e0 la toute fin.  Et ce malgr\u00e9 le retour de Sami Zayn en 30e , Drew McIntyre qui l&rsquo;a sorti du ring afin de compl\u00e9ter le  carr\u00e9 d&rsquo;As entre Cody, Drew, CM Punk et Gunther qui c&rsquo;est fait \u00e9limin\u00e9 une deuxi\u00e8me ann\u00e9e de suite par Rhodes.<\/p>\n\n\n\n<p>Cody et Punk se sont retrouv\u00e9s les deux derniers sur le ring. Les deux hommes ont \u00e9chang\u00e9 des prises et des coups pendant un long moment avant d&rsquo;\u00eatre en mesure de mettre un terme \u00e0 la rencontre. Cody a bloqu\u00e9 un \u00e9ni\u00e8me GTS et a \u00e9t\u00e9 en mesure de balancer Punk en bas du ring.<\/p>\n\n\n\n<p>Cody Rhodes ira donc en main event de WrestleMania 40 et visiblement il semble vouloir affronter Roman Reign car en effet, il c\u00e9l\u00e9br\u00e9 sa victoire en pointant le logo de WrestleMania 40 et il a ensuite point\u00e9 le champion incontest\u00e9 de la WWE  qui \u00e9tait en loge dans les tribunes, et non Seth Rollins qui \u00e9tait dans une loge de l&rsquo;autre c\u00f4t\u00e9. <\/p>\n\n\n\n<p>Ce qui vient effectivement brouiller les cartes pour ceux qui voulaient voir le match entre Reigns et The Rock mais rien n&rsquo;est encore coul\u00e9 dans le b\u00e9ton.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Apr\u00e8s sa victoire Cody Rhodes est rest\u00e9 sur le ring et a fait une promo pour le public pr\u00e9sent.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab\u00a0Tampa, St. Pete, avez-vous pass\u00e9 un bon moment ce soir. Les gars, je vous dois des excuses. Je suis d\u00e9sol\u00e9 pour ce qui s&rsquo;est pass\u00e9 \u00e0 WrestleMania 39. Mais nous allons \u00e0 WrestleMania 40. La nuit a \u00e9t\u00e9 longue, je ne vous garderai pas ici, un spectacle incroyable, une \u00e9quipe incroyable, une production incroyable.<\/p>\n<\/blockquote>\n\n\n\n<p>Il a poursuivi en disant : <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab Parfois, quand je viens \u00e0 Tampa, quand je viens \u00e0 St Pete, parfois j&rsquo;essaie de rester et de rester seul, la raison est que c&rsquo;est un territoire poussi\u00e9reux. Je vous remercie donc beaucoup d&rsquo;en avoir fait un territoire de Cody. Je vous aime tellement les gars. Passez une bonne soir\u00e9e et \u00e0 la prochaine fois.<\/p>\n<\/blockquote>\n\n\n\n<center><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/vfr2w-sw8Q4?si=Ijf1j00B_TGNkZZ5\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/center>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"NCyI5LLPsD\"><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/01\/27\/resultats-et-video-pour-le-wwe-royal-rumble-2024\/\">R\u00e9sultats et Vid\u00e9o pour le WWE Royal Rumble 2024!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0R\u00e9sultats et Vid\u00e9o pour le WWE Royal Rumble 2024!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2024\/01\/27\/resultats-et-video-pour-le-wwe-royal-rumble-2024\/embed\/#?secret=FSMIrdfFYa#?secret=NCyI5LLPsD\" data-secret=\"NCyI5LLPsD\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour ceux qui l&rsquo;ont rat\u00e9, Cody Rhodes est le grand gagnant du Royal Rumble chez les hommes pour une deuxi\u00e8me ann\u00e9e de suite. The Amrican Nightmare a fait son entr\u00e9e en 15e place dans cette grande bataille royale sp\u00e9ciale, et il a \u00e9t\u00e9 en mesure de rester sur le ring jusqu&rsquo;\u00e0 la toute fin. Et&#8230;<\/p>\n","protected":false},"author":609,"featured_media":94765,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,87,71,42,23],"tags":[],"ppma_author":[295],"class_list":["post-94764","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-road-to-wrestlemania","category-royal-rumble","category-wrestlemania","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/94764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=94764"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/94764\/revisions"}],"predecessor-version":[{"id":94766,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/94764\/revisions\/94766"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/94765"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=94764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=94764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=94764"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=94764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}