{"id":94558,"date":"2024-01-22T23:11:00","date_gmt":"2024-01-23T04:11:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=94558"},"modified":"2024-01-23T13:19:57","modified_gmt":"2024-01-23T18:19:57","slug":"hulk-hogan-dans-le-royal-rumble","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/01\/22\/hulk-hogan-dans-le-royal-rumble\/","title":{"rendered":"Hulk Hogan dans le Royal Rumble?"},"content":{"rendered":"\n<p>La WWE c\u00e9l\u00e8bre les 40 ans de carri\u00e8re d&rsquo;Hulk Hogan et la l\u00e9gende s&rsquo;est pr\u00e9sent\u00e9e dans un clip vid\u00e9o pendant le show de WWE RAW du 22 janvier 2024.<\/p>\n\n\n\n<p>Hulk Hogan est revenu sur sa carri\u00e8re, mais il en a aussi profit\u00e9 pour parler du Royal Rumble 2024. Hogan a d\u00e9clar\u00e9 que s&rsquo;il devait parier il mettrait son argent sur CM Punk ou bien Cody Rhodes, mais il ne faut pas oublier le facteur du joker (une entr\u00e9e surprise dans le match). <\/p>\n\n\n\n<p>Hogan a d\u00e9clar\u00e9 qu&rsquo;on ne sait jamais qui peut se pr\u00e9senter au Royal Rumble incluant lui qui a peut-\u00eatre un autre match en lui :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00a0\u00bbLe facteur du joker, on ne sait jamais qui peut se pr\u00e9senter. On ne sait jamais &#8230; [il se montre du doigt], j&rsquo;en ai peut-\u00eatre encore sous le pied.\u00a0\u00bb<\/p>\n<\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>L&rsquo;Immortel est aujourd&rsquo;hui \u00e2g\u00e9 de 70 ans et il a laiss\u00e9 entendre de nombreuses fois par le pass\u00e9 qu&rsquo;il pourrait revenir pour un dernier match \u00e0 la WWE. Comme vous, vous en dout\u00e9, le projet ne s&rsquo;est jamais concr\u00e9tis\u00e9 apr\u00e8s de nombreuses op\u00e9rations au dos.<\/p>\n\n\n\n<p>Ce sera \u00e0 surveiller si Hulk Hogan va r\u00e9ellement participer au Royal Rumble 2024 ou non car il n&rsquo;a rien confirm\u00e9 \u00e0 part laiss\u00e9 sous entendre que peut \u00eatre que. <\/p>\n\n\n\n<p>L&rsquo;\u00e9v\u00e9nement a lieu pr\u00e8s de chez lui, alors le d\u00e9placement serait facile pour ce faire ne douce et ne pas se faire voir avant le moment venu. <\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"dD5hkwWqUx\"><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/01\/22\/resultats-et-video-pour-le-wwe-monday-night-raw-du-22-janvier-2024\/\">R\u00e9sultats et Vid\u00e9o pour le WWE Monday Night RAW du 22 Janvier 2024!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0R\u00e9sultats et Vid\u00e9o pour le WWE Monday Night RAW du 22 Janvier 2024!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2024\/01\/22\/resultats-et-video-pour-le-wwe-monday-night-raw-du-22-janvier-2024\/embed\/#?secret=umeJuRNFyF#?secret=dD5hkwWqUx\" data-secret=\"dD5hkwWqUx\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La WWE c\u00e9l\u00e8bre les 40 ans de carri\u00e8re d&rsquo;Hulk Hogan et la l\u00e9gende s&rsquo;est pr\u00e9sent\u00e9e dans un clip vid\u00e9o pendant le show de WWE RAW du 22 janvier 2024. Hulk Hogan est revenu sur sa carri\u00e8re, mais il en a aussi profit\u00e9 pour parler du Royal Rumble 2024. Hogan a d\u00e9clar\u00e9 que s&rsquo;il devait parier&#8230;<\/p>\n","protected":false},"author":4,"featured_media":94562,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[77,4,43,71,23],"tags":[],"ppma_author":[292],"class_list":["post-94558","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hall-of-fame","category-news","category-raw-wwe","category-royal-rumble","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/94558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=94558"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/94558\/revisions"}],"predecessor-version":[{"id":94561,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/94558\/revisions\/94561"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/94562"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=94558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=94558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=94558"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=94558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}