{"id":94352,"date":"2024-01-17T23:11:00","date_gmt":"2024-01-18T04:11:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=94352"},"modified":"2024-01-18T13:45:54","modified_gmt":"2024-01-18T18:45:54","slug":"le-futur-de-john-cena-a-la-wwe","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/01\/17\/le-futur-de-john-cena-a-la-wwe\/","title":{"rendered":"Le Futur de John Cena \u00e0 la WWE!"},"content":{"rendered":"\n<p>Lors d&rsquo;une r\u00e9cente&nbsp;interview pour PEOPLE, l&rsquo;ancien champion de la WWE et maintenant acteur \u00e0 Hollywood, John Cena s&rsquo;est exprim\u00e9 concernant le futur de sa carri\u00e8re \u00e0 la WWE. <\/p>\n\n\n\n<p>The Champ explique envisager depuis quelque temps une porte de sortie de la WWE, tout en soulignant l&rsquo;importance d&rsquo;apporter une certaine contribution \u00e0 la compagnie.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab\u00a0J&rsquo;ai eu 47 ans l&rsquo;ann\u00e9e derni\u00e8re et il ne me reste plus beaucoup de temps \u00e0 la WWE. J&rsquo;essaie de savoir quand fermer ce chapitre. Je ne serais pas qui je suis professionnellement ou personnellement sans la WWE, et je me suis promis que je ne serais jamais l\u00e0 simplement pour moi-m\u00eame. Chaque fois que je catche, je veux tout donner au public. Et je dois admettre que lorsque j&rsquo;ai atteint la barre des 45 ans, j&rsquo;ai d\u00fb commencer \u00e0 essayer d&rsquo;\u00e9laborer une strat\u00e9gie pour quitter et j&rsquo;essaie d&rsquo;y travailler actuellement.\u00a0\u00bb<\/p>\n<\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>Les 16 fois champion du monde WWE explique ensuite \u00eatre ouvert aux propositions de la WWE concernant un dernier match afin de cl\u00f4turer sa carri\u00e8re ainsi que son int\u00e9r\u00eat \u00e0 devenir par la suite un mentor ou un entra\u00eeneur pour la compagnie :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab\u00a0Je veux juste faire ce qu&rsquo;il y a de mieux pour la compagnie. Si c&rsquo;est un grand match final ou si c&rsquo;est juste un match final, quelle que soit la mani\u00e8re dont je peux \u00eatre int\u00e9gr\u00e9 au show pour faire savoir \u00e0 tout le monde que ce chapitre est termin\u00e9, je suis pr\u00eat \u00e0 \u00e9couter ce que la WWE a \u00e0 dire.<\/p>\n\n\n\n<p>J\u2019ai accumul\u00e9 pr\u00e8s de deux d\u00e9cennies et demie de sagesse gr\u00e2ce auxquelles je pense pouvoir offrir le point de vue d\u2019un mentor, c\u2019est s\u00fbr. Donc si je ne suis pas int\u00e9gr\u00e9 \u00e0 la famille WWE \u00e0 l\u2019avenir et \u00e0 perp\u00e9tuit\u00e9, alors je pense que c\u2019est du gaspillage pour toutes les personnes impliqu\u00e9es.\u00a0\u00bb<\/p>\n<\/blockquote>\n\n\n\n<p>Pour rappel, la derni\u00e8re fois qu&rsquo;on a vu John Cena \u00e0 la WWE, cela remonte au 4 novembre 2023 pour  l&rsquo;\u00e9v\u00e9nement premium Crown Jewel.<\/p>\n\n\n\n<center><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/HnVp4MbP23Y?si=5YcJHatAGg_IAkPF\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/center>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"AWUs5eifzw\"><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/01\/17\/randy-orton-reve-daffronter-john-cena-une-derniere-fois-a-wrestlemania-pour-le-titre-wwe\/\">Randy Orton r\u00eave d&rsquo;affronter John Cena une derni\u00e8re fois \u00e0 WrestleMania pour le titre WWE!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Randy Orton r\u00eave d&rsquo;affronter John Cena une derni\u00e8re fois \u00e0 WrestleMania pour le titre WWE!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2024\/01\/17\/randy-orton-reve-daffronter-john-cena-une-derniere-fois-a-wrestlemania-pour-le-titre-wwe\/embed\/#?secret=ZdfeRSw6Yi#?secret=AWUs5eifzw\" data-secret=\"AWUs5eifzw\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Lors d&rsquo;une r\u00e9cente&nbsp;interview pour PEOPLE, l&rsquo;ancien champion de la WWE et maintenant acteur \u00e0 Hollywood, John Cena s&rsquo;est exprim\u00e9 concernant le futur de sa carri\u00e8re \u00e0 la WWE. The Champ explique envisager depuis quelque temps une porte de sortie de la WWE, tout en soulignant l&rsquo;importance d&rsquo;apporter une certaine contribution \u00e0 la compagnie. \u00ab\u00a0J&rsquo;ai eu&#8230;<\/p>\n","protected":false},"author":4,"featured_media":94353,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[81,4,23],"tags":[],"ppma_author":[292],"class_list":["post-94352","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-crown-jewel","category-news","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/94352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=94352"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/94352\/revisions"}],"predecessor-version":[{"id":94364,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/94352\/revisions\/94364"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/94353"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=94352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=94352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=94352"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=94352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}