{"id":93913,"date":"2024-01-08T13:11:00","date_gmt":"2024-01-08T18:11:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=93913"},"modified":"2024-01-08T16:03:59","modified_gmt":"2024-01-08T21:03:59","slug":"lundertaker-revele-que-vince-mcmahon-depenserait-des-milliers-de-dollars-juste-pour-lui-faire-plaisir-il-croit-que-la-ceinture-de-la-wwe-devrait-etre-loriginale-il-parle-egalement-que-plu","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/01\/08\/lundertaker-revele-que-vince-mcmahon-depenserait-des-milliers-de-dollars-juste-pour-lui-faire-plaisir-il-croit-que-la-ceinture-de-la-wwe-devrait-etre-loriginale-il-parle-egalement-que-plu\/","title":{"rendered":"L\u2019Undertaker r\u00e9v\u00e8le que Vince McMahon d\u00e9penserait des milliers de dollars juste pour lui faire plaisir! Il croit que la ceinture de la WWE devrait \u00eatre l&rsquo;Originale! Il parle \u00e9galement que plusieurs \u00e9taient f\u00e2ch\u00e9s que sa \u00ab\u00a0streak\u00a0\u00bb a prit fin, et plus!"},"content":{"rendered":"\n<p>L\u2019Undertaker et Vince McMahon ont une relation tr\u00e8s \u00e9troite, qui comprend beaucoup de nervures.<\/p>\n\n\n\n<p>The Deadman s\u2019est exprim\u00e9 sur ce sujet lors d\u2019une r\u00e9cente \u00e9dition de questions-r\u00e9ponses de son podcast Six Feet Under, o\u00f9 il a r\u00e9v\u00e9l\u00e9 que l\u2019ancien pr\u00e9sident avait l\u2019habitude de d\u00e9penser des milliers de dollars juste pour en obtenir un. Mis \u00e0 part McMahon, seuls Paul Bearer et Brian Adams l\u2019ont fait aussi dur.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Il n\u2019y a eu que quelques gars qui m\u2019ont fait des c\u00f4tes. Paul Bearer me faisait des c\u00f4tes et Brian Adams me faisait des c\u00f4tes. Ce sont les deux seuls gars qui le feraient \u2014 eh bien, Vince (McMahon)&#8230; Il s\u2019est mis en quatre pour me donner des c\u00f4tes. Il d\u00e9pensait des milliers et des milliers de dollars juste pour me faire et m\u2019amuser. Mais, en ce qui concerne le talent, les deux seuls gars qui me feraient des c\u00f4tes \u00e9taient Paul Bearer et Brian Adams.<\/p>\n<\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Ailleurs dans son podcast, Undertaker a parl\u00e9 du championnat du monde comme d\u2019une ceinture d\u2019apparence traditionnelle et du fait qu\u2019il a toujours d\u00e9test\u00e9 quand elle a un design personnalis\u00e9.<\/p>\n\n\n\n<p>Toujours sur le sur le podcast Six Feet Under, on a demand\u00e9 au Deadman s&rsquo;il avait d\u00e9j\u00e0 envisag\u00e9 de d\u00e9tenir une ceinture personnalis\u00e9e lorsqu&rsquo;il \u00e9tait champion du monde, semblable \u00e0 la ceinture tournante de John Cena ou \u00e0 la ceinture \u00e9conomique de Daniel Bryan. Il dit qu&rsquo;il est de la vieille \u00e9cole et estime que le championnat devrait \u00eatre traditionnel.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Non, je suis un traditionaliste. Je suis de la vieille \u00e9cole. Quel que soit le titre mondial, c\u2019est ce que je voulais repr\u00e9senter. Aussi cool que soit [la ceinture personnalis\u00e9e], c&rsquo;est l&rsquo;une des ceintures les plus belles que j&rsquo;ai vues, j&rsquo;aurais voulu une des ceintures traditionnelles, \u00e0 moins que ce ne soit la ceinture tournante, ce qui \u00e9tait horrible. Si j&rsquo;avais eu le choix, la courroie tournante ou la [ceinture personnalis\u00e9e], j&rsquo;aurais opt\u00e9 pour la [ceinture personnalis\u00e9e]. J&rsquo;aime toujours les championnats traditionnels. \u00c0 l\u2019\u00e9poque, il s\u2019agissait plus d\u2019\u00eatre le champion que de marketing. Je ne suis pas oppos\u00e9 \u00e0 gagner de l\u2019argent. Je pense simplement qu&rsquo;il y a certaines traditions et certaines choses qui ne devraient pas \u00eatre touch\u00e9es. Le championnat devrait \u00eatre le championnat.<\/p>\n<\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>La d\u00e9cision de la WWE de laisser Brock Lesnar briser la s\u00e9quence d&rsquo;invincibilit\u00e9 de The Undertaker \u00e0 WrestleMania 30 en 2014 a \u00e9t\u00e9 d\u00e9battue par les fans et les lutteurs depuis la s\u00e9rie.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab\u00a0Peu de temps apr\u00e8s le match [Ric] Flair [\u00e0 Wrestlemania 18], c&rsquo;est \u00e0 ce moment-l\u00e0 que la s\u00e9quence a vraiment pris vie. C\u2019est vraiment devenu sp\u00e9cial. Il y avait des gars qui vous le disaient, et il y a encore des gars qui vous disaient : <\/p>\n\n\n\n<p>\u00ab Je m&rsquo;en fiche de savoir si je suis l&rsquo;\u00e9v\u00e9nement principal ou non. Je veux la s\u00e9quence.\u2019 C\u2019\u00e9tait une telle attraction. \u2018Qui se sera ? \u00bb <\/p>\n\n\n\n<p>Il arrive l\u00e0-haut 13-0, 14-0. C\u2019est comme : <\/p>\n\n\n\n<p>\u00ab oh, est-ce le gars qui va battre la s\u00e9quence ? \u00bb <\/p>\n\n\n\n<p>Je ne suis pas du genre \u00e0 me vanter, mais \u00e0 de nombreuses reprises, c\u2019\u00e9tait aussi important que l\u2019\u00e9v\u00e9nement principal. Est-ce que ce type est celui qui va mettre un terme \u00e0 cette s\u00e9quence ? C\u2019\u00e9tait juste un moment vraiment sp\u00e9cial.<\/p>\n<\/blockquote>\n\n\n\n<p>Taker a poursuivi: <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00abParmi les fans, m\u00eame parmi les talents, car la plupart des gars l&rsquo;\u00e9taient, ils \u00e9taient \u00e9nerv\u00e9s. Ils disaient : <\/p>\n\n\n\n<p>\u00ab<em> Mec, The Streak n\u2019aurait pas d\u00fb \u00eatre fauch\u00e9.<\/em> \u00bb <\/p>\n\n\n\n<p>C\u2019est le probl\u00e8me. Je n\u2019ai aucune d\u00e9cision \u00e0 prendre \u00e0 ce sujet, mais beaucoup de gars ont contribu\u00e9 \u00e0 faire de cette s\u00e9quence quelque chose, \u00e0 lui donner un sens. Ils disaient : <\/p>\n\n\n\n<p>\u00ab Bon sang, pourquoi tu m\u2019enl\u00e8ves ? Pourquoi enlevez-vous une partie aussi vitale de WrestleMania ?\u00bb <\/p>\n\n\n\n<p>C\u2019\u00e9tait comme \u2018C\u2019est aussi important qu\u2019un match pour le titre.\u2019 \u00bb<\/p>\n<\/blockquote>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>L\u2019Undertaker et Vince McMahon ont une relation tr\u00e8s \u00e9troite, qui comprend beaucoup de nervures. The Deadman s\u2019est exprim\u00e9 sur ce sujet lors d\u2019une r\u00e9cente \u00e9dition de questions-r\u00e9ponses de son podcast Six Feet Under, o\u00f9 il a r\u00e9v\u00e9l\u00e9 que l\u2019ancien pr\u00e9sident avait l\u2019habitude de d\u00e9penser des milliers de dollars juste pour en obtenir un. Mis \u00e0&#8230;<\/p>\n","protected":false},"author":665,"featured_media":93925,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[77,4,42,23],"tags":[],"ppma_author":[289],"class_list":["post-93913","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hall-of-fame","category-news","category-wrestlemania","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/93913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=93913"}],"version-history":[{"count":4,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/93913\/revisions"}],"predecessor-version":[{"id":93926,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/93913\/revisions\/93926"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/93925"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=93913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=93913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=93913"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=93913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}