{"id":93649,"date":"2024-01-03T02:06:00","date_gmt":"2024-01-03T07:06:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=93649"},"modified":"2024-01-03T14:06:39","modified_gmt":"2024-01-03T19:06:39","slug":"mick-foley-parle-du-raisonnement-derriere-son-match-i-quit-avec-the-rock","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/01\/03\/mick-foley-parle-du-raisonnement-derriere-son-match-i-quit-avec-the-rock\/","title":{"rendered":"Mick Foley parle du raisonnement derri\u00e8re son match I Quit avec The Rock!"},"content":{"rendered":"\n<p>Lors d\u2019un r\u00e9cent \u00e9pisode de Foley Is Pod, Mick Foley,lsa vraie l\u00e9gende du Hardcore, est revenu sur la raison d\u2019\u00eatre de son embl\u00e9matique I Quit Match contre The Rock au WWE Royal Rumble 1999.<\/p>\n\n\n\n<p>Il s\u2019agissait d\u2019un match brutal o\u00f9 Foley a pris des coups de chaise r\u00e9p\u00e9t\u00e9s \u00e0 la t\u00eate, ce qui a \u00e9t\u00e9 document\u00e9 dans le documentaire \u00ab&nbsp;Beyond The Mat&nbsp;\u00bb. Foley a expliqu\u00e9 qu\u2019ils essayaient de garder Rock un \u00ab Heel \u00bb jusqu\u2019apr\u00e8s WrestleMania.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab C\u2019est in\u00e9vitable que les gens vont l\u2019acclamer. Vous essayez juste de retarder l\u2019in\u00e9vitable jusqu\u2019apr\u00e8s WrestleMania. C\u2019est difficile de vraiment le huer parce que c\u2019est un artiste tellement dou\u00e9, et il vous fait sourire [et] rire. Mais si nous pouvions montrer un c\u00f4t\u00e9 vicieux et vindicatif [envers lui], nous pourrions retarder l\u2019in\u00e9vitable pendant au moins quelques mois.<\/p>\n<\/blockquote>\n\n\n\n<p><strong>Vous pouvez voir la vid\u00e9o ci-dessous:<\/strong><\/p>\n\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n\n<iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/jBFQ81l7iK0?si=Jgm12tGkU6F0oyPf\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/center>\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Lors d\u2019un r\u00e9cent \u00e9pisode de Foley Is Pod, Mick Foley,lsa vraie l\u00e9gende du Hardcore, est revenu sur la raison d\u2019\u00eatre de son embl\u00e9matique I Quit Match contre The Rock au WWE Royal Rumble 1999. Il s\u2019agissait d\u2019un match brutal o\u00f9 Foley a pris des coups de chaise r\u00e9p\u00e9t\u00e9s \u00e0 la t\u00eate, ce qui a \u00e9t\u00e9&#8230;<\/p>\n","protected":false},"author":665,"featured_media":93699,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[84,30,77,4,71,83],"tags":[],"ppma_author":[289],"class_list":["post-93649","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ecw","category-ex-wwe","category-hall-of-fame","category-news","category-royal-rumble","category-wcw"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/93649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=93649"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/93649\/revisions"}],"predecessor-version":[{"id":93700,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/93649\/revisions\/93700"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/93699"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=93649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=93649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=93649"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=93649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}