{"id":93590,"date":"2024-01-01T16:49:44","date_gmt":"2024-01-01T21:49:44","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=93590"},"modified":"2024-01-01T16:49:47","modified_gmt":"2024-01-01T21:49:47","slug":"mise-a-jour-sur-la-possible-surprise-ce-soir-a-raw-sasha-banks-serait-exclue-mais-the-rock-serait-de-plus-en-plus-au-top-des-rumeurs","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/01\/01\/mise-a-jour-sur-la-possible-surprise-ce-soir-a-raw-sasha-banks-serait-exclue-mais-the-rock-serait-de-plus-en-plus-au-top-des-rumeurs\/","title":{"rendered":"Mise \u00e0 Jour sur la Possible Surprise ce Soir \u00e0 RAW! Sasha Banks serait exclue mais The Rock serait de plus en plus au top des rumeurs!"},"content":{"rendered":"\n<p>En vous souhaitant une bonne ann\u00e9e 2024 et bienvenue sur le site qui vous en donnera encore plus cette ann\u00e9e! <\/p>\n\n\n\n<p>La question du jour demeure \u00ab Qui est l\u2019ancien champion du monde  qui revient \u00e0 la WWE ce soir ? \u00bb<\/p>\n\n\n\n<p>Nous ne le savons pas encore, mais voici ce que nous avons appris.<\/p>\n\n\n\n<p>\u00c0 l&rsquo;approche de l&rsquo;\u00e9pisode <strong>WWE Day 1 de Monday Night <\/strong>RAW de ce soir \u00e0 San Diego, en Californie, il a \u00e9t\u00e9 rapport\u00e9 qu&rsquo;un ancien champion du monde serait de retour pour le sp\u00e9cial annuel de la marque rouge, par Paul \u00ab Triple H \u00bb Levesque confirmant lui m\u00eame les rumeurs.<\/p>\n\n\n\n<p>Notre s\u00e9lecte source rapporte qu&rsquo;il ne devrait pas s&rsquo;agir de Mercedes Mon\u00e9, malgr\u00e9 ses r\u00e9cents postes sur les r\u00e9seaux sociaux qui pouvait le laisser pr\u00e9sager. Et comme cela a \u00e9t\u00e9 dit, on parle de champion du monde et de son temps, ce titre n&rsquo;existait pas pour les femmes dans la compagnie. <\/p>\n\n\n\n<p>Ce que l&rsquo;ont sait par contre c&rsquo;est qu&rsquo;il est dit que la surprise devrait avoir un segment complet de l\u2019\u00e9mission \u00e0 peu pr\u00e8s \u00e0 mi-chemin de la diffusion de trois heures. <\/p>\n\n\n\n<p>Dwayne \u00ab The Rock \u00bb Johnson \u00e9tait \u00e0 Pasadena, qui n&rsquo;est qu&rsquo;\u00e0 quelques heures du lieu de l&rsquo;\u00e9mission de la WWE de ce soir, et lorsque cela a \u00e9t\u00e9 mentionn\u00e9 \u00e0 un haut responsable dans les coulisses de la WWE, ils n&rsquo;ont ni confirm\u00e9 ni ni\u00e9 que se sera lui, mais ont  mentionn\u00e9 que c&rsquo;\u00e9tait \u00ab convaincant \u00bb lorsque les notes de The Rock \u00e9t\u00e9 \u00e9voqu\u00e9es. <\/p>\n\n\n\n<p>Rien n&rsquo;est confirm\u00e9 alors assurez-vous de nous rejoindre ici ce soir pour voir le WWE Day One depuis San Diego dans l&rsquo;\u00e9tat de la Californie.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>En vous souhaitant une bonne ann\u00e9e 2024 et bienvenue sur le site qui vous en donnera encore plus cette ann\u00e9e! La question du jour demeure \u00ab Qui est l\u2019ancien champion du monde qui revient \u00e0 la WWE ce soir ? \u00bb Nous ne le savons pas encore, mais voici ce que nous avons appris. \u00c0&#8230;<\/p>\n","protected":false},"author":2,"featured_media":93591,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,30,77,4,43,87,42],"tags":[],"ppma_author":[287],"class_list":["post-93590","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew-impact-njpw-roh","category-ex-wwe","category-hall-of-fame","category-news","category-raw-wwe","category-road-to-wrestlemania","category-wrestlemania"],"authors":[{"term_id":287,"user_id":2,"is_guest":0,"slug":"jason","display_name":"Jason Desc\u00f4teaux","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/f64adf6d13198c3a532c061cecd8672089a1e9a3d07c702dffe886a7e55a15eb?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/93590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=93590"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/93590\/revisions"}],"predecessor-version":[{"id":93592,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/93590\/revisions\/93592"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/93591"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=93590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=93590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=93590"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=93590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}