{"id":93023,"date":"2023-12-14T00:58:00","date_gmt":"2023-12-14T05:58:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=93023"},"modified":"2024-04-22T14:54:31","modified_gmt":"2024-04-22T18:54:31","slug":"les-infos-pour-mettre-la-main-sur-les-billets-pour-le-wwe-backlash-de-lyon-en-france","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/12\/14\/les-infos-pour-mettre-la-main-sur-les-billets-pour-le-wwe-backlash-de-lyon-en-france\/","title":{"rendered":"Les infos pour mettre la main sur les billets pour le WWE BackLash de Lyon en France!"},"content":{"rendered":"\n<p>Comme vous le savez, la WWE organisera pour la toute premi\u00e8re fois de son histoire un show t\u00e9l\u00e9 mais en plus un Premium Live Event en France, en occurence le WWE Backlash 2024 avec le SmackDown de la veille qui se fera \u00e9galement depuis la LDLC Arena de Lyon.<\/p>\n\n\n\n<p>Juste avant les f\u00eate de fin d&rsquo;ann\u00e9e, la WWE vient d&rsquo;annoncer&nbsp;la date de la mise en vente des billets&nbsp;combin\u00e9s&nbsp;pour Backlash ainsi que SmackDown. Ainsi, les fans pourront acheter&nbsp;leur billet d\u00e8s le&nbsp;vendredi 12 janvier 2024&nbsp;sur <a rel=\"noreferrer noopener\" href=\"https:\/\/www.ticketmaster.fr\/fr\/manifestation\/wwe-pass-2-shows-smackdown-backlash-billet\/idmanif\/571931\" target=\"_blank\">Ticketmaster<\/a>. <\/p>\n\n\n\n<p>La WWE organisera une pr\u00e9vente le 10 janvier d\u00e8s 10h, n&rsquo;oubliez pas de&nbsp;vous y inscrire&nbsp;pour y avoir acc\u00e8s, en <a rel=\"noreferrer noopener\" href=\"https:\/\/www.wwe.com\/backlash-2024-presale\" target=\"_blank\">cliquant ici<\/a>.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><blockquote class=\"twitter-tweet\" data-media-max-width=\"560\"><p lang=\"fr\" dir=\"ltr\">Les billets combin\u00e9s pour <a href=\"https:\/\/twitter.com\/hashtag\/SmackDown?src=hash&amp;ref_src=twsrc%5Etfw\">#SmackDown<\/a> et <a href=\"https:\/\/twitter.com\/hashtag\/WWEBacklash?src=hash&amp;ref_src=twsrc%5Etfw\">#WWEBacklash<\/a> France depuis la <a href=\"https:\/\/twitter.com\/LDLC_Arena?ref_src=twsrc%5Etfw\">@LDLC_Arena<\/a> de Lyon-D\u00e9cines, seront disponibles le Vendredi 12 Janvier 2024! <br><br>Inscrivez-vous maintenant pour recevoir une offre exclusive de pr\u00e9-ventes &#x1f449; <a href=\"https:\/\/t.co\/j5OB4bk2SP\">https:\/\/t.co\/j5OB4bk2SP<\/a> <a href=\"https:\/\/t.co\/pRTeDNvMhF\">pic.twitter.com\/pRTeDNvMhF<\/a><\/p>\u2014 WWE France (@WWEFrance) <a href=\"https:\/\/twitter.com\/WWEFrance\/status\/1735223106275332328?ref_src=twsrc%5Etfw\">December 14, 2023<\/a><\/blockquote> <script async=\"\" src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n<\/td><td><blockquote class=\"twitter-tweet\" data-media-max-width=\"560\"><p lang=\"fr\" dir=\"ltr\">Oui c&rsquo;est historique ! SmackDown and Backlash de la <a href=\"https:\/\/twitter.com\/WWE?ref_src=twsrc%5Etfw\">@WWE<\/a> seront organis\u00e9s en France pour la premi\u00e8re fois. &#x1f4aa;<br><br>&#x1f517;&#x1f3ab; Pr\u00e9vente exclusive LDLC Arena le 11 janvier 2024 : <a href=\"https:\/\/t.co\/BkoXgycJ9J\">https:\/\/t.co\/BkoXgycJ9J<\/a> <a href=\"https:\/\/t.co\/IzX4CmNJVF\">pic.twitter.com\/IzX4CmNJVF<\/a><\/p>\u2014 LDLC Arena (@LDLC_Arena) <a href=\"https:\/\/twitter.com\/LDLC_Arena\/status\/1735227938411348077?ref_src=twsrc%5Etfw\">December 14, 2023<\/a><\/blockquote> <script async=\"\" src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/td><\/tr><\/tbody><\/table><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Comme vous le savez, la WWE organisera pour la toute premi\u00e8re fois de son histoire un show t\u00e9l\u00e9 mais en plus un Premium Live Event en France, en occurence le WWE Backlash 2024 avec le SmackDown de la veille qui se fera \u00e9galement depuis la LDLC Arena de Lyon. Juste avant les f\u00eate de fin&#8230;<\/p>\n","protected":false},"author":4,"featured_media":93024,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52,4,45,23],"tags":[],"ppma_author":[292],"class_list":["post-93023","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-backlash","category-news","category-ppv-wwe","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/93023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=93023"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/93023\/revisions"}],"predecessor-version":[{"id":98678,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/93023\/revisions\/98678"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/93024"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=93023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=93023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=93023"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=93023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}