{"id":92775,"date":"2023-12-09T00:37:00","date_gmt":"2023-12-09T05:37:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=92775"},"modified":"2023-12-11T14:51:23","modified_gmt":"2023-12-11T19:51:23","slug":"shawn-michaels-revele-que-dragon-lee-remplacant-wes-lee-pour-deadline-de-nxt-une-decision-de-derniere-minute","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/12\/09\/shawn-michaels-revele-que-dragon-lee-remplacant-wes-lee-pour-deadline-de-nxt-une-decision-de-derniere-minute\/","title":{"rendered":"Shawn Michaels r\u00e9v\u00e8le que Dragon Lee rempla\u00e7ant Wes Lee pour Deadline de NXT! Une d\u00e9cision de derni\u00e8re minute!"},"content":{"rendered":"\n<p>Shawn Michaels se confie sur la blessure de Wes Lee.<\/p>\n\n\n\n<p>Lee a annonc\u00e9 \u00e0 NXT mardi qu\u2019il \u00e9tait bless\u00e9 et qu\u2019il ne serait pas en mesure d\u2019affronter Dominik Mysterio lors de l\u2019\u00e9v\u00e9nement en direct premium NXT Deadline de ce samedi. The Heartbreak Kid a parl\u00e9 de la blessure de Lee lors de l\u2019appel aux m\u00e9dias de NXT Deadline d\u2019aujourd\u2019hui.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Eh bien, la d\u00e9cision avec Wes \u00e9tait assez proche de la derni\u00e8re minute. Wes se bat depuis un certain temps, je n\u2019en connaissais certainement pas la profondeur. \u00c9videmment, nous recevons des rapports m\u00e9dicaux, mais c\u2019est une d\u00e9cision que Wes a prise de lui-m\u00eame, comme il se doit. De toute \u00e9vidence, c\u2019est un jeune homme qui va sur le terrain et qui performe comme peu d\u2019autres et il avait d\u00e9j\u00e0 un \u00e9norme match avant cet \u00e9v\u00e9nement en direct \u00e0 la recherche du championnat nord-am\u00e9ricain, mais juste un jour ou deux avant, nous avons eu une longue conversation et il ne pensait tout simplement pas qu\u2019il pourrait passer \u00e0 travers le match avec la douleur qu\u2019il ressentait. C\u2019est une d\u00e9cision que lui et notre \u00e9quipe m\u00e9dicale ont prise, c\u2019est la meilleure d\u00e9cision pour Wes et c\u2019est la seule chose qui est importante dans mon esprit en ce moment. Tout cela s\u2019est pass\u00e9 \u00e0 la derni\u00e8re minute, Wes, et c\u2019est tout \u00e0 son honneur, faisait tout ce qu\u2019il pouvait pour se pr\u00e9parer \u00e0 cela, mais ce n\u2019\u00e9tait pas cens\u00e9 \u00eatre le cas.<\/p>\n<\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>Michaels explique alors que Dragon Lee rempla\u00e7ant Wes Lee a \u00e9t\u00e9 une d\u00e9cision de derni\u00e8re minute, et que Dragon Lee a \u00e9videmment des affaires inachev\u00e9es avec Dominik Mysterio.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Donc, nous avons pris la d\u00e9cision de derni\u00e8re minute, je suppose, moins de 24 heures avec Dragon Lee. Je vais dire ceci, il y a \u00e9videmment une histoire d\u2019avant avec Dragon Lee. D\u2019un point de vue \u00e9go\u00efste, pour moi, j\u2019avais tellement h\u00e2te et j\u2019appr\u00e9ciais de l\u2019avoir \u00e0 NXT, mais je mentirais si je ne disais pas que je ne l\u2019ai pas eu aussi longtemps que je le voulais. C\u2019est quelque chose qui, encore une fois, j\u2019ai senti que ce serait un match fantastique. C\u2019est quelqu\u2019un que j\u2019appr\u00e9cie et que j\u2019aime personnellement, pas seulement en tant qu\u2019interpr\u00e8te, mais aussi en tant qu\u2019\u00eatre humain. Je sais qu\u2019il y avait des matchs qui \u00e9taient encore sur la table pour moi \u00e0 NXT, donc j\u2019ai pens\u00e9 que s\u2019il y avait une possibilit\u00e9 que ces matchs puissent avoir lieu, que Dragon Lee serait le meilleur choix. C\u2019est g\u00e9nial de l\u2019avoir \u00e0 NXT, m\u00eame si c\u2019est pour un peu plus longtemps.<\/p>\n<\/blockquote>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"CPDHf0anIO\"><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/12\/09\/resultats-et-video-pour-le-le-special-wwe-nxt-deadline-2023\/\">R\u00e9sultats et Vid\u00e9o pour le le Sp\u00e9cial WWE NXT Deadline 2023!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0R\u00e9sultats et Vid\u00e9o pour le le Sp\u00e9cial WWE NXT Deadline 2023!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2023\/12\/09\/resultats-et-video-pour-le-le-special-wwe-nxt-deadline-2023\/embed\/#?secret=cz8Ty4S84d#?secret=CPDHf0anIO\" data-secret=\"CPDHf0anIO\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Shawn Michaels se confie sur la blessure de Wes Lee. Lee a annonc\u00e9 \u00e0 NXT mardi qu\u2019il \u00e9tait bless\u00e9 et qu\u2019il ne serait pas en mesure d\u2019affronter Dominik Mysterio lors de l\u2019\u00e9v\u00e9nement en direct premium NXT Deadline de ce samedi. The Heartbreak Kid a parl\u00e9 de la blessure de Lee lors de l\u2019appel aux m\u00e9dias&#8230;<\/p>\n","protected":false},"author":665,"featured_media":92864,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,85,45,23],"tags":[],"ppma_author":[289],"class_list":["post-92775","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-nxt","category-ppv-wwe","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/92775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=92775"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/92775\/revisions"}],"predecessor-version":[{"id":92865,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/92775\/revisions\/92865"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/92864"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=92775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=92775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=92775"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=92775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}