{"id":92760,"date":"2023-12-07T00:12:00","date_gmt":"2023-12-07T05:12:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=92760"},"modified":"2023-12-07T15:05:14","modified_gmt":"2023-12-07T20:05:14","slug":"bryan-danielson-fait-ses-adieu-a-montreal-apres-le-taping-du-aew-rampage-plus-spoilers-du-show-a-la-fin","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/12\/07\/bryan-danielson-fait-ses-adieu-a-montreal-apres-le-taping-du-aew-rampage-plus-spoilers-du-show-a-la-fin\/","title":{"rendered":"Bryan Danielson fait ses adieux \u00e0 Montr\u00e9al apr\u00e8s le taping du AEW Rampage!"},"content":{"rendered":"\n<p>Et oui encore des retomb\u00e9s du show de Montr\u00e9al lors du taping de Rampage qui se d\u00e9roulait apr\u00e8s le direct de Dynamite mercredi soir au Centre Bell.<\/p>\n\n\n\n<p> Bryan Danielson a fait ses premiers matchs t\u00e9l\u00e9vis\u00e9s dans la M\u00e9tropole depuis l&rsquo;\u00e9pisode de RAW \u00e0 la datant de 2012 alors qu&rsquo;il travaillait sous le nom de Daniel Bryan.<\/p>\n\n\n\n<p>Et donc mardi soir Danielson a pu affronter Andrade El Idolo lors du AEW Collision enregistr\u00e9 madi soir qui sera diffus\u00e9 ce samedi pour ensuite affronter Daniel Garcia du \u00e0 Rampage enregistr\u00e9 mercredi qui sersa diffus\u00e9 ce vendredi.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>Bien que son passage a \u00e9t\u00e9 apr\u00e9ci\u00e9 des fans, il a laiss\u00e9 un go\u00fbt amer mercredi soir apr\u00e8s avoir pris le micro pour d\u00e9voil\u00e9 qu&rsquo;il s&rsquo;agissait&nbsp;peut-\u00eatre de ses derniers matchs \u00e0 Montr\u00e9al, le signe d&rsquo;une retraite qui serait tr\u00e8s proche comme vous nous en avons parl\u00e9 quelque fois d\u00e9j\u00e0. <\/p>\n\n\n\n<p>Bryan Danielson nous dit :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab\u00a0Ce soir pourrait \u00eatre la derni\u00e8re fois que je catche \u00e0 Montr\u00e9al. Je dis \u00e7a pour vous remercier car \u00e0 chaque fois que je suis venu \u00e0 Montr\u00e9al dans ma carri\u00e8re, vous \u00e9tiez badass et je vous en remercie ! Merci Montr\u00e9al !\u00a0\u00bb<\/p>\n<\/blockquote>\n\n\n\n<p>Tony Khan qui est sorti hors onde apr\u00e8s le show a fait signe que non que ce n&rsquo;est pas sa derni\u00e8re fois mais la d\u00e9cision reste tout de m\u00eame \u00e0 l&rsquo;ancien champion de la WWE. De plus la foule lui a fait un chante \u00ab\u00a0PPV, PPV\u00a0\u00bb et le pr\u00e9sident a dit qu&rsquo;il en prenait bonne note pour ce que \u00e7a vaut.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>Ce n&rsquo;est pas la premi\u00e8re fois que Bryan Danielson \u00e9voque une potentielle retraite. Il avait d\u00e9j\u00e0 d\u00e9clar\u00e9 vouloir prendre sa retraite durant les prochains mois.<\/p>\n\n\n\n<p>Nous vous rappelons que Bryan Danielson est annonc\u00e9 pour AEW All In 2024, qui aura lieu depuis le Wembley Stadium de Londres en ao\u00fbt 2024. Il s&rsquo;agira peut-\u00eatre de l&rsquo;une des derni\u00e8res occasions de le voir sur le ring.<\/p>\n\n\n\n<center><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/FC3D2ro6Ad8?si=Gj-VIXduaOXwoED8\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/center>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Et oui encore des retomb\u00e9s du show de Montr\u00e9al lors du taping de Rampage qui se d\u00e9roulait apr\u00e8s le direct de Dynamite mercredi soir au Centre Bell. Bryan Danielson a fait ses premiers matchs t\u00e9l\u00e9vis\u00e9s dans la M\u00e9tropole depuis l&rsquo;\u00e9pisode de RAW \u00e0 la datant de 2012 alors qu&rsquo;il travaillait sous le nom de Daniel&#8230;<\/p>\n","protected":false},"author":4,"featured_media":92767,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,91,89,30,4],"tags":[],"ppma_author":[292],"class_list":["post-92760","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-all-in","category-collision","category-ex-wwe","category-news"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/92760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=92760"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/92760\/revisions"}],"predecessor-version":[{"id":92766,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/92760\/revisions\/92766"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/92767"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=92760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=92760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=92760"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=92760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}