{"id":92560,"date":"2023-12-01T01:28:00","date_gmt":"2023-12-01T06:28:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=92560"},"modified":"2023-12-01T13:33:17","modified_gmt":"2023-12-01T18:33:17","slug":"lannee-2023-se-termine-mal-pour-certains-fonctionnaires-de-la-wwe","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/12\/01\/lannee-2023-se-termine-mal-pour-certains-fonctionnaires-de-la-wwe\/","title":{"rendered":"L&rsquo;ann\u00e9e 2023 se termine mal pour certains fonctionnaires de la WWE!"},"content":{"rendered":"\n<p>Une nouvelle vague de licenciements au si\u00e8ge social de la WWE s&rsquo;est d\u00e9roul\u00e9e aujourd&rsquo;hui le 1er d\u00e9cembre 2023.<\/p>\n\n\n\n<p>En effet, on apprend via nos sources que la WWE a licenci\u00e9 un nouveau groupe d&#8217;employ\u00e9s \u00e0 Stamford au Connecticut. Au niveau des personnalit\u00e9s \u00e0 l&rsquo;\u00e9cran,\u00a0McKenzie Mitchell fut la premi\u00e8re\u00a0a annonc\u00e9 son licenciement de la compagnie, mais il ne devrait pas y avoir d&rsquo;autres personnes du c\u00f4t\u00e9 du staff que vous voyez dans vos \u00e9crans. <\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>En revenge, en septembre 2023, on apprenait que la\u00a0WWE avait licenci\u00e9 plus de 100 employ\u00e9s\u00a0et aujourd&rsquo;hui la liste s&rsquo;allonge une nouvelle fois. La WWE avait fait de nombreuses coupures avant l&rsquo;achat et la fusion du groupe TKO en avril 2023, mais les coupures d&rsquo;aujourd&rsquo;hui et de septembre 2023 sont pour r\u00e9duire les effectifs en raison qu&rsquo;un employ\u00e9 d&rsquo;un d\u00e9partement peut travailler pour la WWE et la UFC en m\u00eame temps et non doubl\u00e9 les r\u00f4les.<\/p>\n\n\n\n<p>Cette nouvelle vague de licenciements de d\u00e9cembre 2023 avait \u00e9t\u00e9 annonc\u00e9e par les directeurs du groupe TKO lors de la derni\u00e8re conf\u00e9rence des actionnaires. Il est actuellement trop t\u00f4t afin de savoir combien de personne ont perdu leur emploi.<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"QA7O4en27M\"><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/12\/01\/mckenzie-mitchell-licenciee-de-la-wwe-mais-elle-a-un-plan-b\/\">McKenzie Mitchell licenci\u00e9e de la WWE mais elle a un plan B.<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0McKenzie Mitchell licenci\u00e9e de la WWE mais elle a un plan B.\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2023\/12\/01\/mckenzie-mitchell-licenciee-de-la-wwe-mais-elle-a-un-plan-b\/embed\/#?secret=DwGAWo6emK#?secret=QA7O4en27M\" data-secret=\"QA7O4en27M\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Une nouvelle vague de licenciements au si\u00e8ge social de la WWE s&rsquo;est d\u00e9roul\u00e9e aujourd&rsquo;hui le 1er d\u00e9cembre 2023. En effet, on apprend via nos sources que la WWE a licenci\u00e9 un nouveau groupe d&#8217;employ\u00e9s \u00e0 Stamford au Connecticut. Au niveau des personnalit\u00e9s \u00e0 l&rsquo;\u00e9cran,\u00a0McKenzie Mitchell fut la premi\u00e8re\u00a0a annonc\u00e9 son licenciement de la compagnie, mais&#8230;<\/p>\n","protected":false},"author":4,"featured_media":92562,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,23],"tags":[],"ppma_author":[292],"class_list":["post-92560","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/92560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=92560"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/92560\/revisions"}],"predecessor-version":[{"id":92563,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/92560\/revisions\/92563"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/92562"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=92560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=92560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=92560"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=92560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}