{"id":92526,"date":"2023-11-30T14:58:24","date_gmt":"2023-11-30T19:58:24","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=92526"},"modified":"2023-12-04T00:24:21","modified_gmt":"2023-12-04T05:24:21","slug":"resultats-et-video-pour-le-aew-dynamite-du-29-novembre-2023","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/11\/30\/resultats-et-video-pour-le-aew-dynamite-du-29-novembre-2023\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le AEW Dynamite du 29 Novembre 2023!"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong>Pour voir Dynamite, cliquez ici.<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size\"><strong>AEW Dynamite Minneapolis, Minnesota, 29 novembre 2023<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Taz, Excalibur et Bryan Danielson.<\/p>\n\n\n\n<p>&#8211; Le  AEW Dynamite d\u00e9bute avec les commentateurs qui nous souhaitent la bienvenue et Bryan Danielson arrive pour s&rsquo;installer avec les commentateurs pour le soir\u00e9e.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Tournoi AEW Continental Classic <\/strong><\/p>\n\n\n\n<p><strong>Jon Moxley vs Jay Lethal<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin, Moxley fait une Clothesline \u00e0 Lethal et enchaine avec un Pile Driver pour le couvrir, mais Lethal r\u00e9siste \u00e0 deux. Moxley enchaine directement avec son Bulldog Choke pour le faire taper.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnant : Jon Moxley&nbsp;<\/em><\/p>\n\n\n\n<p>&#8211; En vid\u00e9o de samedi dernier apr\u00e8s Collision, Eddie Kingston dit qu&rsquo;il savait que le tournoi serait difficile. Peut-\u00eatre qu&rsquo;il \u00e9tait trop arrogant, comme si ses 2 titres voulaient dire qu&rsquo;il allait forc\u00e9ment gagner.<\/p>\n\n\n\n<p> Kingston dit qu&rsquo;il va rester humble dans la victoire et la d\u00e9faite. Il doit se concentrer sur son prochain adversaire Bryan Danielson.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; De retour suite \u00e0 la pause, en coulisse,&nbsp;Tony Schiavone dit que Revolution aura lieu le 3 mars 2024 pour la retraite de Sting. Ils ont cherch\u00e9 la meilleure salle pour le dernier match de Sting, alors ce sera en Caroline du Nord au Greensboro Coliseum.&nbsp;<\/p>\n\n\n\n<p>Ric Flair et Sting arrivent pour parler de leur rivalit\u00e9 dans cette salle. Sting dit qu&rsquo;il a eu son premier match de titre mondial face \u00e0 Ric Flair dans cette salle. Il n&rsquo;aurait jamais cru possible d&rsquo;\u00eatre 30 ans plus tard avec les trois ici ce soir pour en parler. Le match a fini en \u00e9galit\u00e9 apr\u00e8s 45 minutes sans publicit\u00e9, c&rsquo;\u00e9tait une premi\u00e8re. Flair l&rsquo;a mis sur la carte ce soir l\u00e0 et il veut le remercier pour \u00e7a. L&rsquo;endroit est id\u00e9al pour terminer sa carri\u00e8re. <\/p>\n\n\n\n<p>Ric Flair dit qu&rsquo;il n&rsquo;y a pas de mot pour d\u00e9crire ce qui arrivera l\u00e0-bas. Pendant ces 45 minutes Sting s&rsquo;est fait un nom par lui-m\u00eame et Sting a gagn\u00e9 le respect de ses coll\u00e8gues. Il est chanceux d&rsquo;\u00eatre \u00e0 c\u00f4t\u00e9 de Sting avec ses amis et aller \u00e0 Greensboro pour voir ce moment. Wooo Wooo Wooo.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Tournoi AEW Continental Classic <\/strong><\/p>\n\n\n\n<p><strong>Mark Briscoe vs Rush<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin, Briscoe arrive \u00e0 repousser Rush et lui fait son Elbow Drop du coin pour le couvrir, mais Rush r\u00e9siste \u00e0 deux. Briscoe veut poursuivre avec son finisher, mais Rush le repousse. Rush lui fait une Belly to Belly contre le coin. Rush enchaine avec son Bull Horn&rsquo;s sur Briscoe pour le compte de trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnant : Rush<\/em><\/p>\n\n\n\n<p>&#8211; En coulisse, on retrouve Toni Storm qui se repose et RJ City arrive pour une interview. RJ demande comment elle va apr\u00e8s son speech d&rsquo;acceptation. Storm dit qu&rsquo;elle est fatigu\u00e9e et d\u00e9shydrat\u00e9e. <\/p>\n\n\n\n<p>RJ dit qu&rsquo;elle devra d\u00e9fendre son titre la semaine prochaine, est-ce qu&rsquo;elle est pr\u00e9occup\u00e9e ? Storm dit qu&rsquo;elle n&rsquo;a aucune inqui\u00e9tude.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; Le&nbsp;<strong>champion mondial MJF<\/strong>&nbsp;arrive sur le ring et prend le micro. MJF dit qu&rsquo;il va affronter Samoa Joe pour le titre mondial \u00e0 Worlds End. Il n&rsquo;aime pas vraiment Samoa Joe comme personne, mais il a du respect professionnellement pour lui. Il a du respect pour ce que Joe a fait dans le catch et par le fait qu&rsquo;il est venu \u00e0 la AEW car Joe croyait en la compagnie. Il se souvient avoir re\u00e7u un poster de la TNA. <\/p>\n\n\n\n<p>MJF poursuit en disant que le Submission Machine se d\u00e9marquait car \u00e0 chaque fois que Joe arrivait on savait qu&rsquo;il \u00e9tait le plus dur \u00e0 cuire. Mais Joe n&rsquo;a jamais eu la chance d&rsquo;\u00eatre champion mondial \u00e0 la WWE &#8230;. Mais Joe a fait plus, Joe a prouv\u00e9 qu&rsquo;on n&rsquo;a pas besoin d&rsquo;\u00eatre on body builder pour \u00eatre au sommet du sport. Joe a prouv\u00e9 qu&rsquo;il y a des alternatives et quelqu&rsquo;un comme lui peut-\u00eatre ici aujourd&rsquo;hui. Sans Joe il n&rsquo;y aurait peut-\u00eatre pas de la AEW, alors merci Joe !<\/p>\n\n\n\n<p>MJF continue en disant qu&rsquo;il a un beau parcours aussi. Il a \u00e9t\u00e9 en mesure de construire une nouvelle alternative. Depuis le premier jour il est \u00e0 l&rsquo;AEW et il a construit l&rsquo;endroit brique par brique. Il l&rsquo;a fait en battant des gens comme CM Punk, Cody Rhodes, Jon Moxley, Kenny Omega et autres. Il a aussi surv\u00e9cu contre Samoa Joe. Joe est une l\u00e9gende, mais \u00e0 Worlds End c&rsquo;est pour son h\u00e9ritage. \u00c0 Worlds End MJF va vaincre le boss final une fois de plus. Il va faire une promesse pour tous les fans, le 30 d\u00e9cembre ce n&rsquo;est pas important si sa hanche se d\u00e9boite une autre fois ou si son \u00e9paule l\u00e2che, il promet de montrer au monde que ce n&rsquo;est pas la grosseur du chien qui importe mais bien sa force. \u00c0 Worlds End Joe devra le tuer pour le vaincre. <\/p>\n\n\n\n<p>MJF pose devant les fans, mais les lumi\u00e8res commencent \u00e0 clignoter.&nbsp;Le groupe du diable arrive sur le ring pour attraper MJF, mais Samoa Joe arrive pour les en chasser ! Les lumi\u00e8res s&rsquo;\u00e9teignent et on peut lire un challenge pour un Tag Team Match de la part du groupe du diable. \u00ab\u00a0\u00c0 moins que MJF ne soit pas le h\u00e9ros qu&rsquo;il pr\u00e9tend \u00eatre\u00a0\u00bb. MJF dit que \u00e7a suffit avec cette histoire. Il va d\u00e9masquer tous ses hommes les uns apr\u00e8s les autres. Ils veulent un match par \u00e9quipe, alors il va leur donner&nbsp;!<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; De retour, les commentateurs confirment que MJF et Samoa Joe vont affronter deux hommes masqu\u00e9s la semaine prochaine \u00e0 AEW Montr\u00e9al.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Wardlow vs AR Fox<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin, Wardlow fait une Powerbomb \u00e0 AR Fox, une seconde et un Swenton Bomb du coin. Wardlow rel\u00e8ve Fox pour une troisi\u00e8me Powerbomb et l&rsquo;arbitre arr\u00eate le match.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnant : Wardlow&nbsp;<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Hardy Boyz&nbsp;<em>(Matt et Jeff Hardy)<\/em>&nbsp;et Brother Zay vs Top Flight<em>&nbsp;(Dante et Darius Martin)<\/em>&nbsp;et Action Andretti<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin, Darius et Andretti s&rsquo;occupent des Hardy en ringside. Dante bloque une prise de Zay sur le ring. Darius intervient pour une German Suplex et Dante compl\u00e8te avec une Slam pour le compte de trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnants : Top Flight et Action Andretti<\/em><\/p>\n\n\n\n<p>&#8211; De retour, en coulisse, Renee Paquette est avec les gagnants du dernier match pour avoir leurs commentaires, mais Penta El Zero Miedo arrive. Penta et Dante se tapent dans la main. El Hijo del Vikingo et Komander arrivent pour lancer le challenge d&rsquo;un trois contre trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>TBS Championship &#8211; House Rules Match<\/strong><\/p>\n\n\n\n<p><strong>Julia Hart \u00a9 vs Emi Sakura<\/strong><br><em>Aucune victoire par soumission.<\/em><\/p>\n\n\n\n<p>\u00c0 la fin, Julia arrive \u00e0 appliquer son Hartless, Sakura tape, mais \u00e7a ne change rien puisque c&rsquo;est House Rules sans soumission. Julia arr\u00eate la soumission et porte un coup de pied \u00e0 Sakura. Julia enchaine avec son Moonsault pour le compte de trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnante : Julia Hart<\/em><\/p>\n\n\n\n<p>&#8211; En coulisse, RJ City est avec Mariah May pour en savoir plus sur ses intentions. Mariah May dit qu&rsquo;elle est la nouvelle et elle a h\u00e2te de montrer ce qu&rsquo;elle peut faire. Alors merci de lui avoir pr\u00e9sent\u00e9 Toni Storm et elle sait que Toni l&rsquo;adore. <\/p>\n\n\n\n<p>RJ dit qu&rsquo;il est heureux d&rsquo;aider. Mariah May entre dans le bureau de Tony Khan.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211;&nbsp;<strong>Christian Cage<\/strong>&nbsp;arrive sur le ring avec des agents de s\u00e9curit\u00e9 et prend le micro. Christian dit qu&rsquo;il aimerait inviter la Rated R Superstar sur ce ring. Personne n&rsquo;arrive. Christian dit qu&rsquo;il sait qu&rsquo;Adam Copeland est l\u00e0. Il veut simplement r\u00e9pondre au challenge de Copeland alors il aimerait bien avoir sa pr\u00e9sence. Personne n&rsquo;arrive. Christian dit qu&rsquo;il aimerait parler \u00e0 Copeland. C&rsquo;est possible de l&rsquo;aviser via quelqu&rsquo;un en coulisse ? Personne n&rsquo;arrive. <\/p>\n\n\n\n<p>La musique d&rsquo;Adam Copeland commence finalement et il arrive sur le ring. Christian se cache derri\u00e8re les agents de s\u00e9curit\u00e9. Christian continue en disant que les directeurs voulaient avoir la s\u00e9curit\u00e9, ce n&rsquo;est pas son id\u00e9e. Mais Copeland a raison, ils n&rsquo;ont pas besoin d&rsquo;agents de s\u00e9curit\u00e9, alors ils peuvent partir. Les agents quittent le ring. Christian dit que la semaine derni\u00e8re Copeland l&rsquo;a challeng\u00e9 pour un match de championnat TNT \u00e0 <strong>Montr\u00e9al <\/strong>pour  Dynamite. Il est ici pour annoncer qu&rsquo;ils ne pourront pas atteindre Montr\u00e9al. <\/p>\n\n\n\n<p>Christian poursuit en disant que Copeland a envoy\u00e9 Killswitch et Nick Wayne sur la touche. Il est tr\u00e8s frustr\u00e9 par ces \u00e9v\u00e9nements. Tellement qu&rsquo;il avait besoin de d&rsquo;air frais pour penser. C&rsquo;\u00e9tait un roadtrip de pens\u00e9es et de recherches afin de savoir pourquoi il est devenu cette personne. Et sur la route il s&rsquo;est souvenu du moment lorsqu&rsquo;ils ont emprunt\u00e9 la voiture de sa m\u00e8re pour faire la tourn\u00e9e des shows. Il n&rsquo;avait pas un dollar, mais ce n&rsquo;\u00e9tait pas important. Ils savaient qu&rsquo;ils allaient r\u00e9ussir et ils l&rsquo;ont fait.<\/p>\n\n\n\n<p>Christian dit qu&rsquo;ils sont devenus plusieurs fois champions par \u00e9quipe, la meilleure \u00e9quipe de tous les temps. Mais si on enl\u00e8ve la relation catch, c&rsquo;est encore plus profond. Tout le monde sait que Copeland a grandi avec une m\u00e8re seule, tout le monde sait que Copeland n&rsquo;avait pas de figure paternelle. Il ne dit pas qu&rsquo;il est le p\u00e8re de Copeland, mais il est son fr\u00e8re. Son p\u00e8re est devenu le p\u00e8re de Copeland. Copeland \u00e9tait \u00e0 la table de famille, Copeland a dormi \u00e0 la maison et son p\u00e8re le soutient encore m\u00eame aujourd&rsquo;hui. Il aime Copeland, ils sont une famille. Lorsque la m\u00e8re de Copeland est morte il y a quelques ann\u00e9es, c&rsquo;\u00e9tait le moment le plus difficile de sa vie.&nbsp;Mais juste avant de mourir, elle a dit qu&rsquo;elle aimerait voir les deux une fois de plus sur le ring ensemble. Il a r\u00e9fl\u00e9chi et il s&rsquo;est dit pourquoi ne pas revenir ensemble comme une \u00e9quipe pour la m\u00e8re de Copeland ? Il faut le faire pour elle&nbsp;!<\/p>\n\n\n\n<p>Copeland est surpris par les paroles de Christian et ce dernier tente de le frapper avec le titre TNT mais Copeland lui fait un Low Blow ! Copeland dit que c&rsquo;\u00e9tait un bel essaie par un idiot. Copeland dit \u00e0 Christian de bien nettoyer la ceinture, car la semaine prochaine elle va venir avec lui. Il a presque oubli\u00e9 : va te faire foutre&nbsp;!<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Tournoi AEW Continental Classic <\/strong><\/p>\n\n\n\n<p><strong>Jay White vs Swerve Strickland<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin, Strickland fait un Back Breaker \u00e0 White et enchaine avec son House Call. Strickland monte sur le coin pour son Double Stomp et il touche la cible. Strickland le couvre, mais White r\u00e9siste \u00e0 la derni\u00e8re seconde. Strickland le rel\u00e8ve, mais White le surprend avec son Blade Runner. Strickland roule en bas du ring. Les deux font ensuite des comptes rapides et se donnent des coups. White arrive \u00e0 faire une Sleeper Suplex et le prend en Blade Runner, mais Strickland le renverse en compte rapide pour le compte de trois !<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnant : Swerve Strickland<\/em><\/p>\n\n\n\n<p>Le show se termine avec une c\u00e9l\u00e9bration de Strickland.<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"GGwTOXMaQp\"><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/11\/29\/avant-gout-pour-le-aew-dynamite-du-29-novembre-2023\/\">Reprise Vid\u00e9o et Programme pour le AEW Dynamite du 29 Novembre 2023!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Reprise Vid\u00e9o et Programme pour le AEW Dynamite du 29 Novembre 2023!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2023\/11\/29\/avant-gout-pour-le-aew-dynamite-du-29-novembre-2023\/embed\/#?secret=9DMQt9k3Fv#?secret=GGwTOXMaQp\" data-secret=\"GGwTOXMaQp\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>AEW Dynamite Minneapolis, Minnesota, 29 novembre 2023 Les commentateurs sont Taz, Excalibur et Bryan Danielson. &#8211; Le AEW Dynamite d\u00e9bute avec les commentateurs qui nous souhaitent la bienvenue et Bryan Danielson arrive pour s&rsquo;installer avec les commentateurs pour le soir\u00e9e. Tournoi AEW Continental Classic Jon Moxley vs Jay Lethal \u00c0 la fin, Moxley fait une&#8230;<\/p>\n","protected":false},"author":609,"featured_media":92528,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,50,30,77,21,49],"tags":[],"ppma_author":[295],"class_list":["post-92526","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-dynamite","category-ex-wwe","category-hall-of-fame","category-resultats","category-roh"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/92526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=92526"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/92526\/revisions"}],"predecessor-version":[{"id":92614,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/92526\/revisions\/92614"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/92528"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=92526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=92526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=92526"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=92526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}