{"id":92107,"date":"2023-11-17T22:27:00","date_gmt":"2023-11-18T03:27:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=92107"},"modified":"2023-11-21T19:44:27","modified_gmt":"2023-11-22T00:44:27","slug":"resultats-et-video-pour-le-aew-collision-du-17-novembre-2023","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/11\/17\/resultats-et-video-pour-le-aew-collision-du-17-novembre-2023\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le AEW Collision du 17 Novembre 2023!"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2023\/11\/17\/aew-en-face-a-face-avec-smackdown-ce-soir-des-20h-est-2h-europe-programme-et-avant-gout\/\" target=\"_blank\">Pour voir Collision, cliquez ici<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size\"><strong>AEW Collision Inglewood, Californie, 17 novembre 2023<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Kevin Kelly, Tony Schiavone et Nigel McGuinness.<\/p>\n\n\n\n<p>&#8211; Le  AEW Collision exceptionnellement vendredi, d\u00e9marre avec les commentateurs qui nous souhaitent la bienvenue et on retrouve Tony Schiavone sur le ring. <\/p>\n\n\n\n<p>&#8211; Schiavone nous pr\u00e9sente<strong>&nbsp;Christian Cage<\/strong>&nbsp;qui arrive sur le ring avec Luchasaurus et Nick Wayne. Schiavone demande \u00e0 Christian ses commentaires sur le fait qu&rsquo;il va d\u00e9fendre son titre TNT ce soir \u00e0 Rampage et ses commentaires sur Full Gear.<\/p>\n\n\n\n<p>Christian dit qu&rsquo;on est \u00e0 Los Angeles, une ville de gens en plastique, \u00e7a fera du bien d&rsquo;entendre un peu de v\u00e9rit\u00e9 ici. Demain nous verrons le dernier match de Sting \u00e0 Los Angeles et son dernier match en carri\u00e8re, c&rsquo;est une garantie. Il ne peut plus endurer Sting avec sa peinture stupide au visage et entendre le nommer un ic\u00f4ne. Ce n&rsquo;est pas un ic\u00f4ne de voler des ch\u00e8ques de payent depuis autant d&rsquo;ann\u00e9es. Il ajoute que si Darby a besoin d&rsquo;un peu d&rsquo;aide paternelle, il peut l&rsquo;appeler. Est-ce que Ric Flair sera ringside demain ? Schiavone approuve. Cage dit que si Flair se met le nez dans ses affaires, ce sera le moment o\u00f9 Flair va rencontrer J\u00e9sus.<\/p>\n\n\n\n<p>Christian dit que pour Adam Copeland, il va avoir regrett\u00e9 d&rsquo;avoir sign\u00e9 son contrat \u00e0 la AEW. Il connait Copeland le mieux, il sait que Copeland veut voler sa lumi\u00e8re et non faire \u00e9quipe avec lui. Il n&rsquo;est pas la m\u00eame personne qu&rsquo;il \u00e9tait, il est Christian Cage. Demain on va avoir quel chemin de carri\u00e8re aura aid\u00e9 le plus. Beth ferait mieux de coucher les enfants car il va casser le cou de Copeland. <\/p>\n\n\n\n<p>Schiavone lui demande ses commentaires sur le match TNT. Christian r\u00e9pond que c&rsquo;est normal de vouloir l&rsquo;avoir sur tous les shows. Ce n&rsquo;est pas important qui va gagner le 4-Way Match, il pourrait battre les 4 en m\u00eame temps. La foule lui chante de le prouver. Christian dit qu&rsquo;on le verra. Il est le syst\u00e8me.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; En coulisse, Lexy est avec Big Bill et Ricky Starks qui ont une nouvelle pour les fans. Big Bill dit qu&rsquo;ils sont la meilleure \u00e9quipe de l&rsquo;histoire sans question. Ce n&rsquo;\u00e9tait pas OK le fait de perdre les titres sans subir le compte. <\/p>\n\n\n\n<p>Ricky dit qu&rsquo;il a parl\u00e9 avec&nbsp;Tony Khan et il a eu le choix de choisir la stipulation pour corriger la situation. Alors ce sera un Ladder Match comme Big Bill est le plus grand. Ils vont quitter LA comme la meilleure \u00e9quipe en style.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Miro vs Daniel Garcia<\/strong><\/p>\n\n\n\n<p>En fin de match, Miro frappe Garcia et lui porte un coup de pied. Miro enchaine avec son Game Over pour l&#8217;emporter par soumission.<\/p>\n\n\n\n<p><em>Gagnant : Miro <\/em><\/p>\n\n\n\n<p>&#8211; En coulisse, Lexy est avec CJ \u00ab\u00a0Lana\u00a0\u00bb Perry et Andrade El Idolo pour avoir leur commentaire. Andrade dit qu&rsquo;il est tellement heureux d&rsquo;avoir CJ comme manager. <\/p>\n\n\n\n<p>CJ dit qu&rsquo;Andrade est le meilleur catcheur, un catcheur de troisi\u00e8me g\u00e9n\u00e9ration, il fait \u00e7a depuis ses 3 ans.&nbsp;Alors elle a ajout\u00e9 Andrade dans le tournoi Continental Classic, elle a n\u00e9goci\u00e9 avec Tony et il aura un bonus d&rsquo;argent pour sa participation.&nbsp;<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Andrade dit qu&rsquo;ils n&rsquo;ont pas parl\u00e9 de \u00e7a. CJ lui parle \u00e0 l&rsquo;oreille et Andrade est heureux.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>King Of The Black Throne&nbsp;<em>(Malakai Black et Brody King)<\/em>&nbsp;vs The Boyz&nbsp;<em>(Brent et Brandon)<\/em><\/strong><\/p>\n\n\n\n<p>En fin de match, Black et King terminent avec leur Inferno pour le compte de trois en moins de cinq minutes.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnants : King Of The Black Throne<\/em><\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur le match TBS de Full Gear.<\/p>\n\n\n\n<p style=\"font-size:25px\"><strong>Fatal 4 Way pour l&rsquo;Aspirant titre TNT <\/strong><\/p>\n\n\n\n<p><strong>Trent Beretta vs Brian Cage vs Komander vs Penta El Zero Miedo<\/strong><\/p>\n\n\n\n<p>En fin de match, Penta se lance en Flip sur Cage en bas du ring. Komander d\u00e9cide de se lancer en Flip sur Penta. Komander monte sur le coin et marche sur les c\u00e2bles pour son Splash, mais Beretta l&rsquo;\u00e9vite et l&rsquo;attrape pour son Strong Zero pour le compte de trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnant : Trent Beretta<\/em><\/p>\n\n\n\n<p>&#8211; En coulisse, Lexy est avec Don Callis et Powerhouse Hobbs pour avoir leur r\u00e9action sur l&rsquo;attaque sur Paul Wight. <\/p>\n\n\n\n<p>Callis dit que c&rsquo;est termin\u00e9 pour Paul Wight, il est sur la touche pour de bon. Hobbs a fait une Slam \u00e0 un g\u00e9ant, \u00e0 une l\u00e9gende, sur une voiture pour le casser. Lexy demande ce que \u00e7a repr\u00e9sente pour leur famille. <\/p>\n\n\n\n<p>Hobbs dit que \u00e7a repr\u00e9sente que tout le monde peut avoir le m\u00eame r\u00e9sultat. Il a mis sur la touche une l\u00e9gende, un g\u00e9ant, un multiple champion. Il est grand, noir et fort. Wight ferait mieux de rester \u00e0 l&rsquo;h\u00f4pital.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Wardlow vs Evan Daniels<\/strong><\/p>\n\n\n\n<p>Wardlow \u00e9cranse directement Daniels et lui fait une Powerbomb. Wardlow enchaine avec un Swenton Bomb et fait une Powerbomb, mais l&rsquo;arbitre arr\u00eate le match puisqu&rsquo;Evans ne r\u00e9pond plus.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnant : Wardlow&nbsp;via arr\u00eat de l&rsquo;arbitre<\/em><\/p>\n\n\n\n<p>&#8211; Les commentateurs&nbsp;pr\u00e9sentent la carte de Full Gear pour demain.<\/p>\n\n\n\n<p>&#8211; Ricky Starks et Big Bill prennent place avec les commentateurs pour le prochain match.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Dax Harwood vs Rush<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Rush se pr\u00e9pare pour son finisher, mais Starks entre sur le ring et lui fait un Spear ! Big Bill attaque Dax aussi. L&rsquo;arbitre arr\u00eate le combat.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Aucun Gagnant<\/em><\/p>\n\n\n\n<p> Apr\u00e8s le combat, les \u00e9quipes de Full Gear arrivent sur le ring pour la bagarre. Les officiels arrivent pour s\u00e9parer tout le monde.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; En coulisse, Lexy demande \u00e0 Action Andretti s&rsquo;il a une mise \u00e0 jour sur Darius Martin apr\u00e8s l&rsquo;attaque du Kingdom, mais le Kingdom arrive. Mike Bennett dit que Darius a un echymose \u00e0 l&rsquo;\u00e9go et un mauvais cou. Strong dit qu&rsquo;il a trouv\u00e9 sa prochaine victime : Action.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Buddy Matthews vs Wheeler Yuta<\/strong><\/p>\n\n\n\n<p>En fin de match, Matthews bloque une attaque sur le coin avec une Running Powerbomb pour le couvrir, mais Yuta r\u00e9siste. Matthews enchaine avec un Stomp et couvre Yuta pour le compte de trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnant : Buddy Matthews<\/em><\/p>\n\n\n\n<p> Apr\u00e8s le combat, Buddy Matthews d\u00e9cide d&rsquo;aller chercher une chaise, mais Claudio \u00ab\u00a0Cesaro\u00a0\u00bb Castagnoli arrive sur le ring, Matthews d\u00e9cide de de partir. <\/p>\n\n\n\n<p>Castagnoli dit que si Matthews voulait l&rsquo;attention du Blackpool Combat Club, suffisait de le demander et non faire des promos \u00e9tranges. Il pr\u00e9f\u00e8re faire ses challenges en personne ici sous la lumi\u00e8re. Il n&rsquo;aimerait pas venir \u00e0 Los Angeles sans botter un cul, alors pourquoi ne pas faire un match \u00e0 Full Gear ? \u00c0 moins que Matthews doit avoir l&rsquo;approbation de Malakai Black. <\/p>\n\n\n\n<p>Matthews approuve.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur la rivalit\u00e9 entre Orange Cassidy et Jon Moxley.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Saraya et Ruby Soho vs Kris Statlander et Hikaru Shida<\/strong><\/p>\n\n\n\n<p>En fin de match, Angelo Parker arrive en ringside pour aider Soho \u00e0 se relever. Saraya voit ce qui se passe et elle est furieuse. Statlander veut faire une Clothesline \u00e0 Soho, mais Soho l&rsquo;\u00e9vite et elle frappe Parker par erreur. Shida en profite pour faire son Katana sur Saraya pour le compte de trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnantes : Kris Statlander et Hikaru Shida<\/em><\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; En coulisse, on retrouve Tony Schiavone avec&nbsp;<strong>MJF<\/strong> pour une entrevue sp\u00e9cial Full Gear.&nbsp;<\/p>\n\n\n\n<p>Schiavone demande pourquoi \u00e0 Full Gear il a d\u00e9cid\u00e9 d&rsquo;avoir deux matchs et sans Roderick Strong. MJF dit qu&rsquo;il sait qu&rsquo;il aura une t\u00e2che difficile en Pre-Show, malgr\u00e9 que les Gunns sont laids. Mais il fera tout pour gagner le match, il a promis \u00e0 Cole qu&rsquo;ils seraient toujours champions.<\/p>\n\n\n\n<p> Schiavone demande ses commentaires sur Jay White qui a vol\u00e9 le titre mondial. MJF dit qu&rsquo;il est frustr\u00e9. Le titre repr\u00e9sente tout pour lui. Lorsque White l&rsquo;a vol\u00e9, il a d\u00fb se rappeler pourquoi White l&rsquo;a fait. White est ins\u00e9cure, White a vol\u00e9 le titre afin d&rsquo;essayer de se prouver \u00e0 lui-m\u00eame. La mauvaise nouvelle est que l&rsquo;homme d\u00e9fini le titre et non le contraire. Alors \u00e0 Full Gear White va perdre car personne n&rsquo;est de niveau du diable. <\/p>\n\n\n\n<p>Schiavone dit que MJF sera le champion avec le plus long r\u00e8gne, un champion avec le plus de d\u00e9fenses et en plus un an depuis sa victoire du titre, qu&rsquo;est-ce que \u00e7a repr\u00e9sente pour lui ? MJF dit que c&rsquo;est \u00e9norme pour un enfant avec un probl\u00e8me mental d&rsquo;avoir cette place. Pour un juif d&rsquo;avoir cette place. Pour avoir r\u00e9ussi tout \u00e7a. Alors il va d\u00e9fier tout ce qui est devant lui pour r\u00e9aliser l&rsquo;exploit.<\/p>\n\n\n\n<p>Le show se termine ainsi.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2023\/11\/17\/aew-en-face-a-face-avec-smackdown-ce-soir-des-20h-est-2h-europe-programme-et-avant-gout\/\" target=\"_blank\">Pour voir Collision, cliquez ici<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"hkxmbrqVsx\"><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/11\/17\/aew-en-face-a-face-avec-smackdown-ce-soir-des-20h-est-2h-europe-programme-et-avant-gout\/\">Reprise Vid\u00e9o et Programme pour le AEW Collision et Rampage du 17 Novembre 2023!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Reprise Vid\u00e9o et Programme pour le AEW Collision et Rampage du 17 Novembre 2023!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2023\/11\/17\/aew-en-face-a-face-avec-smackdown-ce-soir-des-20h-est-2h-europe-programme-et-avant-gout\/embed\/#?secret=VIZGlmsrbq#?secret=hkxmbrqVsx\" data-secret=\"hkxmbrqVsx\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>AEW Collision Inglewood, Californie, 17 novembre 2023 Les commentateurs sont Kevin Kelly, Tony Schiavone et Nigel McGuinness. &#8211; Le AEW Collision exceptionnellement vendredi, d\u00e9marre avec les commentateurs qui nous souhaitent la bienvenue et on retrouve Tony Schiavone sur le ring. &#8211; Schiavone nous pr\u00e9sente&nbsp;Christian Cage&nbsp;qui arrive sur le ring avec Luchasaurus et Nick Wayne. Schiavone&#8230;<\/p>\n","protected":false},"author":4,"featured_media":92108,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,89,30,77,93,21,49,83],"tags":[],"ppma_author":[292],"class_list":["post-92107","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-collision","category-ex-wwe","category-hall-of-fame","category-nxt-ex-wwe","category-resultats","category-roh","category-wcw"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/92107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=92107"}],"version-history":[{"count":9,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/92107\/revisions"}],"predecessor-version":[{"id":92124,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/92107\/revisions\/92124"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/92108"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=92107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=92107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=92107"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=92107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}