{"id":91962,"date":"2023-11-15T12:50:58","date_gmt":"2023-11-15T17:50:58","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=91962"},"modified":"2023-11-15T12:51:02","modified_gmt":"2023-11-15T17:51:02","slug":"logan-paul-dit-quil-a-sauve-rey-mysterio-a-crown-jewel-mais-quil-a-aussi-failli-le-tuer","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/11\/15\/logan-paul-dit-quil-a-sauve-rey-mysterio-a-crown-jewel-mais-quil-a-aussi-failli-le-tuer\/","title":{"rendered":"Logan Paul dit qu\u2019il a sauv\u00e9 Rey Mysterio \u00e0 Crown Jewel mais qu\u2019il a aussi failli le tuer!"},"content":{"rendered":"\n<p>Logan Paul discute de son r\u00e9cent affrontement contre Rey Mysterio.<\/p>\n\n\n\n<p>Paul a battu la l\u00e9gende du lucha-libre \u00e0 Crown Jewel pour remporter le championnat des \u00c9tats-Unis, son premier titre depuis qu\u2019il a commenc\u00e9 \u00e0 travailler pour la WWE en 2021. \u00c0 un moment donn\u00e9 dans l\u2019affrontement, Mysterio a tent\u00e9 un Moonsault, qui semblait sur le point de tomber directement sur son cou. Heureusement, Paul a rattrap\u00e9 Mysterio et ils ont pu poursuivre le match sans aucun autre probl\u00e8me.<\/p>\n\n\n\n<p>Dans la derni\u00e8re \u00e9dition de son podcast Impaulsive, Paul dit qu\u2019il sera heureux de s\u2019attribuer le m\u00e9rite d\u2019avoir sauv\u00e9 Mysterio, mais admet que la raison pour laquelle le b\u00e2clage a failli se produire \u00e9tait due au fait qu\u2019il se tenait trop en arri\u00e8re.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Je vais dire la v\u00e9rit\u00e9 parce que j\u2019ai vu tous ces gros titres positifs. \u00ab Logan sauve Rey Mysterio. \u00bb La communaut\u00e9 mexicaine devient folle, ils me f\u00e9licitent, disent que je suis une sorte de h\u00e9ros. Je me dis : \u00ab Dang, je suis reconnu pour quelque chose de cool ? Je le prends. Ensuite, j\u2019ai regard\u00e9 le clip, apr\u00e8s avoir \u00e9valu\u00e9 ma performance, alors que je pense que j\u2019ai sauv\u00e9 Rey Mysterio. Je crois que j\u2019ai aussi failli tuer Rey Mysterio. Je pense que j\u2019\u00e9tais trop loin pour le d\u00e9m\u00e9nagement, et je pense qu\u2019il n\u2019a pas d\u00e9blay\u00e9 assez de terrain pour le d\u00e9m\u00e9nagement. <\/p>\n<\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>C\u2019est ce qui s\u2019est pass\u00e9. J\u2019\u00e9tais trop loin, il n\u2019a pas d\u00e9gag\u00e9 assez de terrain, nous avons tous les deux fait une erreur. Je devais l\u2019attraper, je devais l\u2019attraper. Je n\u2019allais pas ne pas l\u2019attraper. Honn\u00eatement, m\u00eame si j\u2019aime les gros titres et que j\u2019aime me faire gazer, je ne faisais que mon travail. J\u2019accepterai les louanges. Le plus dur, c\u2019est que quand je l\u2019ai attrap\u00e9, j\u2019\u00e9tais dans une position de genou d\u2019araign\u00e9e. J\u2019ai des genoux compromis, alors peut-\u00eatre qu\u2019ils auraient pu se casser.<\/p>\n<\/blockquote>\n\n\n\n<p>Dans un r\u00e9cent post sur Youtube, Paul a mentionn\u00e9 qu\u2019il adorerait d\u00e9fendre le championnat des \u00c9tats-Unis contre des Superstars comme Cody Rhodes et LA Knight. Vous pouvez lire \u00e0 ce sujet\u00a0ici, ou consulter son \u00e9pisode Impaulsive ci-dessous.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"MvJIsA3O4q\"><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/11\/14\/logan-paul-veut-cody-rhodes-la-knight-et-un-match-revanche-contre-roman-reigns\/\">Logan Paul veut Cody Rhodes, LA Knight et un match revanche contre Roman Reigns<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Logan Paul veut Cody Rhodes, LA Knight et un match revanche contre Roman Reigns\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2023\/11\/14\/logan-paul-veut-cody-rhodes-la-knight-et-un-match-revanche-contre-roman-reigns\/embed\/#?secret=eA2Joqz3bt#?secret=MvJIsA3O4q\" data-secret=\"MvJIsA3O4q\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Logan Paul discute de son r\u00e9cent affrontement contre Rey Mysterio. Paul a battu la l\u00e9gende du lucha-libre \u00e0 Crown Jewel pour remporter le championnat des \u00c9tats-Unis, son premier titre depuis qu\u2019il a commenc\u00e9 \u00e0 travailler pour la WWE en 2021. \u00c0 un moment donn\u00e9 dans l\u2019affrontement, Mysterio a tent\u00e9 un Moonsault, qui semblait sur le&#8230;<\/p>\n","protected":false},"author":665,"featured_media":91972,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[81,4,23],"tags":[],"ppma_author":[289],"class_list":["post-91962","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-crown-jewel","category-news","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/91962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=91962"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/91962\/revisions"}],"predecessor-version":[{"id":91973,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/91962\/revisions\/91973"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/91972"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=91962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=91962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=91962"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=91962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}