{"id":91558,"date":"2023-11-03T21:11:00","date_gmt":"2023-11-04T01:11:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=91558"},"modified":"2023-11-03T23:34:59","modified_gmt":"2023-11-04T03:34:59","slug":"deuxieme-heure-de-smackdown-82","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/11\/03\/deuxieme-heure-de-smackdown-82\/","title":{"rendered":"Deuxi\u00e8me Heure de Smackdown!"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/11\/03\/resultats-et-video-pour-le-wwe-friday-night-smackdown-du-3-novembre-2023\/\">Pour revenir \u00e0 la premi\u00e8re, cliquez ici.<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p>&#8211; Solo Sikoa arrive sur le ring avec Paul Heyman. Ce dernier se demande combien de personnes r\u00e9alisent que le Doctor of Thuganomics, John Cena, est sur sa fin. Ce n&rsquo;est pas de la fa\u00e7on que Paul Heyman voulait, ce n&rsquo;est ni de sa faute ni celle de Roman Reigns. John Cena revient \u00e0 la WWE et se bat face \u00e0 la Bloodline. On ne pense quand m\u00eame pas que la Bloodline ne va pas r\u00e9pondre ?<\/p>\n\n\n\n<p>Solo Sikoa a un \u00e9norme avenir \u00e0 la WWE, non pas juste en enforcer, mais aussi en Tribal Chief. Il faut des victimes pour y arriver et il n&rsquo;y a pas une plus grande victime que John Cena.\u00a0Solo Sikoa prend le micro et demande \u00e0 Paul Heyman pourquoi il perd \u00e0 son temps \u00e0 nous parler alors qu&rsquo;ils sont venus parler \u00e0 John Cena ? <\/p>\n\n\n\n<p>Le 16 fois champions du monde de la WWE fait son entr\u00e9e et se met face \u00e0 Solo Sikoa. Ce dernier dit \u00eatre \u00e9nerv\u00e9 de devoir attendre Crown Jewel pour affronter John Cena, mais il suit les ordres de Roman Reigns. On lui a dit de donner le micro \u00e0 Cena pour qu&rsquo;il puisse nous dire au revoir.<\/p>\n\n\n\n<p> Cena demande \u00e0 Solo Sikoa si c&rsquo;est tout ce qu&rsquo;il peut faire ? \u00c7a fait un an qu&rsquo;on attend de voir Sikoa parler et c&rsquo;est tout ce qu&rsquo;il a. Alors lui va r\u00e9pondre avec la moiti\u00e9 de sa voix en 90 secondes. John Cena dit \u00e0 Solo Sikoa qu&rsquo;on sait tous qu&rsquo;il a un travail ici seulement gr\u00e2ce \u00e0 son cousin. Sikoa pense \u00eatre un grand enforcer mais ce n&rsquo;est rien d&rsquo;autre qu&rsquo;une version de mauvaise qualit\u00e9 de Tazz. Voil\u00e0, \u00e7a fait environ 90 secondes. John Cena l\u00e2che le micro et s&rsquo;en va.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&#8211; En coulisse, on retrouve Damage CTRL. Nick Aldis arrive et les informe que Dakota Kai et Iyo Sky seront bannies du ringside pour le match de ce soir. <\/p>\n\n\n\n<p>Iyo Sky dit \u00e0 Bayley qu&rsquo;elle peut le faire.<\/p>\n\n\n\n<p>&#8211; Les Brawling Brutes font leur entr\u00e9e, suivis par Pretty Deadly mais ils se font attaquer par leurs adversaires du soir pendant leur entr\u00e9e.<\/p>\n\n\n\n<p style=\"font-size:25px\"><strong>Donnybrook Rules Match<\/strong><\/p>\n\n\n\n<p><strong>Pretty Deadly (Elton Prince &amp; Kit Wilson) vs Brawling Brutes (Butch &amp; Ridge Holland)<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin , Butch et Kit Wilson sont dans le coin mais Elton Prince envoie une bouteille sur Butch. Pretty Deadly lui fait ensuite son Spilled Milk \u00e0 travers une table pour l&#8217;emporter par tomb\u00e9.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnants : Pretty Deadly<\/em><\/p>\n\n\n\n<p>&#8211; En coulisse, Nick Aldis tombe sur Paul Heyman qui lui dit d&rsquo;avoir un bon staff m\u00e9dical pour Crown Jewel car LA Knight en aura besoin, \u00e7a sera la version la plus sauvage de Roman Reigns et on l&rsquo;a jamais vue.<\/p>\n\n\n\n<p>&#8211; C&rsquo;est l&rsquo;heure de la pes\u00e9e entre Rey Mysterio et Logan Paul avant leur match \u00e0 Crown Jewel. Nick Aldis pr\u00e9sente la pes\u00e9e et nous demande d&rsquo;accueillir Logan Paul puis Rey Mysterio. <\/p>\n\n\n\n<p>Paul monte en premier sur la balance, il p\u00e8se environ 97kg. Au tour de Rey Mysterio qui p\u00e8se environ 79kg. <\/p>\n\n\n\n<p>Nick Aldis leur demande de faire un face \u00e0 face. Logan Paul insulte Rey Mysterio qui lui met une gifle. Les officiels les s\u00e9parent.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&#8211; Les commentateurs pr\u00e9sentent\u00a0la carte de WWE Crown Jewel 2023.<\/p>\n\n\n\n<p>&#8211; La semaine prochaine \u00e0 SmackDown : Bobby Lashley affrontera Carlito.<\/p>\n\n\n\n<p style=\"font-size:25px\"><strong>Finale de la soir\u00e9e<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Bayley vs Bianca Belair<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du match, Bianca Belair porte Bayley pour lui faire un KOD mais Bayley arrive \u00e0 l&rsquo;\u00e9viter puis tente un roll up. Belair se rel\u00e8ve et Bayley attrape les cheveux de Belair qui arrive \u00e0 lui mettre un coup avec ses cheveux. Elle enchaine avec son KOD pour la victoire par tomb\u00e9.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnante : Bianca Belair<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le match, Bianca Belair c\u00e9l\u00e8bre et s&rsquo;approche de Bayley en ringside. Belair la porte puis lui fait un nouveau KOD \u00e0 travers la table des commentateurs. Le show se termine ainsi.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-center\" style=\"font-size:25px\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/11\/03\/avant-gout-pour-le-wwe-friday-night-smackdown-du-3-novembre-2023-dernier-show-avant-crown-jewel\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir Smackdown, cliquez ici.<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"VcEu4xXz4b\"><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/11\/03\/avant-gout-pour-le-wwe-friday-night-smackdown-du-3-novembre-2023-dernier-show-avant-crown-jewel\/\">Reprise Vid\u00e9o et Programme pour le WWE Friday Night Smackdown du 3 Novembre 2023! Dernier Show  Avant Crown Jewel!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Reprise Vid\u00e9o et Programme pour le WWE Friday Night Smackdown du 3 Novembre 2023! Dernier Show  Avant Crown Jewel!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2023\/11\/03\/avant-gout-pour-le-wwe-friday-night-smackdown-du-3-novembre-2023-dernier-show-avant-crown-jewel\/embed\/#?secret=5johL1wIzR#?secret=VcEu4xXz4b\" data-secret=\"VcEu4xXz4b\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>&#8211; Solo Sikoa arrive sur le ring avec Paul Heyman. Ce dernier se demande combien de personnes r\u00e9alisent que le Doctor of Thuganomics, John Cena, est sur sa fin. Ce n&rsquo;est pas de la fa\u00e7on que Paul Heyman voulait, ce n&rsquo;est ni de sa faute ni celle de Roman Reigns. John Cena revient \u00e0 la&#8230;<\/p>\n","protected":false},"author":609,"featured_media":91562,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"ppma_author":[295],"class_list":["post-91558","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-smackdown"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/91558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=91558"}],"version-history":[{"count":7,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/91558\/revisions"}],"predecessor-version":[{"id":91584,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/91558\/revisions\/91584"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/91562"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=91558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=91558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=91558"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=91558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}