{"id":90907,"date":"2023-10-13T20:23:00","date_gmt":"2023-10-14T00:23:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=90907"},"modified":"2023-10-17T12:06:23","modified_gmt":"2023-10-17T16:06:23","slug":"resultats-et-video-pour-le-wwe-friday-night-smackdown-du-13-octobre-2023","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/10\/13\/resultats-et-video-pour-le-wwe-friday-night-smackdown-du-13-octobre-2023\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le WWE Friday Night Smackdown du 13 Octobre 2023!"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/10\/13\/avant-gout-pour-le-wwe-friday-night-smackdown-du-vendredi-13-octobre-2023\/\">Pour voir Smackdown, cliquez ici.<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p><strong>WWE SmackDown Tulsa, Oklahoma, 13 octobre 2023<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Michael Cole, Corey Graves et Kevin Patrick.<\/p>\n\n\n\n<p>&#8211; Le WWE Friday Night SmackDown d\u00e9bute avec les commentateurs qui nous souhaitent la bienvenue pour la Season Premiere de SmackDown.&nbsp;<\/p>\n\n\n\n<p>&#8211; <strong>John Cena<\/strong>&nbsp;fait son entr\u00e9e et souhaite \u00e9galement la bienvenue mais il se fait interrompre par la musique de <strong>Roman Reigns<\/strong>&nbsp;qui fait son retour aux c\u00f4t\u00e9s de Paul Heyman et Solo Sikoa !<\/p>\n\n\n\n<p>La Bloodline fait face \u00e0 John Cena puis Roman Reigns demande \u00e0 Tulsa de le reconnaitre. La foule chante le nom de Cena et Roman Reigns leur dit qu&rsquo;ils chantent pour un l\u00e2che, il fait son retour car lui a pris une pause et en plus de \u00e7a, John Cena a eu l&rsquo;audace de laisser les gens l&rsquo;appeler le GOAT, c&rsquo;est lui le vrai GOAT !<\/p>\n\n\n\n<p>Roman Reigns invite John Cena \u00e0 partir sinon c&rsquo;est eux qui vont le faire partir. John Cena lui r\u00e9pond qu&rsquo;il n&rsquo;est pas l\u00e0 pour le d\u00e9fier, il est l\u00e0 pour le reconnaitre. Champion depuis 1 138 jours, c&rsquo;est le plus grand accomplissement de tous les temps.&nbsp;Il n&rsquo;est pas l\u00e0 pour le d\u00e9fier ce soir car il n&rsquo;a rien fait pour le m\u00e9riter, mais il connait quelqu&rsquo;un qui le m\u00e9rite&#8230; La musique de LA Knight retentit et fait son entr\u00e9e avant de s&rsquo;installer face \u00e0 Roman Reigns.<\/p>\n\n\n\n<p>LA Knight demande si c&rsquo;est bien Roman Reigns ?&nbsp;<strong>YEAH !<\/strong>&nbsp;Le Head of the Table ?&nbsp;<strong>YEAH !<\/strong>&nbsp;Le Tribal Chief ?&nbsp;<strong>YEAH<\/strong>&nbsp;<strong>!<\/strong>&nbsp;Le champion qui d\u00e9fend sa ceinture ?&nbsp;<strong>Nah nah<\/strong>&nbsp;<strong>!<\/strong>&nbsp;Oh, il a oubli\u00e9 de se pr\u00e9senter, pas mal de choses ont chang\u00e9 depuis la derni\u00e8re fois que Reigns \u00e9tait l\u00e0. Il demande \u00e0 la foule de lui dire \u00e0 qui appartient le game maintenant :&nbsp;<strong>LA KNIGHT<\/strong>&nbsp;!<\/p>\n\n\n\n<p>Roman Reigns lui dit que la foule sait maintenant prononcer son nom. Lui est champion depuis plus de 1 100 jours, il a accompli plus de choses que tout ce que LA Knight peut r\u00eaver accomplir. Pour qui LA Knight se prend pour se tenir sur son ring ? LA Knight lui r\u00e9pond qu&rsquo;il est la star montante la plus rapide de l&rsquo;histoire de SmackDown&#8230; Jimmy Uso attaque LA Knight par derri\u00e8re mais ce dernier arrive \u00e0 l&rsquo;envoyer par dessus la troisi\u00e8me corde !<\/p>\n\n\n\n<p>Roman Reigns, Solo Sikoa et Paul Heyman quittent le ring puis Reigns dit \u00e0 Sikoa de s&rsquo;occuper de LA Knight. Solo Sikoa monte sur le tablier du ring et invite LA Knight \u00e0 l&rsquo;affronter ce soir, LA Knight accepte.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p><strong>Pretty Deadly (Elton Prince &amp; Kit Wilson) vs Brawling Brutes (Butch &amp; Ridge Holland)<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin, Elton Prince fait semblant d&rsquo;\u00eatre bless\u00e9 et l&rsquo;arbitre demande \u00e0 Ridge Holland de reculer. Kit Wilson en profite pour mettre un Kick sur Holland puis Prince enchaine avec un roll up pour l&#8217;emporter.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnants : Pretty Deadly<\/em><\/p>\n\n\n\n<p>&#8211; On revoit la victoire de la LWO face \u00e0 Bobby Lashley et les Street Profits avec le retour de Carlito. En coulisse, Kayla Braxton est avec Carlito qui dit n&rsquo;avoir qu&rsquo;un mot pour d\u00e9crire son retour \u00e0 la WWE: c&rsquo;est cool. Bobby Lashley le rejoint et lui dit que la derni\u00e8re fois qu&rsquo;il l&rsquo;avait vu, Carlito se faisait battre \u00e0 SmackDown, il lui souhaite la bienvenue dans son show. Carlito lui demande ce qu&rsquo;il pense si son premier match \u00e0 SmackDown depuis son retour se faisait contre Bobby Lashley.<\/p>\n\n\n\n<p>Les Street Profits attaquent Carlito par derri\u00e8re, les officiels arrivent pour mettre fin \u00e0 l&rsquo;attaque. Apr\u00e8s la pause publicitaire, la LWO a rejoint Carlito pour v\u00e9rifier qu&rsquo;il aille bien. Bayley arrive et se prend la t\u00eate avec Zelina Vega. Adam Pearce les arr\u00eate et leur dit d&rsquo;aller s&rsquo;affronter maintenant.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p><strong>Bayley&nbsp;<em>accompagn\u00e9e de Dakota Kai et Iyo Sky<\/em>&nbsp;vs Zelina Vega<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin,  Bayley fait son Rose Plant sur Zelina Vega suivi du tomb\u00e9 pour gagner.<\/p>\n\n\n\n<p><strong>Gagnante : Bayley<\/strong><\/p>\n\n\n\n<p> Apr\u00e8s le match, Damage CTRL continue \u00e0 attaquer Zelina Vega mais Charlotte Flair arrive pour faire fuir le clan.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-center\" style=\"font-size:25px\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/?p=90908\">Pour la suite de Smackdown, cliquez ici.<\/a><\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>WWE SmackDown Tulsa, Oklahoma, 13 octobre 2023 Les commentateurs sont Michael Cole, Corey Graves et Kevin Patrick. &#8211; Le WWE Friday Night SmackDown d\u00e9bute avec les commentateurs qui nous souhaitent la bienvenue pour la Season Premiere de SmackDown.&nbsp; &#8211; John Cena&nbsp;fait son entr\u00e9e et souhaite \u00e9galement la bienvenue mais il se fait interrompre par la&#8230;<\/p>\n","protected":false},"author":609,"featured_media":90913,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,36,23],"tags":[],"ppma_author":[295],"class_list":["post-90907","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-resultats","category-smackdown","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/90907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=90907"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/90907\/revisions"}],"predecessor-version":[{"id":91025,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/90907\/revisions\/91025"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/90913"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=90907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=90907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=90907"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=90907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}