{"id":90055,"date":"2023-09-22T12:18:27","date_gmt":"2023-09-22T16:18:27","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=90055"},"modified":"2023-09-22T12:19:16","modified_gmt":"2023-09-22T16:19:16","slug":"la-raison-de-plusieurs-liberations-de-superstars-apres-la-fusion-de-la-wwe-avec-tko","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/09\/22\/la-raison-de-plusieurs-liberations-de-superstars-apres-la-fusion-de-la-wwe-avec-tko\/","title":{"rendered":"La raison de plusieurs lib\u00e9rations de Superstars apr\u00e8s la fusion de la WWE avec TKO!"},"content":{"rendered":"\n<p>L&rsquo;onde de choc a d\u00fbt se faire ressentir assez pour que vous sachiez que La WWE a pris la d\u00e9cision de licencier 22 Superstars le 21 septembre 2023.<\/p>\n\n\n\n<p> Des SuperStars hommes et femmes du roster principal qui \u00e9taient \u00e0 la WWE depuis de nombreuses ann\u00e9es et d&rsquo;autres qui venaient de d\u00e9buter du c\u00f4t\u00e9 de NXT.<\/p>\n\n\n\n<p>Une nouvelle qui \u00e9tait tr\u00e8s surprenante puisqu&rsquo;en avril 2023, suite \u00e0 l&rsquo;annonce de l&rsquo;achat du groupe Endeavor pour former le groupe TKO, Nick Khan, pr\u00e9sident WWE avait confirm\u00e9 que la WWE allait\u00a0exclusivement proc\u00e9der \u00e0 des licenciements au niveau de son si\u00e8ge social. <\/p>\n\n\n\n<p>Des licenciements pour l&rsquo;organisation puisqu&rsquo;une seule \u00e9quipe administrative est n\u00e9cessaire pour g\u00e9rer la WWE et la UFC sous le toit du groupe TKO et non deux \u00e9quipes. On apprenait que\u00a0plus de 100 employ\u00e9s avaient \u00e9t\u00e9 licenci\u00e9s\u00a0la semaine derni\u00e8re pour cet effet.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Il semble bien que  la WWE a chang\u00e9 d&rsquo;id\u00e9e sur le sujet de la protection de ses WWE Superstars face \u00e0 la fusion, ou bien Nick Khan avait dit un petit mensonge \u00e0 l&rsquo;\u00e9poque. <\/p>\n\n\n\n<p>Le Wrestling Observer a fait le point sur le sujet et pr\u00e9cise que TKO a fait une \u00e9valuation du salaire versus le retour sur investissement. Ce qui fait en sorte que des catcheurs qui sont peu ou mal utilis\u00e9 car ils sont pay\u00e9 faisant parti du roster principal mais performe \u00e0 NXT se sont retrouv\u00e9s \u00e0 la porte.<\/p>\n\n\n\n<p>Conclusion, les r\u00e9cents licenciements ont \u00e9t\u00e9 fait sur une analyse du \u00a0\u00bbtemps impliqu\u00e9 versus le salaire versus le retour sur investissement\u00a0\u00bb. <\/p>\n\n\n\n<p>Des noms comme Dolph Ziggler, Shelton Benjamin, Dana Brooke, Mustafa Ali et autres qui coutait plus cher pour la  WWE \u00e0 comparer au temps sur les \u00e9crans ou bien leur importance dans les storylines, et aussi en vente de marchandises.<\/p>\n\n\n\n<p>Ceux qui \u00e9taient \u00e0 NXT pourrait se voir offrir une offre moindre d&rsquo;ici quelques mois car cela c&rsquo;est d\u00e9j\u00e0 vu dans le pass\u00e9 pour r\u00e9ajuster leur salaire \u00e0 la baisse. Mais il faudra voir s&rsquo;ils vont pr\u00e9f\u00e9rer faire le saut avec Tony Khan pour un plus gros montant ou sauter \u00e0 l&rsquo;ancienne TNA et avoir un iMPACT sur leur carri\u00e8re.<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"4A9Z2qGK8y\"><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/09\/21\/la-wwe-fait-le-menage-plusieurs-superstars-liberees-de-leur-contrat-shelton-benjamin-dolph-ziggler-elias-dana-brooke-mustafa-ali-emma-et-plusieurs-autres\/\">La WWE fait le m\u00e9nage! Plusieurs SuperStars Lib\u00e9r\u00e9es de leur Contrat! Shelton Benjamin, Dolph Ziggler, Elias, Dana Brooke, Mustafa Ali, Emma et Plusieurs Autres!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0La WWE fait le m\u00e9nage! Plusieurs SuperStars Lib\u00e9r\u00e9es de leur Contrat! Shelton Benjamin, Dolph Ziggler, Elias, Dana Brooke, Mustafa Ali, Emma et Plusieurs Autres!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2023\/09\/21\/la-wwe-fait-le-menage-plusieurs-superstars-liberees-de-leur-contrat-shelton-benjamin-dolph-ziggler-elias-dana-brooke-mustafa-ali-emma-et-plusieurs-autres\/embed\/#?secret=P4RxtztvrN#?secret=4A9Z2qGK8y\" data-secret=\"4A9Z2qGK8y\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>L&rsquo;onde de choc a d\u00fbt se faire ressentir assez pour que vous sachiez que La WWE a pris la d\u00e9cision de licencier 22 Superstars le 21 septembre 2023. Des SuperStars hommes et femmes du roster principal qui \u00e9taient \u00e0 la WWE depuis de nombreuses ann\u00e9es et d&rsquo;autres qui venaient de d\u00e9buter du c\u00f4t\u00e9 de NXT&#8230;.<\/p>\n","protected":false},"author":4,"featured_media":90057,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,22,4,23],"tags":[],"ppma_author":[292],"class_list":["post-90055","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ex-wwe","category-indy","category-news","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/90055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=90055"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/90055\/revisions"}],"predecessor-version":[{"id":90056,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/90055\/revisions\/90056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/90057"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=90055"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=90055"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=90055"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=90055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}