{"id":898,"date":"2019-03-25T03:40:07","date_gmt":"2019-03-25T03:40:07","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=898"},"modified":"2019-03-25T03:40:10","modified_gmt":"2019-03-25T03:40:10","slug":"et-si-seth-rollins-avait-de-laide-de-la-ufc-pour-battre-brock-lesnar","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2019\/03\/25\/et-si-seth-rollins-avait-de-laide-de-la-ufc-pour-battre-brock-lesnar\/","title":{"rendered":"Et si, Seth Rollins avait de l&rsquo;Aide de la UFC pour Battre Brock Lesnar&#8230;"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Dans cet Express, d\u00e9couvrez ce qui a lanc\u00e9 la rumeur que Rollins pourrait recevoir de l&rsquo;aide pour son match face \u00e0 Brock Lesnar lors de WrestleMania, et bien plus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-C&rsquo;est dans moins de deux semaines que le champion Universal, Brock Lesnar fera face \u00e0 Seth Rollins afin de d\u00e9fendre son titre \u00e0 WrestleMania 35. Un match qui s\u2019annonce physique pour les deux hommes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il y a quelques semaines, il .\u00e9tait rapport\u00e9 que le combattant de l\u2019UFC Daniel Cormier s\u2019\u00e9tait moqu\u00e9 de la carri\u00e8re \u00e0 la WWE du Beast dans l\u2019optique de provoquer un face \u00e0 face entre les deux hommes lorsque Lesnar d\u00e9cidera enfin de revenir dans l\u2019Octogone.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hors, il y a quelques heures, Cormier a remis une couche promettant l\u2019enfer \u00e0 Lesnar et annon\u00e7ant que s\u2019il ne venait pas \u00e0 lui c\u2019est lui qui viendrait \u00e0 sa rencontre, notamment lors de WrestleMania 35, en intervenant directement dans le combat avec Rollins.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans une interview Cormier d\u00e9clare :<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>\u00ab Je n\u2019ai pas encore de combat pr\u00e9vu, mais j\u2019ai les yeux riv\u00e9s sur Brock Lesnar. J\u2019irai peut-\u00eatre \u00e0 WrestleMania, et j\u2019irai lui co\u00fbter son titre l\u00e0-bas pour qu\u2019il puisse se d\u00e9p\u00eacher d\u2019aller \u00e0 l\u2019UFC pour le battre l\u00e0 bas aussi. \u00bb<\/code><\/pre>\n\n\n\n<p class=\"wp-block-paragraph\">Hypoth\u00e8se \u00e9tonnante, mais pas si  farfelue. En effet, la WWE et l\u2019UFC se sont de plus en plus rapproch\u00e9s  depuis quelques ann\u00e9es. S\u2019\u00e9changeant des talents. Laisser entrevoir un match  Cormier vs. Lesnar \u00e0 WrestleMania serait un coup de buzz incroyable pour les deux compagnies. Le  match retour qui aurait alors lieu \u00e0 l\u2019UFC se d\u00e9roulerait en ao\u00fbt  d\u2019apr\u00e8s les derni\u00e8res informations venant de Dana White.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Notons \u00e9galement que Daniel Cormier est  WWE compatible. Fan de lutte, la star de l\u2019UFC a \u00e9t\u00e9 approch\u00e9e par FOX pour tenir les commentaires de SmackDown \u00e0 la fin de l\u2019ann\u00e9e. Il a m\u00eame pass\u00e9 des essais<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enfin, tandis que Conor McGregor\n est aussi sur les tablettes de la compagnie de Stamford, dans une id\u00e9e \nd\u2019accompagnant de Becky Lynch sur la plus grande sc\u00e8ne du monde, Cormier\n ne serait finalement que le joyau de la couronne.<\/p>\n\n<center><blockquote class=\"twitter-tweet\" data-lang=\"fr\"><p lang=\"en\" dir=\"ltr\">When <a href=\"https:\/\/twitter.com\/dc_mma?ref_src=twsrc%5Etfw\">@dc_mma<\/a> gets his date with Brock Lesnar, <a href=\"https:\/\/twitter.com\/arielhelwani?ref_src=twsrc%5Etfw\">@arielhelwani<\/a> WILL NOT be the first to know (via <a href=\"https:\/\/twitter.com\/SportsCenter?ref_src=twsrc%5Etfw\">@SportsCenter<\/a>) <a href=\"https:\/\/t.co\/z2iJR1OVZY\">pic.twitter.com\/z2iJR1OVZY<\/a><\/p>&mdash; ESPN MMA (@espnmma) <a href=\"https:\/\/twitter.com\/espnmma\/status\/1109695685845270528?ref_src=twsrc%5Etfw\">24 mars 2019<\/a><\/blockquote>\n<script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/center>\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Dans cet Express, d\u00e9couvrez ce qui a lanc\u00e9 la rumeur que Rollins pourrait recevoir de l&rsquo;aide pour son match face \u00e0 Brock Lesnar lors de WrestleMania, et bien plus. -C&rsquo;est dans moins de deux semaines que le champion Universal, Brock Lesnar fera face \u00e0 Seth Rollins afin de d\u00e9fendre son titre \u00e0 WrestleMania 35. Un&#8230;<\/p>\n","protected":false},"author":4,"featured_media":899,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"ppma_author":[292],"class_list":["post-898","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","author_category":"","first_name":"Jean","last_name":"Vinnier","user_url":"https:\/\/www.facebook.com\/jean.vinnier","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=898"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/898\/revisions"}],"predecessor-version":[{"id":900,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/898\/revisions\/900"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/899"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=898"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}