{"id":89737,"date":"2023-09-14T15:33:00","date_gmt":"2023-09-14T19:33:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=89737"},"modified":"2023-09-14T20:40:39","modified_gmt":"2023-09-15T00:40:39","slug":"jade-cargill-pourrait-en-avoir-fini-avec-la-aew-et-serait-en-voie-de-cross-the-line-a-la-wwe","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/09\/14\/jade-cargill-pourrait-en-avoir-fini-avec-la-aew-et-serait-en-voie-de-cross-the-line-a-la-wwe\/","title":{"rendered":"Jade Cargill pourrait en avoir fini avec la AEW et serait en voie de Cross The Line \u00e0 la WWE!"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>Comme vous le savez <strong>Jade Cardill<\/strong> a r\u00e9cemment effectu\u00e9 son retour et aura son rematch face \u00e0 la championne TBS <strong>Kris Statlander<\/strong> ce vendredi 15 septembre lors de Rampage. Comme ce f\u00fbt enregistr\u00e9 mercredi, allez \u00e0 la fin pour voir le spoiler. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Selon les informations de notre selecte source,\u00a0Jade Cargill devrait quitter la AEW \u00e0 la fin de son contrat, son match \u00e0 Rampage cette semaine pourrait \u00eatre sa derni\u00e8re apparition dans la compagnie de Tony Khan.<\/p>\n\n\n\n<p>Des sources au sein de l&rsquo;\u00e9lite et de la WWE pensent que\u00a0Jade Cargill va rejoindre la WWE\u00a0apr\u00e8s son aventure \u00e0 la concurrence. <\/p>\n\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n\n<p>Par contre Fightful affirme ne pas avoir \u00e9t\u00e9 inform\u00e9 qu&rsquo;une offre avait \u00e9t\u00e9 faite \u00e0 Jade Cargill et ne connait pas la dur\u00e9e restante de son contrat avec la Al Elite Wrestling. Et la WWE ne peut pas n\u00e9gocier avec elle d&rsquo;ici l\u00e0. Mais bon le maraudage existe depuis que la premi\u00e8re ligue de sport professionnel existe. <\/p>\n\n\n\n<p>Jade Cargill avait pass\u00e9 un tryout de la WWE en 2019 mais elle avait pr\u00e9f\u00e9r\u00e9 rejoindre la AEW. Jade Cargill a d\u00e9but\u00e9 avec l&rsquo;\u00e9lite en novembre 2020 et elle a commenc\u00e9 \u00e0 ce moment-l\u00e0 une s\u00e9rie de victoires sans perdre le moindre match jusqu&rsquo;\u00e0 Double or Nothing 2023 o\u00f9 Kris Statlander a r\u00e9ussi \u00e0 lui prendre la ceinture TBS. Elle est revenue la semaine derni\u00e8re \u00e0 Collision et a demand\u00e9 un rematch pour son titre que d\u00e9tient Kris Statlander.<\/p>\n\n\n\n<p>Pour savoir le r\u00e9sultats, le spoiler ce trouve sous la publicit\u00e9 ci-dessous:<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p class=\"has-text-align-center\" style=\"font-size:25px\"><strong>SPOILER ALERTE<\/strong><\/p>\n\n\n\n<p>Et donc celle qui d\u00e9tient la plus longue streak de la All Elite Wrestling Jade Cargill avec <strong>508\u00a0<\/strong>jours de championnat TBS, a perdu face \u00e0 la championne Kris Statlander. Ce qui donne donc un push \u00e0 la championne. Ce pourrait donc \u00eatre l\u00e0 dessus que Cargill finisse avec la AEW. <\/p>\n\n\n\n<p>Nous en saurons plus dans la semaine \u00e0 venir. Pour voir son retour la semaine derni\u00e8re visiter le AEW Collision ci-dessous.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Comme vous le savez Jade Cardill a r\u00e9cemment effectu\u00e9 son retour et aura son rematch face \u00e0 la championne TBS Kris Statlander ce vendredi 15 septembre lors de Rampage. Comme ce f\u00fbt enregistr\u00e9 mercredi, allez \u00e0 la fin pour voir le spoiler. Selon les informations de notre selecte source,\u00a0Jade Cargill devrait quitter la AEW \u00e0&#8230;<\/p>\n","protected":false},"author":4,"featured_media":89739,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,54,4,23],"tags":[],"ppma_author":[292],"class_list":["post-89737","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-double-or-nothing","category-news","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/89737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=89737"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/89737\/revisions"}],"predecessor-version":[{"id":89741,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/89737\/revisions\/89741"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/89739"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=89737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=89737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=89737"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=89737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}