{"id":88466,"date":"2023-08-26T00:42:00","date_gmt":"2023-08-26T04:42:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=88466"},"modified":"2023-08-27T11:37:10","modified_gmt":"2023-08-27T15:37:10","slug":"austin-theory-sest-bien-calme-depuis-sa-victoire-a-wrestlemania-39-la-longevite-de-rey-mysterio-et-plus","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/08\/26\/austin-theory-sest-bien-calme-depuis-sa-victoire-a-wrestlemania-39-la-longevite-de-rey-mysterio-et-plus\/","title":{"rendered":"Austin Theory s\u2019est bien calm\u00e9 depuis sa victoire \u00e0 WrestleMania 39! La long\u00e9vit\u00e9 de Rey Mysterio, et plus!"},"content":{"rendered":"\n<p>Booker T a donn\u00e9 son avis sur divers sujets dans son dernier\u00a0podcast Hall Of Fame.<\/p>\n\n\n\n<p>Au cours de celle-ci, le WWE Hall Of Famer a parl\u00e9 de Rey Mysterio battant Austin Theory pour le titre des \u00c9tats-Unis et plus encore. Voici les faits saillants :<\/p>\n\n\n\n<p><strong>Sur Rey Mysterio remportant le titre des \u00c9tats-Unis:<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab\u00a0Tu sais quoi, mec? Je pense \u00e0 Rey. Je l\u2019ai publi\u00e9. Il. Vous savez, j\u2019ai pens\u00e9 que cela s\u2019est concr\u00e9tis\u00e9 parce que je l\u2019ai entendu parler. Non, j\u2019ai vu que je lisais quelque chose que Rey voulait gagner un championnat de plus avant de prendre sa retraite. Je ne sais pas si c\u2019\u00e9tait le titre mondial ou quelque chose comme \u00e7a, mais je sais qu\u2019il voulait gagner un championnat de plus. Et ils ont probablement dit, eh bien, Ray, nous ne pouvons pas y aller, mais nous y allons, nous allons vous en lancer un, vous savez et vous laisser partir au coucher du soleil. Mais maintenant, mec, je suis heureux pour Ray Mysterio, mec. Juste, vous savez, Rey est l\u00e0 pour le faire, mec. Il le fait depuis longtemps pour des gars comme moi. Et de voir Rey encore l\u00e0-bas le faire, \u00e7a me fait sacr\u00e9ment du bien. En plus de pouvoir le faire avec son fils Dominik Quelle affaire g\u00e9niale, g\u00e9niale d\u2019accomplir quelque chose comme \u00e7a. \u00bb<\/p>\n<\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p><strong>Sur un manque de pouss\u00e9e pour Austin Theory apr\u00e8s sa victoire sur John Cena:<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab&nbsp;Je veux dire, il s\u2019est refroidi, non? Je veux dire, il s\u2019est beaucoup calm\u00e9, mec. Et c\u2019est parfois, mec, tu dois savoir comment changer de vitesse, non? Parfois, vous savez, vous pouvez aller l\u00e0-bas et courir le m\u00eame shtick chaque semaine, chaque semaine, chaque semaine, et les gens peuvent, vous savez, vraiment obtenir, vous savez, je ne dirais pas \u00e9limin\u00e9 progressivement, mais ils peuvent syntoniser quelqu\u2019un d\u2019autre qui leur donne ce quelque chose qu\u2019ils recherchent. Et en ce moment, LA Knight lui donne le sentiment qu\u2019ils veulent. Vous voyez ce que je veux dire? Avec ce gamin. Je dis sans th\u00e9orie, je dis. Quand vous \u00eates gu\u00e9ri, vous devez gu\u00e9rir. Ils doivent vous m\u00e9priser. Et parfois, vous savez, pensez que les gu\u00e9risseurs ne franchissent pas cette ligne ces jours-ci. Je regarde Dominik Mysterio. C\u2019est la chaleur que je recherche. Voil\u00e0. C\u2019est ce que je recherche. J\u2019ai besoin que les fans ne veuillent pas que vous puissiez dire un mot parce qu\u2019ils vous m\u00e9prisent tellement. Vous savez et ne pensez pas, vous savez, cette salade \u00e9tait, \u00e0 peu pr\u00e8s fixe, parfaite pour que ce gamin puisse aller l\u00e0-bas et r\u00e9ussir. Ce gamin a fait une grande partie du travail par lui-m\u00eame jusqu\u2019\u00e0 pr\u00e9sent. Et c\u2019est en grande partie la performance sur le ring. Mec, mec, c\u2019est comme le vent. Vous pouvez le sentir, mais vous ne pouvez pas le toucher. Et je n\u2019ai pas le temps de l\u2019expliquer. Je ne. Je suis s\u00e9rieux. Je ne. Mais c\u2019est une grande partie du probl\u00e8me. \u00bb<\/p>\n<\/blockquote>\n\n\n\n<center><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/yIoPRgoRSIc?si=mtfhrxq7E0C0CLIC\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/center>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Booker T a donn\u00e9 son avis sur divers sujets dans son dernier\u00a0podcast Hall Of Fame. Au cours de celle-ci, le WWE Hall Of Famer a parl\u00e9 de Rey Mysterio battant Austin Theory pour le titre des \u00c9tats-Unis et plus encore. Voici les faits saillants : Sur Rey Mysterio remportant le titre des \u00c9tats-Unis: \u00ab\u00a0Tu sais&#8230;<\/p>\n","protected":false},"author":665,"featured_media":88622,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[77,4,85,83,23],"tags":[],"ppma_author":[289],"class_list":["post-88466","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hall-of-fame","category-news","category-nxt","category-wcw","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/88466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=88466"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/88466\/revisions"}],"predecessor-version":[{"id":88623,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/88466\/revisions\/88623"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/88622"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=88466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=88466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=88466"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=88466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}