{"id":88088,"date":"2023-08-14T22:39:01","date_gmt":"2023-08-15T02:39:01","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=88088"},"modified":"2023-08-14T22:39:04","modified_gmt":"2023-08-15T02:39:04","slug":"deuxieme-heure-de-raw-90","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/08\/14\/deuxieme-heure-de-raw-90\/","title":{"rendered":"Deuxi\u00e8me Heure de RAW"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/?p=88089\">Pour revenir \u00e0 la 1\u00e8re heure, cliquez ici.<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Gunther vs Otis<\/strong><\/p>\n\n\n\n<p>En fin de match, Otis se lance en Caterpillar, mais Gunther le bloque avec un coup de pied. Gunther enchaine avec sa Powerbomb pour le compte de trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnant : Gunther<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, Gable monte sur le ring et fait sa German Suplex sur Gunther pour le chasser du ring !<\/p>\n\n\n\n<p>&#8211; En coulisse, Damian Priest demande \u00e0 Finn Balor pourquoi il a envoy\u00e9 son ami. Finn Balor lui dit de se calmer. Rhea Ripley dit que tout le monde veut les voir imploser. Ils ont tellement accompli depuis leur alliance, ils perdent leur concentration. <\/p>\n\n\n\n<p>JD McDonagh arrive pour parler \u00e0 Balor, mais Priest se f\u00e2che, Balor dit \u00e0 McDonagh d&rsquo;attendre plus loin. Balor dit que ce soir il va battre Cody Rhodes au nom du Judgment Day et ils vont faire \u00e7a ensemble.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&#8211; De retour, on pr\u00e9sente une vid\u00e9o de\u00a0vendredi dernier \u00e0 SmackDown\u00a0avec Jey Uso qui annonce son d\u00e9part de la Bloodline et de la WWE.<\/p>\n\n\n\n<p>&#8211; En coulisse, dans une vid\u00e9o plus t\u00f4t aujourd&rsquo;hui, Jackie Redmond est avec Drew McIntyre pour savoir ce qui l&rsquo;attend pour la suite. McIntyre allait r\u00e9pondre, mais Matt Riddle arrive. <\/p>\n\n\n\n<p>Riddle dit que \u00e7a prend toujours un Bro pour aider lorsqu&rsquo;on est au plus bas. Quoi de mieux que d&rsquo;avoir un nouveau partenaire ? Ce soir ils pourraient affronter les Viking Raiders. Ils pourraient se nommer les Glas-Bro ou autre. <\/p>\n\n\n\n<p>McIntyre dit que si Riddle trouve personne, il va le consid\u00e9rer.<\/p>\n\n\n\n<p>&#8211; De retour, on pr\u00e9sente une vid\u00e9o sur Indi Hartwell. Hartwell qui aura une chance contre Ripley ce soir.<\/p>\n\n\n\n<p><strong>Matt Riddle et Drew McIntyre vs Viking Raiders\u00a0<em>(Ivar et Erik) acc de Valhalla<\/em><\/strong><\/p>\n\n\n\n<p>En fin de match, Erik frappe Riddle en ringside et remonte sur le ring. McIntyre \u00e9vite un coup et fait son Claymore sur Erik pour le compte de trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnants : Matt Riddle et Drew McIntyre<\/em><\/p>\n\n\n\n<p>&#8211; En coulisse, Indi Hartwell se pr\u00e9pare pour son match. Raquel Gonzalez arrive et dit qu&rsquo;elle n&rsquo;est toujours pas lib\u00e9r\u00e9e par le m\u00e9decin, mais ce soir c&rsquo;est la chance de Indi pour montrer \u00e0 la WWE Universe ce qu&rsquo;elle peut faire.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&#8211; De retour, en coulisse,\u00a0<strong>Matt Riddle et Drew McIntyre<\/strong>\u00a0discutent ensemble. Riddle est bien fier du match disant qu&rsquo;ils vont surement gagner les titres par \u00e9quipe. <\/p>\n\n\n\n<p>The New Day arrive. Xavier Woods demande s&rsquo;il entend vraiment cette d\u00e9claration pendant l&rsquo;anniversaire de Kofi ? <\/p>\n\n\n\n<p>Riddle lui souhaite un joyeux anniversaire. <\/p>\n\n\n\n<p>Kofi dit qu&rsquo;ils ne sont pas une \u00e9quipe, ni des amis, ils ne m\u00e9ritent pas une chance pour les titres. Woods dit qu&rsquo;ils quittent et la division perd la t\u00eate. Les Street Profits se prennent pour Benjamin et Alexander.\u00a0Kofi dit que la semaine prochaine ils pourraient s&rsquo;affronter afin de voir quelle \u00e9quipe m\u00e9rite sa chance pour les titres. <\/p>\n\n\n\n<p>Riddle dit que le challenge est accept\u00e9\u00a0et McIntyre en revient pas!<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Rhea Ripley\u00a0<em>acc de Dominik Mysterio<\/em>\u00a0vs Indi Hartwell\u00a0<em>acc  de Candice LeRae<\/em><\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Ripley r\u00e9siste \u00e0 un compte rapide de Hartwell et lui fait son Riptide pour le compte de trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnante : Rhea Ripley<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, Candice LeRae entre sur le ring pour attaquer Ripley et prot\u00e9ger Indi. Candice et Indi donnent quelques coups sur Ripley et quittent le ring.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o de l&rsquo;attaque de Nakamura sur Rollins lundi dernier \u00e0 RAW.<\/p>\n\n\n\n<p>&#8211;\u00a0<strong>Shinsuke Nakamura<\/strong>\u00a0arrive sur le ring et on quitte pour la pause. <\/p>\n\n\n\n<p class=\"has-text-align-center\" style=\"font-size:25px\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/?p=88087\">Pour la suite de RAW, cliquez ici<\/a><\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Gunther vs Otis En fin de match, Otis se lance en Caterpillar, mais Gunther le bloque avec un coup de pied. Gunther enchaine avec sa Powerbomb pour le compte de trois. Gagnant : Gunther Apr\u00e8s le combat, Gable monte sur le ring et fait sa German Suplex sur Gunther pour le chasser du ring !&#8230;<\/p>\n","protected":false},"author":4,"featured_media":88099,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43],"tags":[],"ppma_author":[292],"class_list":["post-88088","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-raw-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/88088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=88088"}],"version-history":[{"count":6,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/88088\/revisions"}],"predecessor-version":[{"id":88118,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/88088\/revisions\/88118"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/88099"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=88088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=88088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=88088"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=88088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}