{"id":87992,"date":"2023-08-12T14:34:47","date_gmt":"2023-08-12T18:34:47","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=87992"},"modified":"2023-08-12T14:34:49","modified_gmt":"2023-08-12T18:34:49","slug":"jey-uso-deplace-dans-la-section-des-anciens-de-la-wwe","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/08\/12\/jey-uso-deplace-dans-la-section-des-anciens-de-la-wwe\/","title":{"rendered":"Jey Uso d\u00e9plac\u00e9 dans la section des anciens de la WWE!"},"content":{"rendered":"\n<p>Vendredi soir dernier \u00e0 la fin de SmackDown, Jey Uso a refus\u00e9 de pardonner son fr\u00e8re en lui mettant un Superkick en pleine tronche avant de prononcer les mots suivants : <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab\u00a0Je me tire  de la Bloodline, je tire  casse de SmackDown, je me tire de la WWE !\u00a0\u00bb<\/p>\n<\/blockquote>\n\n\n\n<p>La WWE qui met le paquet pour garder le Kayfabe dans l&rsquo;histoire qui entoure la Bloodline puisque le profil de Jey Uso a \u00e9t\u00e9 d\u00e9plac\u00e9 sur le site officiel de la compagnie dans la section des anciens.<\/p>\n\n\n\n<p>\u00a0Il est donc pass\u00e9 des catcheurs actifs \u00e0 la section Alumni, o\u00f9 se trouvent 99% personnes qui ne sont plus aujourd&rsquo;hui du c\u00f4t\u00e9 de la WWE. 99% car il y a le 1% que Vince a refuser de voir l\u00e0. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"758\" height=\"745\" src=\"https:\/\/www.jdx.info\/lutte\/wp-content\/uploads\/2023\/08\/F3V-rrIXgAAw2qC.png\" alt=\"\" class=\"wp-image-87993\" srcset=\"https:\/\/www.jdx.info\/lutte\/wp-content\/uploads\/2023\/08\/F3V-rrIXgAAw2qC.png 758w, https:\/\/www.jdx.info\/lutte\/wp-content\/uploads\/2023\/08\/F3V-rrIXgAAw2qC-300x295.png 300w\" sizes=\"auto, (max-width: 758px) 100vw, 758px\" \/><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Vendredi soir dernier \u00e0 la fin de SmackDown, Jey Uso a refus\u00e9 de pardonner son fr\u00e8re en lui mettant un Superkick en pleine tronche avant de prononcer les mots suivants : \u00ab\u00a0Je me tire de la Bloodline, je tire casse de SmackDown, je me tire de la WWE !\u00a0\u00bb La WWE qui met le paquet&#8230;<\/p>\n","protected":false},"author":4,"featured_media":87994,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,30,22,4,36,23],"tags":[],"ppma_author":[292],"class_list":["post-87992","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew-impact-njpw-roh","category-ex-wwe","category-indy","category-news","category-smackdown","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/87992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=87992"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/87992\/revisions"}],"predecessor-version":[{"id":87995,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/87992\/revisions\/87995"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/87994"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=87992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=87992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=87992"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=87992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}