{"id":87756,"date":"2023-08-07T22:23:57","date_gmt":"2023-08-08T02:23:57","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=87756"},"modified":"2023-08-07T22:37:58","modified_gmt":"2023-08-08T02:37:58","slug":"deuxieme-heure-de-raw-88","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/08\/07\/deuxieme-heure-de-raw-88\/","title":{"rendered":"Deuxi\u00e8me Heure de RAW"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/?p=87757\">Pour revenir \u00e0 la premi\u00e8re Heure, cliquez ici.<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p>&#8211; De retour suite \u00e0 la pause, en coulisse, Maxxine Dupri parle au t\u00e9l\u00e9phone. Ludwig Kaiser arrive pour la saluer. <\/p>\n\n\n\n<p>Kaiser dit qu&rsquo;elle doit aviser Gable que Gunther a d\u00e9j\u00e0 h\u00e2te de laver le sol avec le corps de Gable une nouvelle fois. Dupri lui demande de quitter son vestiaire. Kaiser dit qu&rsquo;il a ses yeux sur Dupri depuis quelques semaines, elle ira loin. Mais des gens ne peuvent jamais s&rsquo;am\u00e9liorer.\u00a0Lui il est un A+, alors qu&rsquo;Otis est un gros fou. Dupri le gifle ! <\/p>\n\n\n\n<p>Otis arrive et dit \u00e0 Kaiser de venir sur le ring s&rsquo;il veut de l&rsquo;action.<\/p>\n\n\n\n<p>&#8211;\u00a0<strong>Becky Lynch<\/strong>\u00a0dit qu&rsquo;elle est si pr\u00e8s de la fin. Elle se bat, elle parle, elle gagne et perd. Elle devient fatigu\u00e9e, mais elle est plein d&rsquo;espoir pour terminer cette histoire en affrontant Trish Stratus la semaine prochaine. La meilleure d&rsquo;une ancienne g\u00e9n\u00e9ration contre la meilleure de cette g\u00e9n\u00e9ration actuelle et toutes les autres jusqu&rsquo;\u00e0 l&rsquo;infini. Sans aucune intervention, aucune Zoey Stark, seulement frapper Trish sans h\u00e9sitation. <\/p>\n\n\n\n<p>Zoey Stark arrive et dit que Becky Lynch a peur de Zoey Stark. The Man a laiss\u00e9 ses couilles \u00e0 la maison en acceptant qu&rsquo;elle soit bannie en ringside. Becky dit que le probl\u00e8me est que Zoey est trop bonne dans ce qu&rsquo;elle fait et elle veut l&rsquo;avoir facile. Tellement facile avec Trish Stratus et aussi trop stupide pour r\u00e9aliser que Trish l&rsquo;am\u00e8ne dans la mauvaise direction. Zoey dit que Becky est jalouse. Becky est furieuse d&rsquo;avoir \u00e9t\u00e9 mise de c\u00f4t\u00e9 par la meilleure de tous les temps. <\/p>\n\n\n\n<p>La musique de Shayna Baszler commence et elle arrive sur le ring. Becky dit que Baszler semble l&rsquo;avoir eu difficile. Baszler dit que c&rsquo;est pire pour Ronda Rousey, malheureusement on ne le verra pas car elle a sorti Ronda Rousey de la WWE. <\/p>\n\n\n\n<p>Baszler dit qu&rsquo;elle n&rsquo;\u00e9tait pas invit\u00e9e pour leur petite f\u00eate, mais Zoey voulait jouer la plus forte. Zoey Stark dit que Baszler est le plus gros sac de boxe. Elle peut la renvoyer \u00e0 la maison comme Rousey. <\/p>\n\n\n\n<p>Becky Lynch dit que \u00e7a sonne comme un challenge, pourquoi ne pas faire \u00e7a maintenant ? Adam Pearce confirme le match.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&#8211; De retour, en coulisse, Finn Balor et JD McDonagh discutent ensemble. Damian Priest arrive et dit qu&rsquo;il veut parler en priv\u00e9e. Balor dit qu&rsquo;il connait McDonagh depuis des ann\u00e9es, alors Priest peut lui parler tous ensemble. Priest demande ce qui arrive. Ils ne voient pas Balor toute la soir\u00e9e et se pr\u00e9sente sur le ring pour attaquer Seth Rollins. Ils ne sont plus dans le plan ? Balor dit qu&rsquo;il a voulu faire son propre plan comme Priest n&rsquo;a pas suivi celui de SummerSlam.<strong>\u00a0<\/strong><\/p>\n\n\n\n<p>Priest dit qu&rsquo;il a donn\u00e9 son aide et malgr\u00e9 son aide Balor a quand m\u00eame perdu. Balor dit qu&rsquo;il a peut-\u00eatre perdu \u00e0 cause de Priest aussi. Ce contrat qui semble jouer sur les deux. Rhea Ripley arrive et ram\u00e8ne les deux au calme. Ils doivent agir comme des hommes et non des enfants. \u00c0 SummerSlam ils \u00e9taient tous l\u00e0 pour aider Finn Balor, mais \u00e7a n&rsquo;a pas fonctionn\u00e9.\u00a0Ils doivent bien s&rsquo;entendre pour diriger RAW. Priest et Balor approuvent.  <\/p>\n\n\n\n<p>McDonagh dit qu&rsquo;ils devraient peut-\u00eatre se d\u00e9barrasser de la mallette pour r\u00e9gler leur conflit.<\/p>\n\n\n\n<p>&#8211; Becky est avec les commentateurs pour le match.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Zoey Stark vs Shayna Baszler<\/strong><\/p>\n\n\n\n<p>En fin de match, Baszler applique un Kirifuda Clutch sur le tablier \u00e0 Stark, mais l&rsquo;arbitre la repousse. Baszler revient \u00e0 la charge avec un coup de pied et fait un Piper&rsquo;s Pit sur Stark pour le compte de trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnante : Shayna Baszler<\/em><\/p>\n\n\n\n<p>&#8211; En coulisse, Byron Saxton est avec Shinsuke Nakamura qui veut parler. Nakamura dit qu&rsquo;il ne peut plus endurer les gens sur son chemin. Ce soir il a gagn\u00e9 et il dessine son propre chemin.\u00a0<\/p>\n\n\n\n<p>L&rsquo;interview se fait interrompe par JD McDonagh qui attaque Sami Zayn plus loin. Les officiels arrivent pour stopper McDonagh.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Otis\u00a0acc de Maxxine Dupri\u00a0vs Ludwig Kaiser\u00a0acc de Giovanni Vinci<\/strong><\/p>\n\n\n\n<p>En fin de match, Kaiser et Dupri discutent ensemble sur le tablier, Otis en profite pour frapper Kaiser dans le dos. Otis se pr\u00e9pare pour son finisher, mais Vinci monte sur le tablier, Otis lui fait une Suplex. L&rsquo;arbitre sort Vinci du ring. Gunther et Kaiser en profitent pour porter un Running Kick \u00e0 Otis, Kaiser fait le compte de trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnant : Ludwig Kaiser<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, Imperium attaque Otis trois contre un. Chad Gable arrive et Imperium prend la fuite.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&#8211; En coulisse, Jackie Redmond arr\u00eate Cody Rhodes et Seth Rollins pour savoir si Sami Zayn sera capable de faire son match. Cody et Seth r\u00e9pondent en m\u00eame temps qu&rsquo;ils ne savent pas. <\/p>\n\n\n\n<p>Cody laisse la place \u00e0 Seth pour l&rsquo;interview. Seth dit que Sami veut faire le match, les m\u00e9decins non.\u00a0Alors c&rsquo;est deux contre trois, ou peut-\u00eatre un contre trois selon Cody. <\/p>\n\n\n\n<p>Shinsuke Nakamura arrive et dit qu&rsquo;il peut offrir son aide si besoin. Rollins dit qu&rsquo;il a beaucoup de respect pour Nakamura, c&rsquo;est accept\u00e9.<\/p>\n\n\n\n<p>&#8211; The Miz fait son entr\u00e9e vers le ring et on quitte pour la pause.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-center\" style=\"font-size:25px\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/?p=87755\">Pour la suite de RAW, cliquez ici.<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"mmuCZhsg2q\"><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/08\/07\/troisieme-heure-de-raw-83\/\">Troisi\u00e8me Heure de RAW<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Troisi\u00e8me Heure de RAW\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2023\/08\/07\/troisieme-heure-de-raw-83\/embed\/#?secret=yNXZOi2OCM#?secret=mmuCZhsg2q\" data-secret=\"mmuCZhsg2q\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>&#8211; De retour suite \u00e0 la pause, en coulisse, Maxxine Dupri parle au t\u00e9l\u00e9phone. Ludwig Kaiser arrive pour la saluer. Kaiser dit qu&rsquo;elle doit aviser Gable que Gunther a d\u00e9j\u00e0 h\u00e2te de laver le sol avec le corps de Gable une nouvelle fois. Dupri lui demande de quitter son vestiaire. Kaiser dit qu&rsquo;il a ses&#8230;<\/p>\n","protected":false},"author":4,"featured_media":87772,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43],"tags":[],"ppma_author":[292],"class_list":["post-87756","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-raw-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/87756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=87756"}],"version-history":[{"count":8,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/87756\/revisions"}],"predecessor-version":[{"id":87795,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/87756\/revisions\/87795"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/87772"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=87756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=87756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=87756"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=87756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}