{"id":87087,"date":"2023-07-26T00:01:00","date_gmt":"2023-07-26T04:01:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=87087"},"modified":"2023-07-25T17:31:53","modified_gmt":"2023-07-25T21:31:53","slug":"le-champion-dimpact-wrestling-dit-que-jeff-jarrett-est-lhomme-le-plus-intelligent-de-la-lutte-professionnel-et-le-felicite-pour-sa-performance-lors-du-dernier-match-de-ric-flair","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/07\/26\/le-champion-dimpact-wrestling-dit-que-jeff-jarrett-est-lhomme-le-plus-intelligent-de-la-lutte-professionnel-et-le-felicite-pour-sa-performance-lors-du-dernier-match-de-ric-flair\/","title":{"rendered":"Le champion d&rsquo;Impact Wrestling dit que Jeff Jarrett est l\u2019homme le plus intelligent de la lutte professionnel, et le f\u00e9licite pour sa performance lors du dernier match de Ric Flair!"},"content":{"rendered":"\n<p>Alex Shelley ne tarit pas d\u2019\u00e9loges sur le grand Jeff Jarrett.<\/p>\n\n\n\n<p>Le champion du monde IMPACT a parl\u00e9 de Double-J lors d\u2019une signature virtuelle avec Captain\u2019s Corner, o\u00f9 il a qualifi\u00e9 l\u2019actuel directeur du d\u00e9veloppement commercial de\u00a0la AEW d\u2019homme\u00a0le plus intelligent de toute la lutte professionnelle. Shelley explique que l\u2019industrie du catch serait \u00e0 jamais diff\u00e9rente sans Jarrett, citant sa cr\u00e9ation de la TNA et son travail \u00e0 la WWE\/WCW comme meilleurs exemples.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Il (Jeff Jarrett) est probablement l\u2019homme le plus intelligent de la lutte, n\u2019est-ce pas ? C\u2019est probablement le gars le plus intelligent que j\u2019ai jamais rencontr\u00e9. C\u2019est juste un g\u00e9nie. Il a surv\u00e9cu \u00e0 diff\u00e9rentes \u00e9poques de la lutte et il a eu tellement d\u2019exp\u00e9riences diff\u00e9rentes et a lutt\u00e9 contre tout le monde. , comment peux-tu ne pas \u00eatre un g\u00e9nie \u00e0 ce moment-l\u00e0 ? Venir \u00e0 Memphis comme \u00e7a et ensuite faire la transition vers le style WWF, c\u2019est totalement diff\u00e9rent, non ? C\u2019est un jeu totalement diff\u00e9rent, donc du point de vue d\u2019un catcheur, les choses que vous faisiez et qui ont fonctionn\u00e9 l\u00e0-bas ne vont pas n\u00e9cessairement fonctionner dans le Nord, mais elles l\u2019ont fait, puis aller de l\u00e0 \u00e0 la WCW au bon moment, puis retourner \u00e0 la WWF et lui donner un gimmick ou il a d\u00e9cid\u00e9. Je ne sais pas lequel mais ce n\u2019\u00e9tait pas forc\u00e9ment g\u00e9nial avec les trucs de la NWA. Rappelez-vous quand il avait les couleurs de Miami \u2013 les Dolphins en quelque sorte? Et puis faire la transition pour lui couper les cheveux dans un match avec X-Pac et ensuite devenir un heel de haut niveau, c\u2019est tout simplement incroyable, et d\u00e9marrer une entreprise. Sans Jeff Jarrett, le business du catch tel que nous le connaissons serait totalement diff\u00e9rent. Je veux dire totalement diff\u00e9rent. Je ne sais pas si nous (Motor City Machine Guns) aurions eu des carri\u00e8res en toute honn\u00eatet\u00e9, donc le plus grand respect pour Jeff.<\/p>\n<\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Shelley souligne plus tard \u00e0 quel point Jarrett \u00e9tait bon dans le main event du Last Match de Ric Flair, o\u00f9 lui et Jay Lethal ont \u00e9t\u00e9 battus par le Nature Boy et Andrade El Idolo.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Je pensais qu\u2019il avait en quelque sorte vol\u00e9 la vedette sur Last Match de (Ric) Flair aussi. Quand je regardais, comme un homme, tout le monde allait bien, mais je ne peux pas quitter Jeff des yeux. Je ne sais pas ce que c\u2019est.<\/p>\n<\/blockquote>\n\n\n\n<p>Ailleurs dans la signature, Shelley a parl\u00e9 des Time Splitters (Lui et KUSHIDA) et de la fa\u00e7on dont ils allaient avoir une course \u00e9largie \u00e0 la WWE jusqu\u2019\u00e0 ce que l\u2019\u00e9pid\u00e9mie de COVID-19 le ruine.<\/p>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Alex Shelley ne tarit pas d\u2019\u00e9loges sur le grand Jeff Jarrett. Le champion du monde IMPACT a parl\u00e9 de Double-J lors d\u2019une signature virtuelle avec Captain\u2019s Corner, o\u00f9 il a qualifi\u00e9 l\u2019actuel directeur du d\u00e9veloppement commercial de\u00a0la AEW d\u2019homme\u00a0le plus intelligent de toute la lutte professionnelle. Shelley explique que l\u2019industrie du catch serait \u00e0 jamais&#8230;<\/p>\n","protected":false},"author":665,"featured_media":87167,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,30,77,22,4,41,83],"tags":[],"ppma_author":[289],"class_list":["post-87087","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-ex-wwe","category-hall-of-fame","category-indy","category-news","category-tna-impact","category-wcw"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/87087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=87087"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/87087\/revisions"}],"predecessor-version":[{"id":87168,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/87087\/revisions\/87168"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/87167"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=87087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=87087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=87087"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=87087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}