{"id":86910,"date":"2023-07-18T19:53:00","date_gmt":"2023-07-18T23:53:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=86910"},"modified":"2023-07-19T02:20:27","modified_gmt":"2023-07-19T06:20:27","slug":"resultats-et-video-pour-le-wwe-nxt-du-18-juillet-2023","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/07\/18\/resultats-et-video-pour-le-wwe-nxt-du-18-juillet-2023\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le WWE NXT du 18 Juillet 2023!"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/07\/18\/avant-gout-pour-le-wwe-nxt-du-18-juillet-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir NXT, cliquez ici.<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size\"><strong>WWE NXT, Orlando, Floride, 18 Juillet 2023<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Vic Joseph et Booker T.<\/p>\n\n\n\n<p>&#8211; Le  WWE NXTd\u00e9marre avec une vid\u00e9o des \u00e9v\u00e9nements de la\u00a0semaine derni\u00e8re \u00a0avec la victoire de Ilja Dragunov sur Bron Breakker et la pr\u00e9sence du Judgment Day.<\/p>\n\n\n\n<p>Trick Williams dit qu&rsquo;\u00e0 deux semaines de Great American Bash il veut passer au business. Il nous pr\u00e9sente notre champion de NXT, l&rsquo;homme qui ne rate pas et celui qui va stopper le dragon, Carmelo Hayes. Hayes dit que la semaine derni\u00e8re ils ont rat\u00e9. Williams dit que si ce n&rsquo;\u00e9tait pas de la mallette ils gagnaient. Hayes dit que c&rsquo;\u00e9tait 4 contre 2, ils \u00e9taient \u00e0 quatre seconde de battre un clan dominant. Ilja Dragunov arrive avec un micro.<\/p>\n\n\n\n<p>Dragunov dit que la semaine derni\u00e8re il ne voulait pas se mettr le nez dans les affaires de Hayes. Mais Hayes ne semble pas comprendre quelque chose, si Damian Priest avait utilis\u00e9 sa mallette, Hayes aurait perdu le match et le titre de NXT aussi peut-\u00eatre. Il voulait emp\u00eacher Damien Priest d&rsquo;amener le titre dans le main roster car il veut affronter Hayes \u00e0 Great American Bash. On dirait que Hayes a perdu le contr\u00f4le. Hayes dit qu&rsquo;il reste Melo, tout est sous contr\u00f4le. Il a vu le match entre Dragunov et Breakker, il sait exactement ce que Dragunov est capable de faire, il est pr\u00eat pour lui. Dragunov dit qu&rsquo;il se donne toujours sur le ring, lorsqu&rsquo;il est sur le ring \u00e7a repr\u00e9sente quelque chose et les fans le sentent. Hayes va sentir la d\u00e9faite \u00e0 Great American Bash. Hayes dit qu&rsquo;il sent les critiques du monde entier et la tension dans les coulisses car il est le champion, il sent tout. Les deux vont livrer un combat, tout le monde le sait, mais Dragunov est le plus qualifi\u00e9 pour l&rsquo;affronter. Il planifie un tr\u00e8s tr\u00e8s tr\u00e8s long r\u00e8gne et en attendant il fera que des victoires. Dragunov va bien le sentir et il va frapper diff\u00e9rent. Dragunov dit que Hayes devra frapper encore plus fort, sinon Hayes va tomber. Hayes ne pourra pas contr\u00f4ler son feu. Hayes dit que ce sera champagne pour un et l&rsquo;autre que de la douleur.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&#8211; En coulisse, Mustafa Ali retrouve Wes Lee. Ali demande \u00e0 quoi il pensait en d\u00e9fendant son titre contre Dominik. Lee dit que Dominik est venu le voir et il a accept\u00e9, c&rsquo;est ainsi.<\/p>\n\n\n\n<p> Ali dit que l&rsquo;encre pour leur match \u00e0 Great American Bash n&rsquo;a pas encore s\u00e8ch\u00e9.\u00a0Il ne veut pas affronter Dominik pour le PLE. Lee dit qu&rsquo;il est pr\u00eat pour Dom et le Judgment Day. Ali dit qu&rsquo;il veut affronter le meilleur champion Nord-Am\u00e9ricain de l&rsquo;histoire \u00e0 The Bash. Lee dit qu&rsquo;il sera l\u00e0.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o de plus t\u00f4t aujourd&rsquo;hui de Tony D&rsquo;Angelo qui est lib\u00e9r\u00e9 de prison. Channing Lorenzo l&rsquo;attend sur le parking.<\/p>\n\n\n\n<p><strong>Tag Team Match<\/strong><\/p>\n\n\n\n<p><strong>Angel Garza et Humberto Carrillo vs Nathan Frazer et Dragon Lee<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Frazer repousse Carrillo et Garza du ring avec un Double Drop Kick. Frazer se lance en Cross Body sur les deux en bas du ring. Frazer lancer Garza sur le ring et Lee enchaine avec son Asai DDT pour le compte de trois.<\/p>\n\n\n\n<p><strong>Gagnants : Nathan Frazer et Dragon Lee<\/strong><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Garza et Carrillo argumentent ensemble. Carrillo pousse Garza au sol et quitte seul !<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente la suite de la vid\u00e9o de Baron Corbin qui arrive \u00e0 destination. Corbin dit qu&rsquo;il a br\u00fbl\u00e9 son pass\u00e9 pour \u00e9voluer, mais \u00e9voluer comment ? Il doit imposer la peur pour \u00eatre respect\u00e9 et devenir le champion. Il va faire face \u00e0 son futur, au reste de sa carri\u00e8re.<strong>&nbsp;L&rsquo;homme devant lui retire sa capuche et il s&rsquo;agit du nouveau Baron Corbin<\/strong>.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o de NXT Anonymous o\u00f9 on voit Booker T qui donne des conseils \u00e0 Roxanne Perez. Booker T explique \u00e0 Perez qu&rsquo;elle devra tout sortir pour affronter Blair Davenport.<\/p>\n\n\n\n<p><strong>Gigi Dolin vs Kiana James<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Dolin enl\u00e8ve le sac \u00e0 main \u00e0 James. Dolin veut la frapper avec le sac, mais l&rsquo;arbitre lui enl\u00e8ve. James en profite pour faire son 401K sur le sac \u00e0 main pour le compte de trois sur Dolin.<\/p>\n\n\n\n<p><em>Gagnante : Kiana James<\/em><\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente un Tweeet de Noam Dar qui est toujours d\u00e9vast\u00e9.<\/p>\n\n\n\n<p>&#8211; En coulisse, McKenzie demande \u00e0 Eddy Thorpe ses commentaires sur son match NXT Underground. Thorpe dit que c&rsquo;\u00e9tait le match de sa vie, ce match l&rsquo;a mis en route pour un match de championnat. Noam Dar arrive en chaise roulante pouss\u00e9e par son clan. Jakara Jackson dit que Dar s&rsquo;excuse pour annuler le SuperNova Sessions encore une fois.\u00a0Oro lui donne une photo de Noam Dar en prix de consolation. Thorpe d\u00e9chire la photo et dit qu&rsquo;il pr\u00e9f\u00e8re se battre que parler.\u00a0Oro dit qu&rsquo;ils ont seulement besoin d&rsquo;un ring. Les officiels arrivent pour les s\u00e9parer.<\/p>\n\n\n\n<p><strong>Scrypts et Axiom vs Bronco Nima et Lucien Price<\/strong><\/p>\n\n\n\n<p>Scrypts d\u00e9cide de frapper Axiom et laisser Axiom se faire battre sur le ring et rigoler. Price et Nima font une s\u00e9rie de prises et de coups sur Axiom. Price fait une Big Boot sur Axiom pour terminer le match en deux minutes.<\/p>\n\n\n\n<p><em>Gagnants : Bronco Nima et Lucien Price<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Scrypts quitte avec Nima et Price.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&#8211; Le ring est d\u00e9cor\u00e9 avec une famille italienne\u00a0pour le retour de Tony D&rsquo;Angelo. Channing Lorenzo dit que tout a chang\u00e9 le 25 mai pour la famille lorsque D&rsquo;Angelo a termin\u00e9 en prison \u00e0 cause de Gallus. Gallus pensait pouvoir contr\u00f4ler les rues de NXT en lan\u00e7ant des accusations sur le patron. Le voici le voil\u00e0. D&rsquo;Angelo arrive sur le ring et fait des c\u00e2lins \u00e0 tout le monde. <\/p>\n\n\n\n<p>D&rsquo;Angelo dit qu&rsquo;il doit remercier Lorenzo avant de commencer, il ne serait pas ici si ce n&rsquo;\u00e9tait pas de Lorenzo qui a organis\u00e9 un plan de g\u00e9nie. Des gens pensaient que Lorenzo \u00e9tait le rat, mais non. On voit une vid\u00e9o sur cette histoire de prison et la fausse trahison de Lorenzo.<\/p>\n\n\n\n<p>Gallus arrive sur la sc\u00e8ne. Joe Coffey dit qu&rsquo;il ne peut pas croire ce qu&rsquo;il voit. Les deux sont la pire forme de vie qu&rsquo;il n&rsquo;a jamais vue. Ils sont des racailles. Lorenzo va souhaiter retourner dans la cellule car c&rsquo;\u00e9tait plus s\u00e9curitaire que d&rsquo;\u00eatre ici. D&rsquo;Angelo dit que Joe a perdu le contr\u00f4le.<\/p>\n\n\n\n<p>\u00a0Lorenzo dit que c&rsquo;est comme Gallus qui va perdre les titres par \u00e9quipe contre la famille \u00e0 Great American Bash. Lorenzo leur dit de bien faire briller les titres, car la famille Lorenzo va prendre les titres.\u00a0Joe dit qu&rsquo;ils ne pourront m\u00eame pas atteindre The Bash. Gallus entre sur le ring pour un face \u00e0 face. La famille enti\u00e8re de Lorenzo sort tous leur pied de biche. Gallus veut quand m\u00eame se battre, mais ils se font \u00e9craser. Mark Coffey se fait envoyer \u00e0 travers d&rsquo;une table.<\/p>\n\n\n\n<p>&#8211; En coulisse, Trick Williams et Carmelo Hayes croisent le Schism. Hayes en profite pour saluer la bande de bizarres. Joe Gacy dit qu&rsquo;ils n&rsquo;ont pas besoin de leur n\u00e9gativit\u00e9. Leur union va surement s&rsquo;arr\u00eater lorsque Hayes va perdre le titre. Ilja Dragunov arrive. Hayes demande pourquoi il s&rsquo;interpose encore. Dragunov sit que son match avec Hayes est in\u00e9vitable, mais Gacy ils peuvent r\u00e9gler \u00e7a. Hayes et Dragunov commencent \u00e0 se battre avec le Schism. Les officiels arrivent pour s\u00e9parer tout le monde.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Thea Hail\u00a0acc de Duke Hudson\u00a0vs Elektra Lopez<em>\u00a0acc de Lola Vice<\/em><\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Hail bloque une prise de Lopez et lui applique un Kimura Lock pour faire taper Lopez et l&#8217;emporter rapidement.<\/p>\n\n\n\n<p><em>Gagnante : Thea Hail\u00a0<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, Thea Hail dit qu&rsquo;elle a tortur\u00e9 le bras de Lopez et elle a tap\u00e9 de la m\u00eame fa\u00e7on que Tiffany Stratton. Alors elle veut une autre chance pour le titre f\u00e9minin, elle sait qu&rsquo;elle peut le faire ! Hudson dit qu&rsquo;il reste une chose \u00e0 dire : rematch ! La foule chante \u00a0\u00bbrematch\u00a0\u00bb. <\/p>\n\n\n\n<p>Hail dit \u00e0 la blonde de se pointer pour qu&rsquo;elle puisse lui botter le cul. Tiffany Stratton arrive et dit qu&rsquo;elle est clairement sup\u00e9rieure de Hail. Hail a appris une prise et elle pense pouvoir conqu\u00e9rir la terre enti\u00e8re. Hail veut avoir un rematch, et bien elle accepte ! Stratton dit qu&rsquo;elle va la battre pour de bon. <\/p>\n\n\n\n<p>Hail dit qu&rsquo;elle veut ajouter une chose pour le match,\u00a0soit un Submission Match. Stratton dit qu&rsquo;elle est la championne et elle d\u00e9cide de la stipulation et Hail ne peut pas la faire changer d&rsquo;avis. Hail attrape le bras de Stratton et lui applique un Kimura Lock ! Stratton commence \u00e0 hurler et accepte la stipulation.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&#8211; En coulisse, Dominik et Rhea Ripley se pr\u00e9parent pour leur match. La famille D&rsquo;Angelo passe devant pour le saluer et lui souhaiter bonne chance. Lyra Valkyrie arrive. Rhea Ripley dit que Lyra doit lui montrer comment remporter face \u00e0 Jacy Jayne. Lyra approuve.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o promo sur Gable Steveson qui parle de son futur disant qu&rsquo;il pourrait aller aux Jeux olympiques de Paris, aller en tournoi NCAA, ou bien rester \u00e0 WWE NXT.\u00a0La semaine prochaine il va d\u00e9cider de son futur.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Oro Mensah accompagn\u00e9 du clan de Noam Dar vs Eddy Thorpe<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Jakara Jackson lance Noam Dar sur le ring pour distraire l&rsquo;arbitre. L&rsquo;arbitre roule Dar en bas du ring. Dijak d\u00e9barque pour attaquer Thorpe ! Mensah en profite pour faire un Running Kick sur Thorpe pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : Oro Mensah<\/em><\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o d&rsquo;un entrainement entre Dana Brooke et Kelani Jordan. Jordan dit qu&rsquo;elle a eu beaucoup de plaisir et la remercie.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&#8211; En coulisse, Cora Jade se moque de la gymnastique de Jordan.<\/p>\n\n\n\n<p>&#8211; On retrouve Blair Davenport et Roxanne Perez en interview en \u00e9crans partag\u00e9. Perez dit que Booker T lui donnait quelques conseils car les deux vont s&rsquo;affronter \u00e0 Great American Bash. <\/p>\n\n\n\n<p>Davenport dit qu&rsquo;elle devra laisser Perez au sol encore une fois, mais cette fois-ci devant ses fans du Texas. NXT est pour les femmes maintenant, les petites filles n&rsquo;ont plus leur place.<\/p>\n\n\n\n<p> Perez dit qu&rsquo;elle n&rsquo;est pas une cible facile, elle ne sera jamais la plus grande ou la plus puissante. Mais il y a une rage \u00e0 l&rsquo;int\u00e9rieur depuis sa perte du titre et Davenport s&rsquo;ajoute. Davenport lui fera un sortir un c\u00f4t\u00e9 que la NXT Universe n&rsquo;a jamais vu \u00e0 The Bash. Davenport dit que Perez a de grands r\u00eaves dans son petit corps. M\u00eame Perez ne se croit pas. \u00c0 The Bash elle va la blesser et ensuite Perez pourra simplement rester \u00e0 la maison.<\/p>\n\n\n\n<p style=\"font-size:25px\"><strong>Championnat Nord Am\u00e9ricain<\/strong><\/p>\n\n\n\n<p><strong>Dominik Mysterio\u00a0acc de Rhea Ripley\u00a0vs Wes Lee <\/strong>\u00a9<\/p>\n\n\n\n<p>\u00c0 la fin du combat, Lee veut se lancer en saut suicide sur Dominik, mais Dominik se rel\u00e8ve et d\u00e9cide de partir. Lee veut partir avec le championnat, mais Lee se lance sur Dominik en bas du ring ! Lee ram\u00e8ne Dominik sur le ring et monte sur le coin pour un 450. Finn Balor arrive pour distraire l&rsquo;arbitre, de l&rsquo;autre c\u00f4t\u00e9 Damian Priest veut attaquer Lee, mais Lee le repousse avec son Cardiac Kick. Ripley intervient et cogne Lee avec son titre f\u00e9minin ! Dominik couvre Lee pour la victoire.<\/p>\n\n\n\n<p><em>Gagnant et Nouveau Champion : Dominik Mysterio<\/em><\/p>\n\n\n\n<p>Le show se termine avec une c\u00e9l\u00e9bration du Judgment Day.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-center\" style=\"font-size:25px\"><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2023\/07\/18\/avant-gout-pour-le-wwe-nxt-du-18-juillet-2023\/\" target=\"_blank\">Pour voir NXT, cliquez ici.<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"MrT0uBHgnq\"><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/07\/18\/avant-gout-pour-le-wwe-nxt-du-18-juillet-2023\/\">Reprise Vid\u00e9o et Programme pour le WWE NXT du 18 Juillet 2023!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Reprise Vid\u00e9o et Programme pour le WWE NXT du 18 Juillet 2023!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2023\/07\/18\/avant-gout-pour-le-wwe-nxt-du-18-juillet-2023\/embed\/#?secret=Zq7E0XYM5k#?secret=MrT0uBHgnq\" data-secret=\"MrT0uBHgnq\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>WWE NXT, Orlando, Floride, 18 Juillet 2023 Les commentateurs sont Vic Joseph et Booker T. &#8211; Le WWE NXTd\u00e9marre avec une vid\u00e9o des \u00e9v\u00e9nements de la\u00a0semaine derni\u00e8re \u00a0avec la victoire de Ilja Dragunov sur Bron Breakker et la pr\u00e9sence du Judgment Day. Trick Williams dit qu&rsquo;\u00e0 deux semaines de Great American Bash il veut passer&#8230;<\/p>\n","protected":false},"author":609,"featured_media":86911,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,85,21,23],"tags":[],"ppma_author":[295],"class_list":["post-86910","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-nxt","category-resultats","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/86910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=86910"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/86910\/revisions"}],"predecessor-version":[{"id":86912,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/86910\/revisions\/86912"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/86911"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=86910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=86910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=86910"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=86910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}