{"id":86354,"date":"2023-07-05T21:54:12","date_gmt":"2023-07-06T01:54:12","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=86354"},"modified":"2023-07-05T22:09:41","modified_gmt":"2023-07-06T02:09:41","slug":"deuxieme-heure-dynamite-4","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/07\/05\/deuxieme-heure-dynamite-4\/","title":{"rendered":"Deuxi\u00e8me Heure Dynamite!"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/?p=86355\">Pour revenir \u00e0 la premi\u00e8re heure, cliquez ici.<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p>&#8211;\u00a0<strong>Chris Jericho<\/strong>\u00a0arrive sur le ring sous une ovation du public canadien et prend le micro. Jericho dit que depuis les derniers mois il a eu de grosses d\u00e9faites \u00e0 son nom et les choses ne vont pas vraiment comme il veut. Alors c&rsquo;est peut-\u00eatre le moment pour r\u00e9\u00e9valuer les choses et faire quelques changements. C&rsquo;est l&rsquo;endroit id\u00e9al pour rena\u00eetre dans la province d&rsquo;Alberta car c&rsquo;est l&rsquo;endroit o\u00f9 il a commenc\u00e9 sa carri\u00e8re. Il a l&rsquo;impression que c&rsquo;\u00e9tait hier qu&rsquo;il commen\u00e7ait son entrainement avec Stu Hart. Il a m\u00eame eu son premier match \u00e0 une heure d&rsquo;ici. Alors il est venu ici quelques jours avant en voiture et il s&rsquo;est rappel\u00e9 c&rsquo;\u00e9tait quoi lorsqu&rsquo;il a commenc\u00e9 le catch. La passion, le feu, lorsque le catch repr\u00e9sentait tout pour lui. Et \u00e7a lui a rappel\u00e9 que le catch repr\u00e9sente toujours tout pour lui. Alberta est l&rsquo;endroit o\u00f9 il renait, c&rsquo;est le moment de devenir un meilleur Chris Jericho. Peut-\u00eatre la meilleure version de Chris Jericho jamais vu. <\/p>\n\n\n\n<p>La musique de Don Callis retenti et il arrive sur le ring sous les hu\u00e9s et les insultes des fans. Il dit qu&rsquo;il entend que Jericho a besoin d&rsquo;un changement. \u00c7a fait six ans qu&rsquo;il a appel\u00e9 Jericho de Tokyo pour lui proposer un match en main event contre Kenny Omega. Jericho a directement accept\u00e9 et ils ont chang\u00e9 le futur du catch. Sans ce match, personne ne serait ici ce soir, Jericho ne serait m\u00eame pas ici sans son id\u00e9e. Jericho dit qu&rsquo;il n&rsquo;a rien entendu \u00e0 cause des hu\u00e9s. <\/p>\n\n\n\n<p>Jericho dit qu&rsquo;il peut dire la m\u00eame chose, il savait que Callis \u00e9tait mis\u00e9rable et qu&rsquo;il voulait revenir dans l&rsquo;univers catch. Il l&rsquo;a aid\u00e9 \u00e0 revenir \u00e0 la AEW et Callis est plus grand et plus fort que jamais dans le catch. Sans lui, Callis ne serait peut-\u00eatre pas ici. <\/p>\n\n\n\n<p>Callis dit qu&rsquo;ensemble ils font toujours l&rsquo;histoire, c&rsquo;est leur accord. Mais il s&rsquo;est retrouv\u00e9 trahi par l&rsquo;idiot de Kenny Omega, alors il devait se construire une nouvelle famille.\u00a0Une nouvelle famille bas\u00e9e sur la confiance, il pense au meilleur de tous les temps, il pense \u00e0 son meilleur ami de 34 ans, il pense \u00e0 Chris Jericho. Alors si Jericho est pr\u00eat \u00e0 changer l&rsquo;histoire encore une fois, est-ce qu&rsquo;il veut rejoindre la famille Don Callis ? <\/p>\n\n\n\n<p>Jericho demande si Callis lui demande vraiment de rejoindre sa famille et son clan. Jericho dit qu&rsquo;il cr\u00e9\u00e9 des clans ici. Si Callis veut vraiment le voir rejoindre son clan, la r\u00e9ponse est \u00a0\u00bbpeut-\u00eatre\u00a0\u00bb. Jericho quitte le ring.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o teasing sur CM Punk qui va affronter Samoa Joe ce samedi \u00e0 Collision dans le tournoi Owen Hart.<\/p>\n\n\n\n<p>&#8211; En coulisse, Renee Paquette est avec Roderick Strong et le m\u00e9decin pour en savoir plus sur sa sant\u00e9. Le m\u00e9decin dit que Strong fait de bon progr\u00e8s, mais ils vont faire attention pour s&rsquo;assurer qu&rsquo;il soit \u00e0 100%. Strong dit qu&rsquo;il va tr\u00e8s bien. Adam Cole arrive et lui dit de faire attention, Strong a tout son temps. Strong demande ce qui arrive avec MJF. Cole dit qu&rsquo;il a ses limites, Strong n&rsquo;a pas besoin de s&rsquo;inqui\u00e9ter.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Quarts de finale<\/strong> <strong>Blind Eliminator Tag Team Tournament <\/strong><\/p>\n\n\n\n<p><strong>MJF et Adam Cole vs Butcher et Matt Menard<\/strong><\/p>\n\n\n\n<p>En fin de match, MJF veut la tag pour la Double Clothesline. Cole repousse Butcher avec un Superkick et enchaine avec un autre Superkick sur Menard. Cole se pr\u00e9pare pour son finisher, MJF demande encore la tag pour la Double Clothesline. Cole ne l&rsquo;\u00e9coute pas et fait son BOOM sur Menard pour le compte de trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnants : MJF et Adam Cole<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, MJF et Cole c\u00e9l\u00e8brent la victoire ensemble. MJF demande le micro. MJF dit qu&rsquo;il a beaucoup de fans du diable ici ce soir. La foule chante MJF. MJF demande si on a des fans du nom bien cool aussi ? Cole lance un BayBay. MJF dit qu&rsquo;ils sont meilleurs que nous BayBay.<\/p>\n\n\n\n<p> MJF dit qu&rsquo;avec la Double Clothesline ils auraient fait un meilleur boulot. MJF dit que les deux devraient avoir une autre session de musculation. La foule chante \u00a0\u00bbYES\u00a0\u00bb. Cole approuve.\u00a0<\/p>\n\n\n\n<p>MJF dit qu&rsquo;il doit dire une autre chose \u00e0 Cole : Joyeux anniversaire !\u00a0MJF et les fans chantent un joyeux anniversaire sous les confettis. Une \u00e9quipe technique arrive avec un g\u00e2teau et d&rsquo;autres objets pour c\u00e9l\u00e9brer. MJF dit que ce soir on est tous ici pour c\u00e9l\u00e9brer Adam Cole. MJF sort ses talents de chanteur pour interpr\u00e9ter \u00a0\u00bbjoyeux anniversaire\u00a0\u00bb. <\/p>\n\n\n\n<p>Cole l&rsquo;arr\u00eate et dit qu&rsquo;il comprend que MJF chante bien. MJF a d\u00e9j\u00e0 trop fait, il peut arr\u00eater. MJF dit qu&rsquo;il manque une chose, Cole doit faire un souhait. Cole souffle sur la bougie. MJF veut le pousser dans le g\u00e2teau, mais Cole l&rsquo;\u00e9vite et le pousse sur le g\u00e2teau. Cole dit que c&rsquo;\u00e9tait vraiment gentil de faire \u00e7a pour son anniversaire, alors merci l&rsquo;ami.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&#8211; En coulisse, Renee Paquette est avec Britt Baker pour avoir ses commentaires avant son match. Baker dit que Ruby Soho parle beaucoup avec ses amies. Ce n&rsquo;est pas important ce qu&rsquo;on dit \u00e0 son propos. Mais Soho a menti \u00e0 tout le monde en disant qu&rsquo;elle lui a tout pris. Soho ne sera jamais capable de lui prendre sa fiert\u00e9, car elle sera toujours l&rsquo;image de la division peut importe ce que Soho lui fera. Et Soho ne pourra jamais lui enlever le fait d&rsquo;\u00eatre la premi\u00e8re gagnante du tournoi Owen Hart et elle pense le gagner encore une fois.<\/p>\n\n\n\n<p>&#8211; De retour, en coulisse, Renee Paquette demande \u00e0\u00a0<strong>Chris Jericho<\/strong>\u00a0plus de d\u00e9tails sur la r\u00e9ponse \u00e0 Don Callis. Daniel Garcia dit qu&rsquo;ils sont la famille de Jericho, c&rsquo;\u00e9tait quoi le peut-\u00eatre. Jericho dit qu&rsquo;ils sont toujours sa famille,\u00a0c&rsquo;\u00e9tait un peut-\u00eatre, aucun oui ou non. Mais Garcia et Sammy Guevara ne peuvent pas passer toute leur carri\u00e8re sous leur aile.\u00a0<\/p>\n\n\n\n<p>Paquette annonce que Garcia et Guevara ont \u00e9t\u00e9 tir\u00e9 au sort ensemble pour le tournoi Blind. <\/p>\n\n\n\n<p>Jericho dit que c&rsquo;est le moment de tout remporter et montrer ce qu&rsquo;ils peuvent faire.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Quart de Final Tournoi Owen Hart <\/strong><\/p>\n\n\n\n<p><strong>Britt Baker vs Ruby Soho\u00a0<em>ac de Saraya et Toni Storm<\/em><\/strong><\/p>\n\n\n\n<p>En fin de match, Soho d\u00e9cide finalement de faire un Cross Face. Baker rampe vers un c\u00e2ble et renverse Soho en Lock Jaw. Storm et Saraya tirent Soho en bas du ring pour la sauver. Baker ram\u00e8ne Soho sur le ring, mais Storm lui attrape la jambe pour la distraire, Baker lui fait un Stomp. Baker bloque une attaque de Soho, mais Soho la renverse en compte rapide avec l&rsquo;aide de Storm pour ajouter de la pression pour compl\u00e9ter le compte de trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnante : Ruby Soho<\/em><\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p class=\"has-medium-font-size\"><strong>Wheeler Yuta vs Kenny Omega<\/strong><\/p>\n\n\n\n<p>En fin de match,\u00a0Omega fait un V-Trigger \u00e0 Yuta. Omega le prend en One Winged Angel, mais Yuta le renverse en compte rapide et Omega r\u00e9siste. Yuta le charge, mais Omega le renverse en Powerbomb. Omega fait un V-Trigger pour le couvrir, mais Yuta r\u00e9siste. Omega se pr\u00e9pare pour la suite&#8230; <\/p>\n\n\n\n<p>Don Callis arrive. La s\u00e9curit\u00e9 arrive pour le retenir. Konosuke Takeshita arrive de l&rsquo;autre c\u00f4t\u00e9 pour faire un Blue Thunder Bomb \u00e0 Omega ! Yuta en profite pour faire un Splash \u00e0 Omega pour le couvrir, mais il r\u00e9siste \u00e0 deux ! Yuta remonte sur le coin, mais Omega le bloque et le prend pour un One Winged Angel pour le compte de trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnant : Kenny Omega<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, Claudio (Cesaro) Castagnoli d\u00e9barque sur le ring pour attaquer Omega avec l&rsquo;aide de Takeshita. <\/p>\n\n\n\n<p>Les Young Bucks et Adam Page arrivent sur le ring \u00e0 leur tour avec des chaises pour chasser Castagnoli et Takeshita \u00e0 l&rsquo;aide de coups de chaises. Page veut donner un autre coup de chaise, mais le Dark Order arrive pour l&rsquo;arr\u00eater. <\/p>\n\n\n\n<p>Le show se termine ainsi.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-center\" style=\"font-size:25px\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/07\/05\/avant-gout-pour-le-aew-dynamite-du-5-juillet-2023\/\">Pour voir Dynamite, cliquez ici.<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"jPOhMF8KSJ\"><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/07\/05\/avant-gout-pour-le-aew-dynamite-du-5-juillet-2023\/\">Reprise Vid\u00e9o et Programme pour le AEW Dynamite du 5 Juillet 2023!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Reprise Vid\u00e9o et Programme pour le AEW Dynamite du 5 Juillet 2023!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2023\/07\/05\/avant-gout-pour-le-aew-dynamite-du-5-juillet-2023\/embed\/#?secret=w62aTvy1fB#?secret=jPOhMF8KSJ\" data-secret=\"jPOhMF8KSJ\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>&#8211;\u00a0Chris Jericho\u00a0arrive sur le ring sous une ovation du public canadien et prend le micro. Jericho dit que depuis les derniers mois il a eu de grosses d\u00e9faites \u00e0 son nom et les choses ne vont pas vraiment comme il veut. Alors c&rsquo;est peut-\u00eatre le moment pour r\u00e9\u00e9valuer les choses et faire quelques changements. C&rsquo;est&#8230;<\/p>\n","protected":false},"author":4,"featured_media":86361,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50],"tags":[],"ppma_author":[292],"class_list":["post-86354","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dynamite"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/86354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=86354"}],"version-history":[{"count":6,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/86354\/revisions"}],"predecessor-version":[{"id":86377,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/86354\/revisions\/86377"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/86361"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=86354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=86354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=86354"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=86354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}