{"id":85515,"date":"2023-06-21T00:50:24","date_gmt":"2023-06-21T04:50:24","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=85515"},"modified":"2023-06-21T00:56:33","modified_gmt":"2023-06-21T04:56:33","slug":"deuxieme-heure-de-gold-rush","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/06\/21\/deuxieme-heure-de-gold-rush\/","title":{"rendered":"Deuxi\u00e8me Heure de Gold Rush!"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.jdx.info\/lutte\/?p=85516\">Pour revenir \u00e0 la premi\u00e8re heure, cliquez ici.<\/a><\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p>&#8211; En coulisse,\u00a0<strong>Seth Rollins<\/strong> rencontre <strong>Nathan Frazer<\/strong>.\u00a0Rollins le f\u00e9licite pour avoir remporter sa grande coupe. Frazer le f\u00e9licite pour son titre et lui demande comment il va. Rollins dit qu&rsquo;il n&rsquo;est pas \u00e0 100%, mais c&rsquo;est de sa faute, il voulait affronter le meilleur Finn Balor. Il est fier de quoi Frazer est devenu. Carmelo Hayes et Trick Williams arrivent. Hayes se pr\u00e9sente avec Williams. <\/p>\n\n\n\n<p>Rollins reste sans mot, mais commence \u00e0 rigoler. Rollins demande ce qu&rsquo;il peut faire pour eux. Hayes dit qu&rsquo;il veut montrer seulement son respect entre champions. Rollins demande s&rsquo;il va battre Baron Corbin la semaine prochaine. Hayes approuve. Hayes demande s&rsquo;il est pr\u00eat pour Breakker. Rollins dit qu&rsquo;il ne rate jamais.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Cora Jade vs Dana Brooke<\/strong><\/p>\n\n\n\n<p>En fin de match, Jade commence \u00e0 s&rsquo;attaquer \u00e0 la jambe de Brooke sans arr\u00eater. Jade applique un Single Leg Crab sur Brooke. Brooke r\u00e9siste et s&rsquo;approche d&rsquo;un c\u00e2ble, mais Jade la ram\u00e8ne au centre du ring. Jade refuse d&rsquo;abandonner, l&rsquo;arbitre d\u00e9cide d&rsquo;arr\u00eater le match car Brooke souffre trop.<\/p>\n\n\n\n<p><em>Gagnante : Cora Jade\u00a0par arr\u00eat de l&rsquo;arbitre<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, Dana Brooke se fait embarquer sur une civi\u00e8re.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o de plus t\u00f4t entre\u00a0<strong>Robert Stone <\/strong>et <strong>Von Wagner.<\/strong>\u00a0Wagner dit qu&rsquo;il veut lui parler ici, car Stone est le seul \u00e0 avoir cru en lui dans cette salle de NXT. <\/p>\n\n\n\n<p>Stone lui demande de parler de sa photo de jeunesse. Wagner explique qu&rsquo;il est n\u00e9 avec un probl\u00e8me de cerveau qui \u00e9tait limit\u00e9 \u00e0 grandir, alors il a \u00e9t\u00e9 oblig\u00e9 d&rsquo;\u00eatre op\u00e9r\u00e9 \u00e0 15 mois. Le m\u00e9decin lui a enlev\u00e9 sa t\u00eate pour corriger son cr\u00e2ne et lui donner une vie. Il a \u00e9t\u00e9 en soin intensif pendant une semaine, heureux d&rsquo;\u00eatre vivant. Son p\u00e8re travaillait pour les factures des soins et sa m\u00e8re ne le quittait jamais. Oui il \u00e9tait diff\u00e9rent par la cicatrice, les jeunes l&rsquo;insultaient de monstre. C&rsquo;\u00e9tait difficile. Les autres parents disaient \u00e0 leur enfant de ne pas le regarder.<\/p>\n\n\n\n<p> Wagner le remercie et dit que \u00e7a suffit pour aujourd&rsquo;hui.<\/p>\n\n\n\n<p>&#8211; En coulisse, Eddy Thorpe parle dans le vestiaire avec des catcheurs sur le match RAW Underground. Axiom dit que ce sera difficile de trouver un gars comme Kemp pour s&rsquo;entrainer.\u00a0<\/p>\n\n\n\n<p>Gable Steveson arrive et dit que Thorpe cherche quelqu&rsquo;un pour s&rsquo;entrainer, il connait bien Kemp,\u00a0alors il peut l&rsquo;aider. Thorpe accepte.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&#8211;\u00a0<strong>Baron Corbin<\/strong>\u00a0est sur le ring pour le face \u00e0 face et Carmelo Hayes arrive. Corbin demande de stopper le theme song de Hayes, il n&rsquo;a pas le temps d&rsquo;attendre pour sa pose. La pose de Hayes ne va pas l&rsquo;aider \u00e0 rester champion. Hayes a le look cool, mais Hayes ne peut rien dire qu&rsquo;il n&rsquo;a jamais entendu et Hayes ne fera rien qu&rsquo;il n&rsquo;a jamais vu la semaine prochaine. <\/p>\n\n\n\n<p>Hayes dit que Corbin n&rsquo;a jamais vu un r\u00e8gne de titre \u00e0 NXT ou bien le respect des fans. Corbin dit qu&rsquo;on n&rsquo;est plus dans la ville natale de Hayes. Il dit ce qu&rsquo;il veut car l&rsquo;opinion des fans ne l&rsquo;importe pas et celle de Hayes non plus. Hayes dit que Corbin vient dans sa maison et Corbin pense pouvoir pendre son titre et se rendre important. C&rsquo;est possible, mais ce n&rsquo;est pas probable. Il a eu des gars du main event qui sont venu pour le challenger et ils ont tous fini sur un tee-shirt. Il n&rsquo;y a aucune diff\u00e9rence entre Corbin et ceux qu&rsquo;il a renvoy\u00e9 chez eux. Alors si Corbin pense devenir Happy Corbin en gagnant il se trompe. <\/p>\n\n\n\n<p>Corbin dit que Happy Corbin lui a achet\u00e9 une maison de plusieurs millions. <\/p>\n\n\n\n<p>Hayes lance des insultes de surface et \u00e7a ne fonctionne pas. Il a eu une carri\u00e8re de huit ans que plusieurs vont juste en r\u00eaver. Ils peuvent comparer les moments WrestleMania, le rythme de vie ou bien le compte de banque. Hayes peut choisir le th\u00e8me qu&rsquo;il veut.<\/p>\n\n\n\n<p>Hayes dit que Corbin a une d\u00e9cennie d&rsquo;avance. \u00c0 26 ans il a remport\u00e9 le tournoi Breakout pour remporter un titre, \u00e0 26 ans Corbin se faisait couper en NFL. Il donne cr\u00e9dit \u00e0 tous les OG de l&rsquo;\u00e8re Black and Gold. Mais il refuse de vivre sa vie en r\u00e9pondant aux attentes de Corbin car il va cr\u00e9er de nouvelles attentes. Hayes dit qu&rsquo;il a construit plus de pi\u00e8ces, de fen\u00eatres et un nouveau toit depuis le d\u00e9part de Corbin de NXT tellement qu&rsquo;il a fait virevolter des gens. <\/p>\n\n\n\n<p>Corbin dit que Hayes doit se convaincre chaque semaine qu&rsquo;il est le meilleur, mais Hayes n&rsquo;est rien. C&rsquo;est pour cette raison que Hayes \u00e9tait derri\u00e8re la barricade. Normalement c&rsquo;est le point o\u00f9 il attaquerait Hayes, mais il n&rsquo;a pas besoin de faire \u00e7a.\u00a0Lorsqu&rsquo;il en aura termin\u00e9 avec Hayes, il va prendre son titre, partir dans sa voiture, aller dans sa grosse maison et boire un verre que Hayes ne peut pas se payer. La le\u00e7on est termin\u00e9e. Corbin quitte le ring.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&#8211; En coulisse, Valentina et Yulisa se f\u00e9licitent pour leur dernier match. Dragon Lee arrive et les motive pour leur match. <\/p>\n\n\n\n<p>Nathan Frazer arrive et dit qu&rsquo;il doit les remercier pour la semaine derni\u00e8re. Sans lui il ne sait pas s&rsquo;il aurait remport\u00e9 la coupe, alors merci. Dragon Lee f\u00e9licite Frazer. <\/p>\n\n\n\n<p>Frazer dit que Lee m\u00e9rite la premi\u00e8re chance pour la coupe, il doit bien s&rsquo;occuper des gens qui s&rsquo;occupent bien de lui. Lee approuve.<\/p>\n\n\n\n<p>&#8211; Sur le parking ext\u00e9rieur du centre de performance NXT, Gallus quitte. Mark Coffey et Wolfgang embarquent dans une voiture, mais Joe reste \u00e0 l&rsquo;ext\u00e9rieur car il parle au t\u00e9l\u00e9phone. <\/p>\n\n\n\n<p>Channing Lorenzo le frappe avec sa porte de voiture et l&#8217;embarque dans le coffre pour ensuite partir avec Joe.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Yulisa Leon et Valentina Feroz vs Lash Legend et Jakara Jackson<\/strong><\/p>\n\n\n\n<p>En fin de match, Feroz porte des coups de pied \u00e0 Legend. Feroz la charge contre le coin et enchaine avec un Head Scissors du coin. Feroz lui fait un Running Knee. Oro Mensah veut intervenir, mais Leon se lance dessus. Legend en profite pour faire un Pump Kick sur Feroz pour le compte de trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnantes : Lash Legend et Jakara Jackson<\/em><\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p style=\"font-size:25px\"><strong>Championnat Mondial Poids Lourd WWE<\/strong><\/p>\n\n\n\n<p><strong>Bron Breakker vs Seth Rollins <\/strong>\u00a9<\/p>\n\n\n\n<p>En fin de match, Rollins fait un Pedgiree sur Breakker et le couvre, mais il r\u00e9siste \u00e0 deux. Rollins frappe Breakker et se lance en Stomp, mais Breakker le bloque en Spear et le couvre, mais Rollins r\u00e9siste \u00e0 deux ! Breakker monte sur le coin et se lance, mais Rollins le bloque avec un coup de pied. Rollins enchaine avec un Stomp et un second Stomp pour le compte de trois sur Breakker.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnant : Seth Rollins<\/em><\/p>\n\n\n\n<p>Rollins c\u00e9l\u00e8bre sur la sc\u00e8ne, mais Finn Balor d\u00e9barque et commence \u00e0 le rouer de coups ! Balor prend une chaise et commence \u00e0 donner des coups de chaise \u00e0 Rollins. <\/p>\n\n\n\n<p>Balor monte sur le coin, mais Trick Williams et Carmelo Hayes arrivent, Balor d\u00e9cide de prendre la fuite.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p style=\"font-size:25px\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/06\/20\/avant-gout-pour-le-wwe-nxt-gold-rush-2023-20-juin-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir NXT Gold Rush Night 1, cliquez ici<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"Ll0Cdt0MGS\"><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/06\/20\/avant-gout-pour-le-wwe-nxt-gold-rush-2023-20-juin-2023\/\">Reprise Vid\u00e9o et Programme pour le WWE NXT Gold Rush 2023, 20 Juin 2023!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Reprise Vid\u00e9o et Programme pour le WWE NXT Gold Rush 2023, 20 Juin 2023!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2023\/06\/20\/avant-gout-pour-le-wwe-nxt-gold-rush-2023-20-juin-2023\/embed\/#?secret=TS6nqROGtk#?secret=Ll0Cdt0MGS\" data-secret=\"Ll0Cdt0MGS\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>&#8211; En coulisse,\u00a0Seth Rollins rencontre Nathan Frazer.\u00a0Rollins le f\u00e9licite pour avoir remporter sa grande coupe. Frazer le f\u00e9licite pour son titre et lui demande comment il va. Rollins dit qu&rsquo;il n&rsquo;est pas \u00e0 100%, mais c&rsquo;est de sa faute, il voulait affronter le meilleur Finn Balor. Il est fier de quoi Frazer est devenu. Carmelo&#8230;<\/p>\n","protected":false},"author":4,"featured_media":85537,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85],"tags":[],"ppma_author":[292],"class_list":["post-85515","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nxt"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/85515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=85515"}],"version-history":[{"count":8,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/85515\/revisions"}],"predecessor-version":[{"id":85545,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/85515\/revisions\/85545"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/85537"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=85515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=85515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=85515"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=85515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}