{"id":85506,"date":"2023-06-20T18:15:00","date_gmt":"2023-06-20T22:15:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=85506"},"modified":"2023-06-21T11:45:16","modified_gmt":"2023-06-21T15:45:16","slug":"le-aew-collision-a-completement-efface-les-12-derniers-mois-dopinion-sur-aew-deric-bishop","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/06\/20\/le-aew-collision-a-completement-efface-les-12-derniers-mois-dopinion-sur-aew-deric-bishop\/","title":{"rendered":"Le AEW Collision a compl\u00e8tement effac\u00e9 les 12 derniers mois d&rsquo;opinion sur AEW\u00a0d&rsquo;Eric Bishop"},"content":{"rendered":"\n<p>Eric Bischoff dit qu\u2019il a plus qu\u2019appr\u00e9ci\u00e9 la premi\u00e8re de Collision, le nouveau show de la All Alite Wrestling.<\/p>\n\n\n\n<p>Le Hall of Famer et ancien pr\u00e9sident de la WCW a parl\u00e9 de ce sujet lors d\u2019une r\u00e9cente interview sur son\u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=aabOvgSnJ_4\" target=\"_blank\" rel=\"noreferrer noopener\">podcast 83 Weeks<\/a>. Bischoff, qui a publiquement critiqu\u00e9 la AEW au cours de la derni\u00e8re ann\u00e9e, d\u00e9clare que cette \u00e9mission a effac\u00e9 tous ses doutes pr\u00e9c\u00e9dents et qu\u2019elle entre dans le produit avec une ardoise vierge.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>J\u2019ai plus que appr\u00e9ci\u00e9 le spectacle. Cela a compl\u00e8tement effac\u00e9 les 12 derniers mois de mon opinion sur la AEW, et j\u2019y vais avec une ardoise enti\u00e8rement vierge.<\/p>\n<\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Entrant dans les d\u00e9tails, Bischoff a fait l\u2019\u00e9loge du travail de Kevin Kelly et Nigel McGuinness, ainsi que de la r\u00e9servation du spectacle dans son ensemble.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Je ne saurais trop insister sur le fait que j\u2019ai \u00e9t\u00e9 impressionn\u00e9 par [Kevin] Kelly et [Nigel] McGuinness. De plus, celui qui a r\u00e9serv\u00e9 ce s**t \u2013 celui qui \u00e9tait dans la pi\u00e8ce, celui qui a eu le plus d\u2019influence sur le formatage et le rythme \u2013 ne laissez jamais cette personne hors de votre vue. Peut-\u00eatre que c\u2019\u00e9tait Tony [Khan]. Je ne pense pas, parce que je n\u2019ai jamais rien vu de la AEW se rapprocher du niveau de quasi-perfection [du formatage &lsquo;Collision&rsquo;].<\/p>\n<\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Bischoff ne pensait pas que c\u2019\u00e9tait un spectacle parfait car il pense que les promos en coulisses de l\u2019AEW sont toujours un probl\u00e8me.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>S\u2019il vous pla\u00eet, quelqu\u2019un, jetez un coup d\u2019\u0153il aux promos en coulisses, car elles nuisent vraiment au produit dans son ensemble. Ils ont d\u00e9montr\u00e9 ici qu\u2019ils en avaient la capacit\u00e9. Ils ont juste besoin de s\u2019y pencher un peu plus.<\/p>\n<\/blockquote>\n\n\n\n<p>Comme Bischoff, Jeff Jarrett a parl\u00e9 de son amour pour la premi\u00e8re d\u2019AEW Collision lors de la derni\u00e8re \u00e9dition de son podcas.<\/p>\n\n\n\n<center><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/aabOvgSnJ_4\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/center>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"p3TUIpAhao\"><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/06\/17\/resultats-et-video-pour-le-aew-collision-du-17-juin-2023\/\">R\u00e9sultats et Vid\u00e9o pour le AEW Collision du 17 Juin 2023!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0R\u00e9sultats et Vid\u00e9o pour le AEW Collision du 17 Juin 2023!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2023\/06\/17\/resultats-et-video-pour-le-aew-collision-du-17-juin-2023\/embed\/#?secret=THjyN2g4T5#?secret=p3TUIpAhao\" data-secret=\"p3TUIpAhao\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Eric Bischoff dit qu\u2019il a plus qu\u2019appr\u00e9ci\u00e9 la premi\u00e8re de Collision, le nouveau show de la All Alite Wrestling. Le Hall of Famer et ancien pr\u00e9sident de la WCW a parl\u00e9 de ce sujet lors d\u2019une r\u00e9cente interview sur son\u00a0podcast 83 Weeks. Bischoff, qui a publiquement critiqu\u00e9 la AEW au cours de la derni\u00e8re ann\u00e9e,&#8230;<\/p>\n","protected":false},"author":665,"featured_media":85556,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,89,30,77,4,83],"tags":[],"ppma_author":[289],"class_list":["post-85506","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-collision","category-ex-wwe","category-hall-of-fame","category-news","category-wcw"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/85506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=85506"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/85506\/revisions"}],"predecessor-version":[{"id":85557,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/85506\/revisions\/85557"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/85556"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=85506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=85506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=85506"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=85506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}