{"id":85435,"date":"2023-06-19T15:03:00","date_gmt":"2023-06-19T19:03:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=85435"},"modified":"2023-06-19T16:24:16","modified_gmt":"2023-06-19T20:24:16","slug":"gunther-a-aime-travaille-avec-kevin-owens-fusion-des-titres-par-equipe-wwe-et-plus","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/06\/19\/gunther-a-aime-travaille-avec-kevin-owens-fusion-des-titres-par-equipe-wwe-et-plus\/","title":{"rendered":"Gunther a aim\u00e9 travaill\u00e9 avec Kevin Owens! \/ Fusion des titres par \u00e9quipe WWE? Et plus!"},"content":{"rendered":"\n<p>Comme vous le savez, les changements de design des titres sont \u00e0 la mode \u00e0 la WWE. Les titres par \u00e9quipe de la WWE, pour leurs parts, n\u2019ont pas encore chang\u00e9s, ils sont toujours reli\u00e9s \u00e0 RAW et\/ ou SmackDown bien qu&rsquo;ils soient d\u00e9tenus par les champions par \u00e9quipe incontest\u00e9 Sami Zayn et Kevin Owens.<\/p>\n\n\n\n<p>Dans l&rsquo;\u00e9mission \u00ab\u00a0The Masked Man Show\u00a0\u00bb, Angelo Dawkins des Street Profits a \u00e9t\u00e9 interrog\u00e9 sur l&rsquo;\u00e9ventualit\u00e9 de nouveaux titres par \u00e9quipe de la WWE.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab Si c&rsquo;est le cas, j&rsquo;esp\u00e8re. On ne peut qu&rsquo;esp\u00e9rer. Les titres actuels sont toujours bien, le rouge et le bleu, nous pourrions les fusionner et les rendre violets. Nous allons introduire le gang violet. S&rsquo;ils d\u00e9cident de les changer, je suis d&rsquo;accord. \u00bb<\/p>\n<\/blockquote>\n\n\n\n<p>Le tout n&rsquo;a pas \u00e9t\u00e9 corrobor\u00e9 par la WWE mais il ne serait pas \u00e9tant d&rsquo;y arriver vu la tendance actuelle de fusionner ou de refondre les titres. <\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Kevin Owens et Sami Zayn ont eu r\u00e9cemment une petite rivalit\u00e9 avec l&rsquo;Imperium \u00e0 Raw. Ce qui a abouti sur plusieurs matchs dont un entre Gunther et KO qui s\u2019est termin\u00e9 par la victoire du champion Intercontinental.<\/p>\n\n\n\n<p>Lors d&rsquo;un entretien avec Steve Fall de \u00ab\u00a0WrestlingNewsCo\u00a0\u00bb, Gunther a parl\u00e9 de son alchimie sur le ring avec Owens:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><br>\u00ab Il semble qu\u2019il a des probl\u00e8mes de temp\u00e9rament pour une raison ou une autre. Je ne sais pas exactement ce qui se passe. Mais dans l&rsquo;ensemble, monter sur le ring et avoir un match avec lui \u00e9tait vraiment bien. Je pense que l&rsquo;\u00e9nergie qu&rsquo;il apporte sur le ring correspond tr\u00e8s bien \u00e0 l&rsquo;\u00e9nergie que j&rsquo;apporte \u00e9galement. C&rsquo;est un tr\u00e8s bon contraste. Je pense que si vous nous regardez, les gens peuvent vraiment s&rsquo;identifier \u00e0 quelqu&rsquo;un qui tient t\u00eate \u00e0 une brute et qui n&rsquo;accepte rien de sa part. Je pense que c&rsquo;est la raison pour laquelle les gens se sont connect\u00e9s \u00e0 ce match et \u00e0 cette histoire d&rsquo;une mani\u00e8re tr\u00e8s authentique. En plus de tout cela, il est ici depuis si longtemps et a accompli beaucoup de grandes choses. J&rsquo;ai vraiment appr\u00e9ci\u00e9 d&rsquo;\u00eatre sur le ring avec lui. Il est tr\u00e8s intense. Il est aussi tr\u00e8s physique. <\/p>\n\n\n\n<p>J&rsquo;aime quand mes matchs sont comme \u00e7a. Je ne crois pas que les matchs doivent \u00eatre toujours beaux et nets. Les meilleurs matchs sont plut\u00f4t hargneux. Si c&rsquo;est intense, brutal et tr\u00e8s physique, je pense que c&rsquo;est ce \u00e0 quoi les gens s&rsquo;identifient le plus. Je pense \u00e9galement que c&rsquo;est pour cela que nous avons eu la r\u00e9action que nous avons eue. \u00bb<\/p>\n<\/blockquote>\n\n\n\n<p>\u00a0Les prochains adversaires de Kevin Owens et Sami Zayn pour les titres sont l&rsquo;\u00e9quipe des Pretty Deadly. Ils vont s\u2019affronter dans 2 semaines \u00e0 Londres lors de SmackDown. Pour l\u2019instant, Gunther n\u2019a pas de challenger officiel mais les choses peuvent changer avec les prochaines semaines et il semblait que ce pourrait \u00eatre Matt Riddle. <\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Comme vous le savez, les changements de design des titres sont \u00e0 la mode \u00e0 la WWE. Les titres par \u00e9quipe de la WWE, pour leurs parts, n\u2019ont pas encore chang\u00e9s, ils sont toujours reli\u00e9s \u00e0 RAW et\/ ou SmackDown bien qu&rsquo;ils soient d\u00e9tenus par les champions par \u00e9quipe incontest\u00e9 Sami Zayn et Kevin Owens&#8230;.<\/p>\n","protected":false},"author":609,"featured_media":85436,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46,4,45,43,36,23],"tags":[],"ppma_author":[295],"class_list":["post-85435","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-money-in-the-bank","category-news","category-ppv-wwe","category-raw-wwe","category-smackdown","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/85435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=85435"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/85435\/revisions"}],"predecessor-version":[{"id":85438,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/85435\/revisions\/85438"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/85436"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=85435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=85435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=85435"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=85435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}