{"id":85424,"date":"2023-06-20T02:57:00","date_gmt":"2023-06-20T06:57:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=85424"},"modified":"2023-06-20T13:15:39","modified_gmt":"2023-06-20T17:15:39","slug":"chris-jericho-discute-de-limportance-du-programme-avec-sting-se-souvient-quand-il-a-pense-pour-la-premiere-fois-a-faire-quelque-chose-avec-lui","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/06\/20\/chris-jericho-discute-de-limportance-du-programme-avec-sting-se-souvient-quand-il-a-pense-pour-la-premiere-fois-a-faire-quelque-chose-avec-lui\/","title":{"rendered":"Chris Jericho discute de l\u2019importance du programme  avec Sting, se souvient quand il a pens\u00e9 pour la premi\u00e8re fois \u00e0 faire quelque chose avec lui!"},"content":{"rendered":"\n<p>Chris Jericho parle de travailler avec Sting pour la toute premi\u00e8re fois.<\/p>\n\n\n\n<p>The Ocho a parl\u00e9 de sa rivalit\u00e9 actuelle avec The Icon lors d\u2019une r\u00e9cente interview sur le&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/podbay.fm\/p\/the-aew-some-pod\" target=\"_blank\">podcast AEW-some<\/a>. Les deux se sont rencontr\u00e9s face \u00e0 face lors de l\u2019\u00e9dition de mercredi dernier du AEW Dynamite et les fans attendent avec impatience o\u00f9 cette rivalit\u00e9 pourrait potentiellement mener. <\/p>\n\n\n\n<p>Jericho commence son interview en rappelant aux animateurs que lui et Sting ne s\u2019\u00e9taient jamais crois\u00e9s dans leur longue carri\u00e8re ensemble dans l\u2019industrie.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>C\u2019est la toute premi\u00e8re fois dans nos deux carri\u00e8res, qui s\u2019\u00e9tendent sur 70 ans combin\u00e9s, que l\u2019un ou l\u2019autre d\u2019entre nous est mont\u00e9 sur le ring ensemble. Jamais. Pas pour une confrontation, pas pour une bataille royale, rien. Nous n\u2019avons jamais touch\u00e9 ou \u00e9t\u00e9 face \u00e0 face dans un ring de lutte professionnelle auparavant.<\/p>\n<\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>Jericho r\u00e9v\u00e8le ensuite que lui et Sting ont eu une rencontre hors cam\u00e9ra en 2021 pendant la pand\u00e9mie lors d\u2019un adieu sp\u00e9cial pour un directeur de spectacle de lutte professionnel de longue date.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Il y a quelques ann\u00e9es, il y a un gars qui s\u2019appelle Keith Mitchell, il a longtemps \u00e9t\u00e9 le r\u00e9alisateur de Dynamite, il a dirig\u00e9 Nitro pendant des ann\u00e9es, il a dirig\u00e9 World Class avec les Von Erichs, il a pris sa retraite en 2021. Nous avons eu une c\u00e9r\u00e9monie d\u2019adieu pour lui devant l\u2019une des petites foules de Jacksonville pendant le confinement. Sting \u00e9tait sur le ring et ils m\u2019ont demand\u00e9 de venir sur le ring. C\u2019\u00e9tait la premi\u00e8re fois que Sting et moi \u00e9tions sur le ring ensemble. C\u2019\u00e9tait hors cam\u00e9ra, hors t\u00e9l\u00e9vision.<\/p>\n<\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>C\u2019est pendant l\u2019adieu de Mitchell que Jericho a d\u00e9cid\u00e9 qu\u2019il voulait faire quelque chose avec Sting quand le moment serait venu.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Je me souviens d\u2019avoir pens\u00e9 et de lui avoir parl\u00e9 : \u00ab C\u2019est fou. Nous n\u2019avons jamais rien fait. Quand le moment sera venu, nous devrons faire quelque chose. \u00bb Le moment \u00e9tait venu mercredi pour la toute premi\u00e8re confrontation, Sting contre Chris Jericho.<\/p>\n<\/blockquote>\n\n\n\n<p>Peu de temps apr\u00e8s leur rencontre avec Dynamite, Jericho et Sting ont \u00e9chang\u00e9 des coups sur Twitter pour exciter la rivalit\u00e9 avant leur affrontement par \u00e9quipe plus tard cette semaine.<\/p>\n\n\n\n<center><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">I&rsquo;m listening to Episode 29 &#8211; Recapping the June 14 Episode of Dynamite (w\/ Special Guest Chris Jericho) from The AEW-some Pod on <a href=\"https:\/\/twitter.com\/podbayfm?ref_src=twsrc%5Etfw\">@podbayfm<\/a>. <a href=\"https:\/\/t.co\/jmUc67JdXm\">https:\/\/t.co\/jmUc67JdXm<\/a><\/p>\u2014 Jason Dark Cash Desc\u00f4teaux (@InfoLutte) <a href=\"https:\/\/twitter.com\/InfoLutte\/status\/1671202161672200192?ref_src=twsrc%5Etfw\">June 20, 2023<\/a><\/blockquote> <script async=\"\" src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/center>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"7vIMkw9yUV\"><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/06\/14\/resultats-et-video-pour-le-aew-dynamite-du-14-juine-2023\/\">R\u00e9sultats et Vid\u00e9o pour le AEW Dynamite du 14 Juine 2023!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0R\u00e9sultats et Vid\u00e9o pour le AEW Dynamite du 14 Juine 2023!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2023\/06\/14\/resultats-et-video-pour-le-aew-dynamite-du-14-juine-2023\/embed\/#?secret=ADQpCNUKFt#?secret=7vIMkw9yUV\" data-secret=\"7vIMkw9yUV\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Chris Jericho parle de travailler avec Sting pour la toute premi\u00e8re fois. The Ocho a parl\u00e9 de sa rivalit\u00e9 actuelle avec The Icon lors d\u2019une r\u00e9cente interview sur le&nbsp;podcast AEW-some. Les deux se sont rencontr\u00e9s face \u00e0 face lors de l\u2019\u00e9dition de mercredi dernier du AEW Dynamite et les fans attendent avec impatience o\u00f9 cette&#8230;<\/p>\n","protected":false},"author":665,"featured_media":85495,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,50,30,77,4,83],"tags":[],"ppma_author":[289],"class_list":["post-85424","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-dynamite","category-ex-wwe","category-hall-of-fame","category-news","category-wcw"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/85424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=85424"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/85424\/revisions"}],"predecessor-version":[{"id":85497,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/85424\/revisions\/85497"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/85495"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=85424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=85424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=85424"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=85424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}