{"id":85371,"date":"2023-06-17T15:55:50","date_gmt":"2023-06-17T19:55:50","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=85371"},"modified":"2023-06-17T15:57:37","modified_gmt":"2023-06-17T19:57:37","slug":"kliq-express-la-wwe-doit-de-largent-a-nash-la-wwe-met-en-vente-un-championnat-special-du-hbk","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/06\/17\/kliq-express-la-wwe-doit-de-largent-a-nash-la-wwe-met-en-vente-un-championnat-special-du-hbk\/","title":{"rendered":"KLIQ EXPRESS: La WWE doit de l&rsquo;argent \u00e0 Nash \/ La WWE met en vente un championnat sp\u00e9cial du HBK!"},"content":{"rendered":"\n<p>Toujours en votre compagnie pour vous en offrir plus comme des nouvelles sur deux membres de la KLIQ!<\/p>\n\n\n\n<p>Kevin Nash a r\u00e9cemment parl\u00e9 d&rsquo;un large \u00e9ventail de sujets sur son <a href=\"https:\/\/www.youtube.com\/@KliqThis\/videos\" target=\"_blank\" rel=\"noreferrer noopener\">podcast Kliq This<\/a>.<\/p>\n\n\n\n<p>Pendant ce temps, le Hall of Famer de la WWE s&rsquo;est plaint du manque d&rsquo;argent qu&rsquo;il per\u00e7oit sur les redevances sur les marchandises, y compris la nWo de la WWE.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab\u00a0Je n&rsquo;ai pas re\u00e7u un dollar sur NWO. Cela devrait \u00eatre 150% de ce que je re\u00e7ois normalement [dans la prochaine p\u00e9riode], et si ce n&rsquo;est pas le cas, je suppose que je mettrai un morceau de papier dans la main d&rsquo;Ari [Emmanuel].\u00a0\u00bb<\/p>\n<\/blockquote>\n\n\n\n<p>Nash s&rsquo;\u00e9tait pr\u00e9c\u00e9demment plaint sur le podcast de ses redevances au dernier trimestre et de la soci\u00e9t\u00e9 lui assurant qu&rsquo;il ferait partie des jeux vid\u00e9o de la WWE. Il a \u00e9galement not\u00e9 qu&rsquo;il recevrait un Big Daddy Cool Funko Pop.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab\u00a0C&rsquo;est comme si j&rsquo;en avais rien \u00e0 foutre. Je m&rsquo;en fous si je re\u00e7ois 7% des paquets de ketchup Heinz que vous vendez aux stades de baseball, je veux les putains de redevances sur ce que vous vendez aux putains de Walgreens et Walmarts et \u00e0 tout le monde sinon, dans la grande bouteille Heinz de 16 oz, je veux l&rsquo;argent \u00bb, a demand\u00e9 Nash. \u00ab\u00a0Donnez-moi tous les Funko que vous voulez, je n&rsquo;obtiens pas 17% des Funko.\u00a0\u00bb<\/p>\n<\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p><\/p>\n\n\n\n<p>Si Nash ne semble pas se faire payer pour les marchandise de la WWE, la boutique en ligne de la compagnie vend maintenant une ceinture de championnat concernant Shawn Michaels Legacy pour 749$ USD.<\/p>\n\n\n\n<p>Les fans peuvent obtenir leur propre ceinture et la pr\u00e9commande est maintenant disponible. <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/images.footballfanatics.com\/shawn-michaels\/shawn-michaels-legacy-championship-title-belt_ss5_p-200057905+pv-1+u-ubmusljujv1ri5amm2bm+v-0qmmvgsqc1ehs4wksvkf.jpg?_hv=2&amp;w=900\" alt=\"\"\/><\/figure>\n<\/div>\n\n\n<ul class=\"wp-block-list\">\n<li>Product ID: 200057905<\/li>\n\n\n\n<li>Brand: WWE Authentic<\/li>\n\n\n\n<li>Imported<\/li>\n\n\n\n<li>First side plate measures approx. 4.02\u2033 \u00d7 5.9\u2033<\/li>\n\n\n\n<li>Second slide plate measures approx. 3.01\u2033 x 4.07\u2033<\/li>\n\n\n\n<li>Snap fasteners<\/li>\n\n\n\n<li>Strap measures approx. 55.25\u2033 \u00d7 10.06\u2033<\/li>\n\n\n\n<li>Weighs approx. 6.17 lbs.<\/li>\n\n\n\n<li>Red crystals on front<\/li>\n\n\n\n<li>Chain one measures approx. 6.128\u2033<\/li>\n\n\n\n<li>Chain two measures approx. 5.316\u2033<\/li>\n\n\n\n<li>Suitable for waist sizes up to 46\u201d<\/li>\n\n\n\n<li>Material: 100% Zinc Alloy \u2013 Plate; 100% Leather \u2013 Strap<\/li>\n\n\n\n<li>Officially licensed<\/li>\n<\/ul>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Toujours en votre compagnie pour vous en offrir plus comme des nouvelles sur deux membres de la KLIQ! Kevin Nash a r\u00e9cemment parl\u00e9 d&rsquo;un large \u00e9ventail de sujets sur son podcast Kliq This. Pendant ce temps, le Hall of Famer de la WWE s&rsquo;est plaint du manque d&rsquo;argent qu&rsquo;il per\u00e7oit sur les redevances sur les&#8230;<\/p>\n","protected":false},"author":2,"featured_media":85372,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,77,4,85,83,23],"tags":[],"ppma_author":[287],"class_list":["post-85371","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ex-wwe","category-hall-of-fame","category-news","category-nxt","category-wcw","category-wwe"],"authors":[{"term_id":287,"user_id":2,"is_guest":0,"slug":"jason","display_name":"Jason Desc\u00f4teaux","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/f64adf6d13198c3a532c061cecd8672089a1e9a3d07c702dffe886a7e55a15eb?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/85371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=85371"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/85371\/revisions"}],"predecessor-version":[{"id":85375,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/85371\/revisions\/85375"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/85372"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=85371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=85371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=85371"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=85371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}