{"id":85301,"date":"2023-06-16T22:19:42","date_gmt":"2023-06-17T02:19:42","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=85301"},"modified":"2023-06-17T00:54:24","modified_gmt":"2023-06-17T04:54:24","slug":"deuxieme-heure-de-smackown","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/06\/16\/deuxieme-heure-de-smackown\/","title":{"rendered":"Deuxi\u00e8me Heure de Smackown!"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong>Pour revenir \u00e0 la premi\u00e8re, cliquez ici.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>&#8211; C&rsquo;est l&rsquo;heure du Grayson Waller Effect. Grayson Waller nous demande d\u2019accueillir Charlotte Flair qui est son invit\u00e9e du soir qui fait son entr\u00e9e. <\/p>\n\n\n\n<p>Waller nous rappelle que Charlotte Flair avait mis fin \u00e0 la streak d&rsquo;Asuka lors d&rsquo;un WrestleMania, mais ce n&rsquo;est plus la m\u00eame Asuka. Alors Charlotte Flair deviendra-t-elle championne pour la 15e fois ?<\/p>\n\n\n\n<p>La musique de Bianca Belair retentit et elle arrive sur le ring. Belair dit avoir perdu le titre et qu&rsquo;on lui a promis un rematch, mais elle n&rsquo;en a pas. Par contre, Charlotte revient et elle a son match. Charlotte Flair dit \u00eatre venue et a demand\u00e9 d&rsquo;avoir un match de titre, elle n&rsquo;a rien fait d&rsquo;interdit. Bianca Belair affirme avoir essay\u00e9 de le faire de la bonne mani\u00e8re. Elle a perdu et elle est rest\u00e9e pr\u00e9sente, elle ne s&rsquo;est pas cass\u00e9e et cach\u00e9e pendant 3 mois.<\/p>\n\n\n\n<p>Charlotte Flair dit avoir battu les meilleures et avoir perdu contre la meilleure. Elle est championne avec ou sans la ceinture, est-ce aussi le cas pour Bianca Belair ?&nbsp;Bianca Belair r\u00e9pond \u00eatre la championne avec le plus long r\u00e8gne et elle n&rsquo;a pas eu \u00e0 le faire 14 fois. En tout cas, elle sera en ringside pour son match contre Asuka et peu importe la gagnante, elle viendra sur le ring pour lui rappeler que le titre revient \u00e0 elle.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; Dans les coulisses, Paul Heyman rejoint Jey Uso et il est d\u00e9sol\u00e9 de lui avoir dit la v\u00e9rit\u00e9 la semaine derni\u00e8re. Il est d\u00e9sol\u00e9 que son fr\u00e8re lui ait co\u00fbt\u00e9 le titre la semaine derni\u00e8re, il l&rsquo;a fait expr\u00e8s. Il a voulu mettre un Kick sur Roman Reigns \u00e0 Night of Champions et il a voulu lui mettre un kick la semaine derni\u00e8re. Jimmy a voulu victimiser son fr\u00e8re \u00e0 la t\u00e9l\u00e9vision, Jey ne m\u00e9rite pas \u00e7a. Paul Heyman dit \u00eatre d\u00e9sol\u00e9. Jey Uso r\u00e9pond qu&rsquo;il est aussi d\u00e9sol\u00e9, d\u00e9sol\u00e9 car s&rsquo;il est toujours dans la Bloodline, Paul Heyman ne l&rsquo;est plus.<\/p>\n\n\n\n<p style=\"font-size:25px\"><strong>Mixed Tag Team Match<\/strong><\/p>\n\n\n\n<p><strong>The O.C. (AJ Styles &amp; Michin) vs Karrion Kross et Scarlett<\/strong><\/p>\n\n\n\n<p>En fin de match, Scarlett gifle AJ Styles. Michin envoie Scarlett en dehors du ring puis Karrion Kross fait son Kross Jacket sur AJ Styles, suivi de son Kross Hammer puis d&rsquo;un Spinning Flatliner pour l&#8217;emporter par tomb\u00e9.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnants : Karrion Kross et Scarlett<\/em><\/p>\n\n\n\n<p>&#8211; En coulisses, Paul Heyman retrouve Roman Reigns et Solo Sikoa. Reigns cherche \u00e0 savoir ce qu&rsquo;il s&rsquo;est pass\u00e9. Paul Heyman ne r\u00e9pond rien puis Solo Sikoa bouge un peu avant qu&rsquo;Heyman ne parte en courant.&nbsp;<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>&#8211; Toujours Backstage, Cameron Grimes est avec Kayla Braxton mais il se fait attaquer par Baron Corbin.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; Rey Mysterio fait son entr\u00e9e et nous dit avoir pu accomplir de nombreuses choses au cours des ann\u00e9es, avoir pu reformer la LWO est un accomplissement dont il est vraiment fier. Une personne peut devenir le prochain Mr. Money in the Bank et c&rsquo;est Santos Escobar.&nbsp;Santos Escobar arrive puis dit avoir beaucoup travaill\u00e9 et fait beaucoup de sacrifices pour l&rsquo;opportunit\u00e9 d&rsquo;une vie avec Money in the Bank. Il remercie Rey Mysterio d&rsquo;avoir cru en lui.<\/p>\n\n\n\n<p>La musique de LA Knight le coupe et il arrive sur le ring. LA Knight pousse Rey Mysterio au sol mais Santos Escobar l&rsquo;attaque et l&rsquo;envoie dans les cordes, LA Knight arriver \u00e0 \u00e9viter le 619 de Rey Mysterio.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>LA Knight vs Santos Escobar<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du match, Santos Escobar arrive \u00e0 retourner un roll up de LA Knight pour l&#8217;emporter par tomb\u00e9.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnant : Santos Escobar<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le match, LA Knight attaque Santos Escobar puis Rey Mysterio arrive pour venir en aider \u00e0 Escobar, mais LA Knight s&rsquo;en va.<\/p>\n\n\n\n<p>&#8211; Dans les coulisses, Jey Uso marche puis rencontre Sami Zayn pendant quelques instants.<\/p>\n\n\n\n<p>&#8211; La semaine prchaine : Ronda Rousey et Shayna Baszler seront face \u00e0 Isla Dawn et Alba Fyre pour l&rsquo;unification des titres par \u00e9quipe \/ Baron Corbin sera face \u00e0 Cameron Grimes \/ Bayley mettra sa place Money in the Bank en jeu face \u00e0 Shotzi.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; Roman Reigns fait son entr\u00e9e aux c\u00f4t\u00e9s de Solo Sikoa et Paul Heyman. Reigns demande \u00e0 Lexington de le reconnaitre puis la musique des Usos retentit, c&rsquo;est Jey qui fait son entr\u00e9e.<\/p>\n\n\n\n<p>Roman Reigns lui dit que les fans veulent des r\u00e9ponses : il est toujours dans la Bloodline ou pas ? Jey R\u00e9pond r\u00e9pond que c&rsquo;est \u00e0 lui de lui dire, c&rsquo;est soit Paul Heyman, soit Jey Uso. Roman Reigns dit qu&rsquo;en tant que Tribal Chief, il peut choisir n&rsquo;importe qui en tant que \u00ab\u00a0wise man.\u00a0\u00bb C&rsquo;est gr\u00e2ce \u00e0 Paul Heyman que Jey Uso est le Right Hand Man et Main Event Jey. Ce n&rsquo;est pas Paul Heyman le probl\u00e8me, c&rsquo;est son fr\u00e8re.<\/p>\n\n\n\n<p>Jimmy Uso arrive et dit \u00e0 Jey que le probl\u00e8me n&rsquo;est pas son fr\u00e8re, c&rsquo;est son cousin. Croit-il r\u00e9ellement ce qui sort de la bouche de Roman Reigns. Roman Reigns r\u00e9pond que \u00e7a leur a pris 10 ans pour faire un WrestleMania. Depuis qu&rsquo;ils sont avec lui, ils ont particip\u00e9 \u00e0 chaque Main Event de WM. Jey Uso est son successeur, il ne pourra pas \u00eatre un Tribal Chief et un jumeau en m\u00eame temps.<\/p>\n\n\n\n<p>Roman Reigns demande \u00e0 Paul Heyman qui avait un probl\u00e8me avec le fait que Jey Uso soit nomm\u00e9 Right Hand Man, Paul Heyman montre Jimmy. Jey Uso demande \u00e0 son fr\u00e8re si c&rsquo;est vrai et Jimmy r\u00e9pond que c&rsquo;est vrai.&nbsp;<\/p>\n\n\n\n<p>Jey Uso commence \u00e0 s&rsquo;\u00e9nerver puis dit \u00e0 Jimmy qu&rsquo;il n&rsquo;est plus dans la Bloodline&#8230; alors lui non plus ! Jey Uso envoie un Superkick \u00e0 Roman Reigns !&nbsp;Solo Sikoa s&rsquo;en prend aux Usos mais ils lui mettent un Superkick. Roman Reigns commence \u00e0 se relever puis les Usos lui font un Double Superkick ! Le show se termine ainsi.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p style=\"font-size:25px\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/06\/16\/avant-gout-pour-le-wwe-friday-night-smackdown-du-16-juin-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir Smackdown, cliquez ici.<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"BOgejcvyfi\"><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/06\/16\/avant-gout-pour-le-wwe-friday-night-smackdown-du-16-juin-2023\/\">Reprise Vid\u00e9o et Programme pour le WWE Friday Night Smackdown du 16 Juin 2023!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Reprise Vid\u00e9o et Programme pour le WWE Friday Night Smackdown du 16 Juin 2023!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2023\/06\/16\/avant-gout-pour-le-wwe-friday-night-smackdown-du-16-juin-2023\/embed\/#?secret=U0SYa0Mxd8#?secret=BOgejcvyfi\" data-secret=\"BOgejcvyfi\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>&#8211; C&rsquo;est l&rsquo;heure du Grayson Waller Effect. Grayson Waller nous demande d\u2019accueillir Charlotte Flair qui est son invit\u00e9e du soir qui fait son entr\u00e9e. Waller nous rappelle que Charlotte Flair avait mis fin \u00e0 la streak d&rsquo;Asuka lors d&rsquo;un WrestleMania, mais ce n&rsquo;est plus la m\u00eame Asuka. Alors Charlotte Flair deviendra-t-elle championne pour la 15e&#8230;<\/p>\n","protected":false},"author":609,"featured_media":85330,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"ppma_author":[295],"class_list":["post-85301","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-smackdown"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/85301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=85301"}],"version-history":[{"count":8,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/85301\/revisions"}],"predecessor-version":[{"id":85345,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/85301\/revisions\/85345"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/85330"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=85301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=85301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=85301"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=85301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}