{"id":85215,"date":"2023-06-14T01:18:00","date_gmt":"2023-06-14T05:18:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=85215"},"modified":"2023-06-14T14:24:10","modified_gmt":"2023-06-14T18:24:10","slug":"andrade-souhaitait-la-separation-des-rosters-a-la-all-elite-wrestling","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/06\/14\/andrade-souhaitait-la-separation-des-rosters-a-la-all-elite-wrestling\/","title":{"rendered":"Andrade souhaitait la s\u00e9paration des Rosters \u00e0 la All Elite Wrestling!"},"content":{"rendered":"\n<p>Nous apprenions cette semaine que Tony Khan n&rsquo;avait\u00a0pas l&rsquo;intention de faire une s\u00e9paration d\u00e9finitive des rosters\u00a0pour ses shows AEW Dynamite et AEW Collision.<br><strong>* <a href=\"https:\/\/www.jdx.info\/lutte\/2023\/06\/13\/la-aew-ne-veut-pas-diviser-son-roster\/\">La AEW ne veut pas diviser son roster!<\/a><\/strong><\/p>\n\n\n\n<p>Une opinion pour laquelle le conjoint de Charlotte Flair n&rsquo;est pas d&rsquo;accord et l&rsquo;a laiss\u00e9 savoir en entrevue pour \u00a0\u00bbPlease Steal Our Ideas\u00a0\u00bb le weekend dernier. Il a d\u00e9clar\u00e9 qu&rsquo;il esp\u00e9rait voir un roster s\u00e9par\u00e9 et aussi des championnats s\u00e9par\u00e9. Tout \u00e7a avant l&rsquo;annonce du grand Tony par contre :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00a0\u00bbJe ne le sais pas encore si ce sera s\u00e9par\u00e9, mais je l&rsquo;esp\u00e8re. J&rsquo;esp\u00e8re qu&rsquo;ils vont faire un nouveau titre. Peut-\u00eatre des rosters s\u00e9par\u00e9s comme dans une autre compagnie. J&rsquo;esp\u00e8re que Dynamite aura son roster et ses talents, et pour Collision je souhaite que se soit s\u00e9par\u00e9 pour cette nouvelle division. [&#8230;] On a besoin de nouveaux objectifs. Si on a des nouveaux championnats, c&rsquo;est bien car tu peux rivaliser pour ces titres.\u00a0\u00bb<\/p>\n<\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Pour rappel, Andrade El Idolo qui \u00e9tait absent de la compagnie pour raison de blessure, mais il n&rsquo;avait pas peur d&rsquo;exprimer ses opinions contre certaines d\u00e9cisions de la compagnie et par un manque au niveau de son booking. <\/p>\n\n\n\n<p>L&rsquo;ajout de Collision permet justement de donner une place \u00e0 ces talent qui avaient quelques probl\u00e8mes du c\u00f4t\u00e9 de Dynamite. Nous verrons assez vite comment le tout va se passer. <\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Nous apprenions cette semaine que Tony Khan n&rsquo;avait\u00a0pas l&rsquo;intention de faire une s\u00e9paration d\u00e9finitive des rosters\u00a0pour ses shows AEW Dynamite et AEW Collision.* La AEW ne veut pas diviser son roster! Une opinion pour laquelle le conjoint de Charlotte Flair n&rsquo;est pas d&rsquo;accord et l&rsquo;a laiss\u00e9 savoir en entrevue pour \u00a0\u00bbPlease Steal Our Ideas\u00a0\u00bb le&#8230;<\/p>\n","protected":false},"author":4,"featured_media":85216,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,89,50,30,4],"tags":[],"ppma_author":[292],"class_list":["post-85215","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-collision","category-dynamite","category-ex-wwe","category-news"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/85215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=85215"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/85215\/revisions"}],"predecessor-version":[{"id":85217,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/85215\/revisions\/85217"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/85216"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=85215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=85215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=85215"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=85215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}