{"id":84727,"date":"2023-06-01T13:27:00","date_gmt":"2023-06-01T17:27:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=84727"},"modified":"2023-06-02T13:31:00","modified_gmt":"2023-06-02T17:31:00","slug":"will-ospreay-est-confiant-a-lidee-de-signer-de-nouveau-avec-la-njpw","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/06\/01\/will-ospreay-est-confiant-a-lidee-de-signer-de-nouveau-avec-la-njpw\/","title":{"rendered":"Will Ospreay est confiant \u00e0 l&rsquo;id\u00e9e de signer de nouveau avec la NJPW!"},"content":{"rendered":"\n<p>Ceux qui le connaissent savent que contrat de Will Ospreay avec la NJPW\u00a0arrive \u00e0 \u00e9ch\u00e9ance en f\u00e9vrier 2024. C&rsquo;est encore bien loin, mais avec un nom si populaire, une fin de contrat qui approche est toujours signe de nombreuses n\u00e9gociations avec plusieurs compagnies de lutte professionnel.<\/p>\n\n\n\n<p>Sans oublier que ses partenaires d&rsquo;Aussie Open sont maintenant sous contrat \u00e0 temps plein avec la All Elite Wrestling, alors est-ce qu&rsquo;il sera pench\u00e9 \u00e0 rejoindre la AEW ? Will Ospreay \u00e9tait en interview pour le podcast \u00a0\u00bbInsight\u00a0\u00bb de Chris Van Vliet et il a exprim\u00e9 qu&rsquo;il est confiant de signer \u00e0 nouveau  avec la NJPW :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00a0\u00bbJe suis tr\u00e8s confiant sur le fait que la New Japan et moi allons trouver une solution car je ne veux pas vivre en Am\u00e9rique. C&rsquo;est mon point qui arr\u00eate tout. Je ne veux juste pas. \u00c7a me limite. Je dis essentiellement que nous allons trouver un accord.\u00a0\u00bb<\/p>\n<\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Au sujet de ses ambitions, il pr\u00e9cise que WrestleMania ne l&rsquo;int\u00e9resse pas et qu&rsquo;il adore son horaire de vie actuelle :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00a0\u00bbBien s\u00fbr que j&rsquo;aimerais \u00eatre devant 80 000 personnes, qui ne voudrait pas ? Mais dans le m\u00eame \u00e9tat d&rsquo;esprit, \u00e7a ne va pas m&#8217;emp\u00eacher de dormir si je ne le fais jamais. Je n&rsquo;ai jamais voulu \u00eatre \u00e0 ce niveau de popularit\u00e9 avec le catch. J&rsquo;aime le faire seulement les weekends et en profiter. Et la New Japan m&rsquo;a offert beaucoup d&rsquo;argent.<\/p>\n<\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>La WWE, la TNA (Impact) et la New Japan \u00e9taient sur la table au m\u00eame moment \u00e0 une \u00e9poque. Et l&rsquo;argument de vente de la New Japan \u00e9tait que je serais capable de retourner \u00e0 la maison. WWE, je devais d\u00e9m\u00e9nager. TNA, presque la m\u00eame chose et l&rsquo;argent n&rsquo;\u00e9tait pas garanti. \u00c0 la New Japan, je pouvais retourner \u00e0 la maison. Et je suis un vrai gars qui aime son endroit. Alors le fait de pouvoir retourner chez moi \u00e9tait incroyable.\u00a0\u00bb<\/p>\n<\/blockquote>\n\n\n\n<p>Conclusion, Ospreay n&rsquo;est pas int\u00e9ress\u00e9 par l&rsquo;argent, ni la popularit\u00e9 et ni \u00e0 d\u00e9m\u00e9nager aux \u00c9tats-Unis ou ailleurs. <\/p>\n\n\n\n<p>La AEW n&rsquo;\u00e9tait pas dans le d\u00e9cor \u00e0 l&rsquo;\u00e9poque, reste maintenant \u00e0 voir si elle lui proposera un contrat o\u00f9 il peut retourner chez lui et ainsi r\u00e9unir tout le trio.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Ceux qui le connaissent savent que contrat de Will Ospreay avec la NJPW\u00a0arrive \u00e0 \u00e9ch\u00e9ance en f\u00e9vrier 2024. C&rsquo;est encore bien loin, mais avec un nom si populaire, une fin de contrat qui approche est toujours signe de nombreuses n\u00e9gociations avec plusieurs compagnies de lutte professionnel. Sans oublier que ses partenaires d&rsquo;Aussie Open sont maintenant&#8230;<\/p>\n","protected":false},"author":4,"featured_media":84728,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,22,55,4],"tags":[],"ppma_author":[292],"class_list":["post-84727","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew-impact-njpw-roh","category-indy","category-njpw","category-news"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/84727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=84727"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/84727\/revisions"}],"predecessor-version":[{"id":84729,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/84727\/revisions\/84729"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/84728"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=84727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=84727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=84727"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=84727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}